{"id":81399,"date":"2026-07-15T23:04:14","date_gmt":"2026-07-15T21:04:14","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/07\/15\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\/"},"modified":"2026-07-15T23:04:14","modified_gmt":"2026-07-15T21:04:14","slug":"cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/07\/15\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\/","title":{"rendered":"Cina, sviluppato il primo dispositivo bionico al mondo per \u201ccomprendere i suoni\u201d"},"content":{"rendered":"<div>\n<p>TIANJIN (CINA) (XINHUA\/ITALPRESS) \u2013 Dei ricercatori cinesi hanno sviluppato il primo dispositivo bionico neurale al mondo che consente al cervello delle persone con deficit uditivi di \u201ccomprendere\u201d i suoni, anzich\u00e8 limitarsi semplicemente a \u201csentirli\u201d.<\/p>\n<p>Il dispositivo, realizzato da un gruppo di ricerca dell\u2019Universit\u00e0 di Nankai, nella municipalit\u00e0 settentrionale cinese di Tianjin, propone un innovativo approccio elettronico di sostituzione e riparazione per la ricostruzione dell\u2019udito, andando oltre i tradizionali impianti cocleari.<\/p>\n<p>\u201cAttualmente gli impianti cocleari risolvono soltanto il problema del \u2018sentir\u00e8. Tuttavia, a causa del loro meccanismo fisso basato su impulsi temporizzati e del numero limitato di elettrodi, restano ancora molto lontani dal sistema uditivo naturale in termini di risoluzione temporale e riconoscimento del parlato in ambienti acustici complessi\u201d, ha spiegato Xu Wentao, responsabile della ricerca presso il College of Electronic and Optical Engineering, in un comunicato stampa diffuso luned\u00ec dall\u2019universit\u00e0.<\/p>\n<p>\u201cIl nostro obiettivo non \u00e8 soltanto fare in modo che il sistema \u2018sent\u00e0, ma consentirgli di \u2018comprender\u00e8 realmente, ovvero di selezionare, elaborare e trasmettere informazioni uditive utili proprio come farebbe un nervo naturale\u201d, ha aggiunto. Secondo Xu, il nuovo dispositivo rappresenta un passo fondamentale nel recupero uditivo, segnando il passaggio dal \u201crecupero della percezione\u201d al \u201cripristino della funzione\u201d.<\/p>\n<p>Lo studio, intitolato \u201cUn\u2019interfaccia neuromorfica artificiale per il recupero delle funzioni uditive\u201d, \u00e8 stato pubblicato online il primo luglio sulla rivista \u201cNature Materials\u201d.<\/p>\n<p>L\u2019udito non dipende soltanto dalle orecchie, ma anche dal nervo uditivo, che agisce come una sorta di \u201cautostrada\u201d per trasmettere al cervello i segnali sonori. Secondo la ricerca, l\u2019ipoacusia neurosensoriale, una forma di sordit\u00e0 causata dal danneggiamento di questo collegamento, interessa circa il 3% della popolazione mondiale.<\/p>\n<p>I tradizionali impianti cocleari possono convertire i suoni in segnali elettrici, ma continuano a dipendere dalla parte ancora funzionante del nervo uditivo del paziente per completare \u201cl\u2019ultimo tratto\u201d della trasmissione.<\/p>\n<p>Quando il nervo uditivo \u00e8 gravemente compromesso o assente, \u201canche gli impianti cocleari pi\u00f9 avanzati diventano inefficaci\u201d, ha osservato Xu, sottolineando che proprio questa difficolt\u00e0 di lunga data potrebbe essere superata grazie alla scoperta del suo gruppo.<\/p>\n<p>Il nuovo dispositivo, descritto come un&#8217;\u201dinterfaccia neuromorfica\u201d capace di imitare i naturali processi di codifica dei nervi uditivi biologici, integra l\u2019acquisizione dei suoni, la codifica neurale, l\u2019elaborazione semantica e la produzione di segnali bioelettrici in un circuito neurale artificiale completo.<\/p>\n<p>Il sistema non si limita a rilevare i suoni, ma li filtra, li analizza e li codifica in maniera simile al sistema uditivo naturale, prima di trasmettere al cervello informazioni dotate di significato, ha spiegato il gruppo di ricerca.<\/p>\n<p>\u201cIn futuro continueremo le nostre ricerche sulla riparazione neurale e sull\u2019intelligenza bionica, impegnandoci per portare le nostre tecnologie fondamentali dal laboratorio all\u2019impiego clinico e al mercato\u201d, ha dichiarato Xu.<\/p>\n<p>\u201cCi auguriamo di ottenere ulteriori progressi nel campo delle neuroprotesi, dell\u2019assistenza sanitaria intelligente, delle interfacce cervello-computer e dell\u2019intelligenza incarnata\u201d, ha concluso.<br \/>(ITALPRESS).<br \/>-Foto Xinhua-<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>TIANJIN (CINA) (XINHUA\/ITALPRESS) \u2013 Dei ricercatori cinesi hanno sviluppato il primo dispositivo bionico neurale al mondo che consente al cervello delle persone con deficit uditivi di \u201ccomprendere\u201d i suoni, anzich\u00e8 limitarsi semplicemente a \u201csentirli\u201d. Il dispositivo, realizzato da un gruppo di ricerca dell\u2019Universit\u00e0 di Nankai, nella municipalit\u00e0 settentrionale cinese di Tianjin, propone un innovativo approccio [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":81400,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-81399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cina, sviluppato il primo dispositivo bionico al mondo per \u201ccomprendere i suoni\u201d - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/07\/15\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cina, sviluppato il primo dispositivo bionico al mondo per \u201ccomprendere i suoni\u201d - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"TIANJIN (CINA) (XINHUA\/ITALPRESS) \u2013 Dei ricercatori cinesi hanno sviluppato il primo dispositivo bionico neurale al mondo che consente al cervello delle persone con deficit uditivi di \u201ccomprendere\u201d i suoni, anzich\u00e8 limitarsi semplicemente a \u201csentirli\u201d. Il dispositivo, realizzato da un gruppo di ricerca dell\u2019Universit\u00e0 di Nankai, nella municipalit\u00e0 settentrionale cinese di Tianjin, propone un innovativo approccio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/07\/15\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T21:04:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/07\\\/15\\\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/07\\\/15\\\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Cina, sviluppato il primo dispositivo bionico al mondo per \u201ccomprendere i suoni\u201d\",\"datePublished\":\"2026-07-15T21:04:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/07\\\/15\\\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\\\/\"},\"wordCount\":489,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/07\\\/15\\\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/20260715_3284.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/07\\\/15\\\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/07\\\/15\\\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\\\/\",\"name\":\"Cina, sviluppato il primo dispositivo bionico al mondo per \u201ccomprendere i suoni\u201d - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/07\\\/15\\\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/07\\\/15\\\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/20260715_3284.jpg\",\"datePublished\":\"2026-07-15T21:04:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/07\\\/15\\\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/07\\\/15\\\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/07\\\/15\\\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/20260715_3284.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/20260715_3284.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/07\\\/15\\\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cina, sviluppato il primo dispositivo bionico al mondo per \u201ccomprendere i suoni\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cina, sviluppato il primo dispositivo bionico al mondo per \u201ccomprendere i suoni\u201d - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/07\/15\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\/","og_locale":"it_IT","og_type":"article","og_title":"Cina, sviluppato il primo dispositivo bionico al mondo per \u201ccomprendere i suoni\u201d - Live Magazine","og_description":"TIANJIN (CINA) (XINHUA\/ITALPRESS) \u2013 Dei ricercatori cinesi hanno sviluppato il primo dispositivo bionico neurale al mondo che consente al cervello delle persone con deficit uditivi di \u201ccomprendere\u201d i suoni, anzich\u00e8 limitarsi semplicemente a \u201csentirli\u201d. Il dispositivo, realizzato da un gruppo di ricerca dell\u2019Universit\u00e0 di Nankai, nella municipalit\u00e0 settentrionale cinese di Tianjin, propone un innovativo approccio [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/07\/15\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-07-15T21:04:14+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/07\/15\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/07\/15\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Cina, sviluppato il primo dispositivo bionico al mondo per \u201ccomprendere i suoni\u201d","datePublished":"2026-07-15T21:04:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/07\/15\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\/"},"wordCount":489,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/07\/15\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/07\/20260715_3284.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/07\/15\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/07\/15\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\/","name":"Cina, sviluppato il primo dispositivo bionico al mondo per \u201ccomprendere i suoni\u201d - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/07\/15\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/07\/15\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/07\/20260715_3284.jpg","datePublished":"2026-07-15T21:04:14+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/07\/15\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/07\/15\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/07\/15\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/07\/20260715_3284.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/07\/20260715_3284.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/07\/15\/cina-sviluppato-il-primo-dispositivo-bionico-al-mondo-per-comprendere-i-suoni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Cina, sviluppato il primo dispositivo bionico al mondo per \u201ccomprendere i suoni\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/07\/20260715_3284.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/81399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=81399"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/81399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/81400"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=81399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=81399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=81399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}