{"id":77939,"date":"2026-06-01T15:04:04","date_gmt":"2026-06-01T13:04:04","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\/"},"modified":"2026-06-01T15:04:04","modified_gmt":"2026-06-01T13:04:04","slug":"2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\/","title":{"rendered":"2 Giugno, Fontana \u201cLa democrazia si rafforza con partecipazione e giovani\u201d"},"content":{"rendered":"<div>\n<p>ROMA (ITALPRESS) \u2013<em><strong> \u201cSiamo alla vigilia della Festa della Repubblica, anniversario fondamentale che richiama il valore della scelta compiuta dagli italiani 80 anni fa.<\/strong> In un contesto internazionale particolarmente complesso, \u00e8 nostro dovere rafforzare la consapevolezza dell\u2019importanza della partecipazione,<strong> soprattutto dei giovani, alla vita pubblica. La democrazia si rafforza quando ciascuno si sente parte di un destino condiviso.<\/strong> Per questo la Camera dei deputati ha promosso numerose iniziative, a partire dalla mostra nella Sala della Lupa, luogo in cui furono proclamati i risultati del referendum istituzionale e dove \u00e8 conservato uno dei tre originali della Costituzione. Abbiamo voluto coinvolgere i giovani attraverso incontri, podcast, progetti con le scuole e iniziative divulgative, nella convinzione che conoscere la nostra storia, e le vite dei protagonisti, significhi comprendere il valore della libert\u00e0 e delle istituzioni democratiche\u201d<\/em>. Cos\u00ec il <strong>presidente della Camera dei deputati, Lorenzo Fontana.<\/strong><\/p>\n<p>\u2013 Foto IPA Agency \u2013<\/p>\n<p>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) \u2013 \u201cSiamo alla vigilia della Festa della Repubblica, anniversario fondamentale che richiama il valore della scelta compiuta dagli italiani 80 anni fa. In un contesto internazionale particolarmente complesso, \u00e8 nostro dovere rafforzare la consapevolezza dell\u2019importanza della partecipazione, soprattutto dei giovani, alla vita pubblica. La democrazia si rafforza quando ciascuno si sente parte di [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":77940,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-77939","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2 Giugno, Fontana \u201cLa democrazia si rafforza con partecipazione e giovani\u201d - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2 Giugno, Fontana \u201cLa democrazia si rafforza con partecipazione e giovani\u201d - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"ROMA (ITALPRESS) \u2013 \u201cSiamo alla vigilia della Festa della Repubblica, anniversario fondamentale che richiama il valore della scelta compiuta dagli italiani 80 anni fa. In un contesto internazionale particolarmente complesso, \u00e8 nostro dovere rafforzare la consapevolezza dell\u2019importanza della partecipazione, soprattutto dei giovani, alla vita pubblica. La democrazia si rafforza quando ciascuno si sente parte di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-01T13:04:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"2 Giugno, Fontana \u201cLa democrazia si rafforza con partecipazione e giovani\u201d\",\"datePublished\":\"2026-06-01T13:04:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\\\/\"},\"wordCount\":153,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/20260601_0396.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\\\/\",\"name\":\"2 Giugno, Fontana \u201cLa democrazia si rafforza con partecipazione e giovani\u201d - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/20260601_0396.jpg\",\"datePublished\":\"2026-06-01T13:04:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/20260601_0396.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/20260601_0396.jpg\",\"width\":1200,\"height\":799},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2 Giugno, Fontana \u201cLa democrazia si rafforza con partecipazione e giovani\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2 Giugno, Fontana \u201cLa democrazia si rafforza con partecipazione e giovani\u201d - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\/","og_locale":"it_IT","og_type":"article","og_title":"2 Giugno, Fontana \u201cLa democrazia si rafforza con partecipazione e giovani\u201d - Live Magazine","og_description":"ROMA (ITALPRESS) \u2013 \u201cSiamo alla vigilia della Festa della Repubblica, anniversario fondamentale che richiama il valore della scelta compiuta dagli italiani 80 anni fa. In un contesto internazionale particolarmente complesso, \u00e8 nostro dovere rafforzare la consapevolezza dell\u2019importanza della partecipazione, soprattutto dei giovani, alla vita pubblica. La democrazia si rafforza quando ciascuno si sente parte di [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-06-01T13:04:04+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"2 Giugno, Fontana \u201cLa democrazia si rafforza con partecipazione e giovani\u201d","datePublished":"2026-06-01T13:04:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\/"},"wordCount":153,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/06\/20260601_0396.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\/","name":"2 Giugno, Fontana \u201cLa democrazia si rafforza con partecipazione e giovani\u201d - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/06\/20260601_0396.jpg","datePublished":"2026-06-01T13:04:04+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/06\/20260601_0396.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/06\/20260601_0396.jpg","width":1200,"height":799},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/2-giugno-fontana-la-democrazia-si-rafforza-con-partecipazione-e-giovani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"2 Giugno, Fontana \u201cLa democrazia si rafforza con partecipazione e giovani\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/06\/20260601_0396.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/77939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=77939"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/77939\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/77940"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=77939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=77939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=77939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}