{"id":77920,"date":"2026-06-01T12:04:10","date_gmt":"2026-06-01T10:04:10","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\/"},"modified":"2026-06-01T12:04:10","modified_gmt":"2026-06-01T10:04:10","slug":"giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\/","title":{"rendered":"Giustizia civile in affanno, nel 2024 meno processi smaltiti di quelli nuovi"},"content":{"rendered":"<div>\n<p>ROMA (ITALPRESS) \u2013 Nel 2024 la giustizia civile italiana \u00e8 ancora poco sotto la soglia di equilibrio tra procedimenti definiti e sopravvenuti (clearance rate 0,99), ma \u00e8 il\u00a0trend decennale\u00a0a spiegare la traiettoria di un sistema in affanno:\u00a0dal 2014 al 2024 l\u2019indice nazionale scende da 1,39 a 1,13, con una\u00a0variazione di -0,26 punti. L\u2019analisi fatta dall\u2019Associazione Italiana Avvocati d\u2019Impresa mostra un\u00a0calo iniziale fino al 2016 (1,13), una\u00a0ripresa tra il 2019 e il 2022 (picco 1,26 nel 2019; 1,22 nel 2022)\u00a0e una\u00a0nuova flessione nel biennio 2023-2024.<br \/>\u201cIn dieci anni la capacit\u00e0 complessiva di smaltire i flussi si \u00e8 indebolita di un quarto di punto: \u00e8 un dato che impone una lettura di medio periodo e decisioni di governo del sistema, non interventi episodici\u201d, commenta l\u2019avvocato\u00a0Antonello Martinez, presidente dell\u2019Associazione Italiana Avvocati d\u2019Impresa e fondatore dello Studio Martinez &amp; Novebaci.<br \/>Corti d\u2019Appello: il decennio accentua le distanze. Il secondo grado, dove per ovvi motivi affluiscono meno cause rispetto al primo grado, conferma una\u00a0eterogeneit\u00e0 territoriale\u00a0che si misura bene sulla scala decennale. Alcuni distretti segnano\u00a0miglioramenti strutturali\u00a0fra il 2014 e il 2024: a Taranto\u00a0il clearance rate cresce di quasi mezzo punto (0,46),\u00a0ad Ancona\u00a0dello 0,21,\u00a0a L\u2019Aquila\u00a0di\u00a0+0,17\u00a0e\u00a0a Genova\u00a0di\u00a0+0,11\u00a0punti.<br \/>Altre Corti d\u2019Appello, invece,\u00a0arretrano sensibilmente: Perugia\u00a0scivola di\u00a0oltre un punto (-1,07),\u00a0di mezzo punto Caltanissetta (-0,55) e Roma\u00a0(-0,54),\u00a0Reggio Calabria\u00a0cala di\u00a0-0,38,\u00a0Lecce\u00a0di\u00a00,36\u00a0e\u00a0Venezia\u00a0di\u00a0-0,20. Nel 2024, a fotografia del presente, il divario resta netto, con\u00a0Trieste a 0,65\u00a0e\u00a0Venezia a 0,58\u00a0sul fondo della graduatoria, a fronte di distretti che superano con decisione la soglia dell\u2019equilibrio. \u201cLe differenze tra distretti sono il vero moltiplicatore delle disuguaglianze per cittadini e imprese: dove l\u2019organizzazione funziona, il sistema regge; altrove, i ritardi diventano strutturali\u201d, osserva\u00a0l\u2019avvocato Martinez.<br \/>Tribunali: punte di efficienza e cali significativi sul lungo periodo. Nel primo grado, la variazione 2014-2024\u00a0evidenzia una\u00a0peculiarit\u00e0 geografica\u00a0altrettanto marcata.<br \/>Spiccano\u00a0miglioramenti\u00a0in sedi che nel decennio guadagnano terreno, come\u00a0Locri\u00a0(+0,45) e\u00a0Patti\u00a0(+0,34), mentre\u00a0Napoli\u00a0(-0,23),\u00a0Bari\u00a0(-0,14) e\u00a0Benevento\u00a0(-0,13) mostrano un indebolimento della capacit\u00e0 di smaltimento. Nella foto del 2024 restano in alto\u00a0Trieste (1,32),\u00a0Genova (1,31)\u00a0e\u00a0Ancona (1,31), mentre\u00a0Salerno (0,90)\u00a0e\u00a0Campobasso (0,87)\u00a0non raggiungono l\u2019equilibrio e accumulano ulteriore arretrato. Questa lettura su dieci anni spiega perch\u00e8 alcuni territori siano riusciti a\u00a0contenere la pendenza del carico\u00a0mentre altri l\u2019hanno vista crescere.<br \/>Materie: decennio di polarizzazione, 2024 ancora \u201ca due velocit\u00e0\u201d. La prospettiva di lungo periodo conferma tendenze contrapposte\u00a0tra le materie pi\u00f9\u00a0standardizzabili\u00a0e quelle\u00a0ad alta complessit\u00e0 o volume. Nel 2024, coerentemente con questa tendenza,\u00a0contratti bancari (1,63)\u00a0e\u00a0responsabilit\u00e0 extracontrattuale (1,48)\u00a0si mantengono sopra soglia, cos\u00ec come\u00a0le successioni (1,17), mentre\u00a0protezione internazionale (0,52),\u00a0famiglia contenziosa (0,64)\u00a0ed\u00a0esecuzioni immobiliari (fino a\u00a00,38\u00a0nell\u2019espropriazione immobiliare) restano le aree pi\u00f9 critiche. \u201cLe materie \u201cpesanti\u201d, se non gestite con processi dedicati e risorse mirate, trascinano verso il basso l\u2019intero sistema: il decennio lo dimostra e il 2024 lo conferma\u201d, sottolinea\u00a0Antonello Martinez.<br \/>Il\u00a02014-2024\u00a0consegna un\u2019Italia giudiziaria\u00a0a pi\u00f9 velocit\u00e0: alcuni uffici hanno consolidato pratiche virtuose e\u00a0ridotto l\u2019arretrato, altri hanno scontato\u00a0limiti organizzativi\u00a0e ondate di contenzioso difficili da assorbire. La priorit\u00e0 non \u00e8 solo riportare l\u2019indice nazionale a\u00a01,00, ma\u00a0stabilizzarlo\u00a0nel tempo, uniformando gli standard minimi fra territori e intervenendo selettivamente sulle materie che assorbono pi\u00f9 risorse. Secondo il presidente dell\u2019Associazione Italiana Avvocati d\u2019Impresa Antonello Martinez: \u201cGovernance, organici e digitale, con\u00a0misure selettive\u00a0su protezione internazionale, famiglia contenziosa ed esecuzioni: qui si gioca la tenuta del prossimo decennio. Le esperienze degli uffici pi\u00f9 veloci dimostrano che si pu\u00f2 fare\u201d.<\/p>\n<p> \u2013 Foto ufficio stampa Associazione Italiana Avvocati d\u2019Impresa \u2013<br \/>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) \u2013 Nel 2024 la giustizia civile italiana \u00e8 ancora poco sotto la soglia di equilibrio tra procedimenti definiti e sopravvenuti (clearance rate 0,99), ma \u00e8 il\u00a0trend decennale\u00a0a spiegare la traiettoria di un sistema in affanno:\u00a0dal 2014 al 2024 l\u2019indice nazionale scende da 1,39 a 1,13, con una\u00a0variazione di -0,26 punti. L\u2019analisi fatta dall\u2019Associazione [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":77921,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-77920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giustizia civile in affanno, nel 2024 meno processi smaltiti di quelli nuovi - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giustizia civile in affanno, nel 2024 meno processi smaltiti di quelli nuovi - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"ROMA (ITALPRESS) \u2013 Nel 2024 la giustizia civile italiana \u00e8 ancora poco sotto la soglia di equilibrio tra procedimenti definiti e sopravvenuti (clearance rate 0,99), ma \u00e8 il\u00a0trend decennale\u00a0a spiegare la traiettoria di un sistema in affanno:\u00a0dal 2014 al 2024 l\u2019indice nazionale scende da 1,39 a 1,13, con una\u00a0variazione di -0,26 punti. L\u2019analisi fatta dall\u2019Associazione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-01T10:04:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Giustizia civile in affanno, nel 2024 meno processi smaltiti di quelli nuovi\",\"datePublished\":\"2026-06-01T10:04:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\\\/\"},\"wordCount\":603,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/20260601_0312.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\\\/\",\"name\":\"Giustizia civile in affanno, nel 2024 meno processi smaltiti di quelli nuovi - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/20260601_0312.jpg\",\"datePublished\":\"2026-06-01T10:04:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/20260601_0312.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/20260601_0312.jpg\",\"width\":1280,\"height\":878},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/06\\\/01\\\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giustizia civile in affanno, nel 2024 meno processi smaltiti di quelli nuovi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giustizia civile in affanno, nel 2024 meno processi smaltiti di quelli nuovi - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\/","og_locale":"it_IT","og_type":"article","og_title":"Giustizia civile in affanno, nel 2024 meno processi smaltiti di quelli nuovi - Live Magazine","og_description":"ROMA (ITALPRESS) \u2013 Nel 2024 la giustizia civile italiana \u00e8 ancora poco sotto la soglia di equilibrio tra procedimenti definiti e sopravvenuti (clearance rate 0,99), ma \u00e8 il\u00a0trend decennale\u00a0a spiegare la traiettoria di un sistema in affanno:\u00a0dal 2014 al 2024 l\u2019indice nazionale scende da 1,39 a 1,13, con una\u00a0variazione di -0,26 punti. L\u2019analisi fatta dall\u2019Associazione [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-06-01T10:04:10+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Giustizia civile in affanno, nel 2024 meno processi smaltiti di quelli nuovi","datePublished":"2026-06-01T10:04:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\/"},"wordCount":603,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/06\/20260601_0312.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\/","name":"Giustizia civile in affanno, nel 2024 meno processi smaltiti di quelli nuovi - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/06\/20260601_0312.jpg","datePublished":"2026-06-01T10:04:10+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/06\/20260601_0312.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/06\/20260601_0312.jpg","width":1280,"height":878},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/06\/01\/giustizia-civile-in-affanno-nel-2024-meno-processi-smaltiti-di-quelli-nuovi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Giustizia civile in affanno, nel 2024 meno processi smaltiti di quelli nuovi"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/06\/20260601_0312.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/77920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=77920"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/77920\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/77921"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=77920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=77920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=77920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}