{"id":77789,"date":"2026-05-29T18:04:02","date_gmt":"2026-05-29T16:04:02","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/05\/29\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\/"},"modified":"2026-05-29T18:04:02","modified_gmt":"2026-05-29T16:04:02","slug":"energia-di-sciascio-la-regione-puglia-fara-la-sua-parte","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/05\/29\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\/","title":{"rendered":"<div>Energia, Di Sciascio &#8220;La Regione Puglia far\u00e0 la sua parte&#8221;<\/div>"},"content":{"rendered":"<p>    <video-js id=\"videojs6a571255d5f0d\" class=\"vjs-big-play-centered\" controls preload=\"auto\" playsinline data-setup='{\"fluid\": true}'>\r\n        <source src=\"https:\/\/video.italpress.com\/play\/mp4\/video\/2l0P\" type=\"video\/mp4\" \/>\r\n    <\/video-js>\r\n           <br \/>\n<\/p>\n<div> LECCE (ITALPRESS) &#8211; &#8220;La Puglia \u00e8 gi\u00e0 un importante riferimento per l&#8217;energia per il Paese, svolgiamo un ruolo determinato dalla geografia importante, siamo in questo momento esportatori di energia. Cerchiamo di fare la nostra parte, ma \u00e8 importante anche un tema di accettazione perch\u00e9 la nostra Regione ha una ricchezza di paesaggio, il 13% del PIL \u00e8 fatto di turismo; c&#8217;\u00e8 un tema di vantaggio per le famiglie e per le imprese, siamo esportatori di energia e va tenuto presente che c&#8217;\u00e8 ancora un prezzo unico che non d\u00e0 nessun beneficio alle nostre famiglie. La Regione Puglia ha fatto e far\u00e0 la sua parte anche in termine di raggiungimenti del target che ci sono stati posti dal Ministero, sapendo bene che non dobbiamo solo pagare pegno, \u00e8 importante valorizzare anche i territori&#8221;. Cos\u00ec Eugenio Di Sciascio, Assessore allo Sviluppo Economico e al Lavoro della Regione Puglia, in occasione del Festival dell&#8217;Energia in corso a Lecce.<br \/>\nxb1\/fsc\/gtr<\/div>\n","protected":false},"excerpt":{"rendered":"<p>LECCE (ITALPRESS) &#8211; &#8220;La Puglia \u00e8 gi\u00e0 un importante riferimento per l&#8217;energia per il Paese, svolgiamo un ruolo determinato dalla geografia importante, siamo in questo momento esportatori di energia. Cerchiamo di fare la nostra parte, ma \u00e8 importante anche un tema di accettazione perch\u00e9 la nostra Regione ha una ricchezza di paesaggio, il 13% del [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":77790,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1171],"tags":[],"class_list":["post-77789","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-video","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Energia, Di Sciascio &quot;La Regione Puglia far\u00e0 la sua parte&quot; - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/05\/29\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Energia, Di Sciascio &quot;La Regione Puglia far\u00e0 la sua parte&quot; - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"LECCE (ITALPRESS) &#8211; &#8220;La Puglia \u00e8 gi\u00e0 un importante riferimento per l&#8217;energia per il Paese, svolgiamo un ruolo determinato dalla geografia importante, siamo in questo momento esportatori di energia. Cerchiamo di fare la nostra parte, ma \u00e8 importante anche un tema di accettazione perch\u00e9 la nostra Regione ha una ricchezza di paesaggio, il 13% del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/05\/29\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-29T16:04:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/05\\\/29\\\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/05\\\/29\\\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Energia, Di Sciascio &#8220;La Regione Puglia far\u00e0 la sua parte&#8221;\",\"datePublished\":\"2026-05-29T16:04:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/05\\\/29\\\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\\\/\"},\"wordCount\":177,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/05\\\/29\\\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/2l0P.jpg\",\"articleSection\":[\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/05\\\/29\\\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/05\\\/29\\\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\\\/\",\"name\":\"Energia, Di Sciascio \\\"La Regione Puglia far\u00e0 la sua parte\\\" - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/05\\\/29\\\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/05\\\/29\\\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/2l0P.jpg\",\"datePublished\":\"2026-05-29T16:04:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/05\\\/29\\\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/05\\\/29\\\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/05\\\/29\\\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/2l0P.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/2l0P.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/05\\\/29\\\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Energia, Di Sciascio &#8220;La Regione Puglia far\u00e0 la sua parte&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Energia, Di Sciascio \"La Regione Puglia far\u00e0 la sua parte\" - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/05\/29\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\/","og_locale":"it_IT","og_type":"article","og_title":"Energia, Di Sciascio \"La Regione Puglia far\u00e0 la sua parte\" - Live Magazine","og_description":"LECCE (ITALPRESS) &#8211; &#8220;La Puglia \u00e8 gi\u00e0 un importante riferimento per l&#8217;energia per il Paese, svolgiamo un ruolo determinato dalla geografia importante, siamo in questo momento esportatori di energia. Cerchiamo di fare la nostra parte, ma \u00e8 importante anche un tema di accettazione perch\u00e9 la nostra Regione ha una ricchezza di paesaggio, il 13% del [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/05\/29\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-05-29T16:04:02+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/05\/29\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/05\/29\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Energia, Di Sciascio &#8220;La Regione Puglia far\u00e0 la sua parte&#8221;","datePublished":"2026-05-29T16:04:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/05\/29\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\/"},"wordCount":177,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/05\/29\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/05\/2l0P.jpg","articleSection":["Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/05\/29\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/05\/29\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\/","name":"Energia, Di Sciascio \"La Regione Puglia far\u00e0 la sua parte\" - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/05\/29\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/05\/29\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/05\/2l0P.jpg","datePublished":"2026-05-29T16:04:02+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/05\/29\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/05\/29\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/05\/29\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/05\/2l0P.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/05\/2l0P.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/05\/29\/energia-di-sciascio-la-regione-puglia-fara-la-sua-parte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Energia, Di Sciascio &#8220;La Regione Puglia far\u00e0 la sua parte&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/05\/2l0P.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/77789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=77789"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/77789\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/77790"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=77789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=77789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=77789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}