{"id":74077,"date":"2026-04-14T21:02:46","date_gmt":"2026-04-14T19:02:46","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\/"},"modified":"2026-04-14T21:02:46","modified_gmt":"2026-04-14T19:02:46","slug":"ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\/","title":{"rendered":"<div>Ungheria, Benifei &#8220;Finita era Orban, nuovo governo riporta Budapest in alveo Ue&#8221;<\/div>"},"content":{"rendered":"<p>    <video-js id=\"videojs6a577083002a5\" class=\"vjs-big-play-centered\" controls preload=\"auto\" playsinline data-setup='{\"fluid\": true}'>\r\n        <source src=\"https:\/\/video.italpress.com\/play\/mp4\/video\/N6Mv\" type=\"video\/mp4\" \/>\r\n    <\/video-js>\r\n           <br \/>\n<\/p>\n<div> BRUXELLES (BELGIO) (ITALPRESS) &#8211; \u201cIn Ungheria \u00e8 finito il sistema di potere di Orban: il nuovo governo ha la possibilit\u00e0 e la volont\u00e0 di riportare finalmente il Paese in un alveo pienamente europeo\u201d. Lo ha dichiarato l\u2019eurodeputato del Partito Democratico Brando Benifei, commentando a Bruxelles la svolta politica a Budapest dopo sedici anni di governo Fidesz. Secondo Benifei, la vittoria di un nuovo Primo Ministro moderato ed europeista segna un cambio di assetto radicale: \u201cSiamo di fronte a un&#8217;impostazione opposta rispetto al passato su temi fondamentali, con una chiara vicinanza all\u2019Europa piuttosto che all\u2019asse Putin-Trump, che per Orban rappresentava un riferimento strategico\u201d. <\/p>\n<p>xf4\/sat\/mca1<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>BRUXELLES (BELGIO) (ITALPRESS) &#8211; \u201cIn Ungheria \u00e8 finito il sistema di potere di Orban: il nuovo governo ha la possibilit\u00e0 e la volont\u00e0 di riportare finalmente il Paese in un alveo pienamente europeo\u201d. Lo ha dichiarato l\u2019eurodeputato del Partito Democratico Brando Benifei, commentando a Bruxelles la svolta politica a Budapest dopo sedici anni di governo [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":74078,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1171],"tags":[],"class_list":["post-74077","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-video","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ungheria, Benifei &quot;Finita era Orban, nuovo governo riporta Budapest in alveo Ue&quot; - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ungheria, Benifei &quot;Finita era Orban, nuovo governo riporta Budapest in alveo Ue&quot; - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"BRUXELLES (BELGIO) (ITALPRESS) &#8211; \u201cIn Ungheria \u00e8 finito il sistema di potere di Orban: il nuovo governo ha la possibilit\u00e0 e la volont\u00e0 di riportare finalmente il Paese in un alveo pienamente europeo\u201d. Lo ha dichiarato l\u2019eurodeputato del Partito Democratico Brando Benifei, commentando a Bruxelles la svolta politica a Budapest dopo sedici anni di governo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-14T19:02:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Ungheria, Benifei &#8220;Finita era Orban, nuovo governo riporta Budapest in alveo Ue&#8221;\",\"datePublished\":\"2026-04-14T19:02:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\\\/\"},\"wordCount\":132,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/N6Mv.jpg\",\"articleSection\":[\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\\\/\",\"name\":\"Ungheria, Benifei \\\"Finita era Orban, nuovo governo riporta Budapest in alveo Ue\\\" - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/N6Mv.jpg\",\"datePublished\":\"2026-04-14T19:02:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/N6Mv.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/N6Mv.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ungheria, Benifei &#8220;Finita era Orban, nuovo governo riporta Budapest in alveo Ue&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ungheria, Benifei \"Finita era Orban, nuovo governo riporta Budapest in alveo Ue\" - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\/","og_locale":"it_IT","og_type":"article","og_title":"Ungheria, Benifei \"Finita era Orban, nuovo governo riporta Budapest in alveo Ue\" - Live Magazine","og_description":"BRUXELLES (BELGIO) (ITALPRESS) &#8211; \u201cIn Ungheria \u00e8 finito il sistema di potere di Orban: il nuovo governo ha la possibilit\u00e0 e la volont\u00e0 di riportare finalmente il Paese in un alveo pienamente europeo\u201d. Lo ha dichiarato l\u2019eurodeputato del Partito Democratico Brando Benifei, commentando a Bruxelles la svolta politica a Budapest dopo sedici anni di governo [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-04-14T19:02:46+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Ungheria, Benifei &#8220;Finita era Orban, nuovo governo riporta Budapest in alveo Ue&#8221;","datePublished":"2026-04-14T19:02:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\/"},"wordCount":132,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/04\/N6Mv.jpg","articleSection":["Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\/","name":"Ungheria, Benifei \"Finita era Orban, nuovo governo riporta Budapest in alveo Ue\" - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/04\/N6Mv.jpg","datePublished":"2026-04-14T19:02:46+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/04\/N6Mv.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/04\/N6Mv.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/ungheria-benifei-finita-era-orban-nuovo-governo-riporta-budapest-in-alveo-ue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Ungheria, Benifei &#8220;Finita era Orban, nuovo governo riporta Budapest in alveo Ue&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/04\/N6Mv.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/74077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=74077"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/74077\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/74078"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=74077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=74077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=74077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}