{"id":74019,"date":"2026-04-14T12:04:18","date_gmt":"2026-04-14T10:04:18","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\/"},"modified":"2026-04-14T12:04:18","modified_gmt":"2026-04-14T10:04:18","slug":"abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\/","title":{"rendered":"Abodi \u201cServe una definizione dei programmi per dare senso al ko con Bosnia\u201d"},"content":{"rendered":"<div>\n<p>ROMA (ITALPRESS) \u2013 \u201cA prescindere dai nomi serve una definizione dei programmi: se gli interessi individuali non sono in sintonia con quello complessivi le cose che devono succedere non succedono. L\u2019esperienza dolorosa dal punto di vista sportivo contro la Bosnia rischia di non avere nemmeno un senso\u201d. Queste le parole di Andrea Abodi, ministro per lo sport e i giovani, a margine della prima edizione del Luiss Sport Forum a Roma. \u201cTesta a testa Malag\u00f2-Abete? Io penso che sia dovere delle componenti e quindi non entro nel merito perch\u00e8 non mi sembra opportuno. Sono affascinato dalle cose da fare, che non sono state fatte neanche con il 98.7%, a dimostrazione che non \u00e8 la quantit\u00e0 del consenso ma la qualit\u00e0 della collaborazione tra le componenti a fare la differenza. Abbiamo messo in ascolto tutte le componenti e stiamo lavorando a testa bassa\u201d, aggiunge Abodi. In merito alla relazione del presidente della Figc Gabriele Gravina sulla salute del calcio italiano, Abodi sottolinea che \u201cla politica \u00e8 sempre un riferimento da questo punto di vista e quando qualcosa non funziona \u00e8 sempre colpa della politica. Io non me la sono mai presa con nessun altro. Per il bene comune dobbiamo sederci attorno a un tavolo con tutte le componenti e prendere quelle decisioni che non sono state presi in questi anni nonostante l\u2019ampio consenso, conclude Abodi.\u00a0<br \/>\u2013 Foto Ipa Agency \u2013<br \/>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) \u2013 \u201cA prescindere dai nomi serve una definizione dei programmi: se gli interessi individuali non sono in sintonia con quello complessivi le cose che devono succedere non succedono. L\u2019esperienza dolorosa dal punto di vista sportivo contro la Bosnia rischia di non avere nemmeno un senso\u201d. Queste le parole di Andrea Abodi, ministro per [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":74020,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-74019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abodi \u201cServe una definizione dei programmi per dare senso al ko con Bosnia\u201d - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abodi \u201cServe una definizione dei programmi per dare senso al ko con Bosnia\u201d - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"ROMA (ITALPRESS) \u2013 \u201cA prescindere dai nomi serve una definizione dei programmi: se gli interessi individuali non sono in sintonia con quello complessivi le cose che devono succedere non succedono. L\u2019esperienza dolorosa dal punto di vista sportivo contro la Bosnia rischia di non avere nemmeno un senso\u201d. Queste le parole di Andrea Abodi, ministro per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-14T10:04:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Abodi \u201cServe una definizione dei programmi per dare senso al ko con Bosnia\u201d\",\"datePublished\":\"2026-04-14T10:04:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\\\/\"},\"wordCount\":239,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/20260414_0298.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\\\/\",\"name\":\"Abodi \u201cServe una definizione dei programmi per dare senso al ko con Bosnia\u201d - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/20260414_0298.jpg\",\"datePublished\":\"2026-04-14T10:04:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/20260414_0298.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/20260414_0298.jpg\",\"width\":1200,\"height\":799},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abodi \u201cServe una definizione dei programmi per dare senso al ko con Bosnia\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abodi \u201cServe una definizione dei programmi per dare senso al ko con Bosnia\u201d - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\/","og_locale":"it_IT","og_type":"article","og_title":"Abodi \u201cServe una definizione dei programmi per dare senso al ko con Bosnia\u201d - Live Magazine","og_description":"ROMA (ITALPRESS) \u2013 \u201cA prescindere dai nomi serve una definizione dei programmi: se gli interessi individuali non sono in sintonia con quello complessivi le cose che devono succedere non succedono. L\u2019esperienza dolorosa dal punto di vista sportivo contro la Bosnia rischia di non avere nemmeno un senso\u201d. Queste le parole di Andrea Abodi, ministro per [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-04-14T10:04:18+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Abodi \u201cServe una definizione dei programmi per dare senso al ko con Bosnia\u201d","datePublished":"2026-04-14T10:04:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\/"},"wordCount":239,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/04\/20260414_0298.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\/","name":"Abodi \u201cServe una definizione dei programmi per dare senso al ko con Bosnia\u201d - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/04\/20260414_0298.jpg","datePublished":"2026-04-14T10:04:18+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/04\/20260414_0298.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/04\/20260414_0298.jpg","width":1200,"height":799},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/abodi-serve-una-definizione-dei-programmi-per-dare-senso-al-ko-con-bosnia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Abodi \u201cServe una definizione dei programmi per dare senso al ko con Bosnia\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/04\/20260414_0298.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/74019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=74019"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/74019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/74020"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=74019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=74019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=74019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}