{"id":74017,"date":"2026-04-14T12:04:16","date_gmt":"2026-04-14T10:04:16","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\/"},"modified":"2026-04-14T12:04:16","modified_gmt":"2026-04-14T10:04:16","slug":"salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\/","title":{"rendered":"Salvini \u201cO l\u2019Europa sospende il patto di stabilit\u00e0 o costretti a fare da soli\u201d"},"content":{"rendered":"<div>\n<p>ROMA (ITALPRESS) \u2013 \u201cNon so a cosa stiamo assistendo: la situazione \u00e8 gi\u00e0 complicata di suo senza che qualcuno si svegli attaccando il Papa, c\u2019\u00e8 un limite alla pazienza umana\u201d. Cos\u00ec il vicepremier e ministro Matteo Salvini, ospite a Non Stop News su Rtl 102.5. \u201cSe c\u2019\u00e8 una guida morale, spirituale e politica che sta invitando al dialogo e chiedendo la risoluzione dei conflitti \u00e8 proprio il Papa \u2013 continua Salvini, \u2013 Mi interessa poco sapere cosa intendesse il presidente degli Stati Uniti, ma so che la situazione economica per milioni di italiani rischia di diventare sempre pi\u00f9 complicata; stiamo ipotizzando una serie di soluzioni, come il blocco del conto bollette su luce, gas e gasolio per tutto il 2026 al pre guerra in Iran. C\u2019\u00e8 bisogno di collaborazione anche da parte dell\u2019Europa, che lasci un minimo di libert\u00e0 di manovra ai singoli paesi: o la sospensione del patto di stabilit\u00e0 la fa Bruxelles di sua iniziativa o saremo costretti a fare da soli. Non chiediamo i soldi in pi\u00f9, ma semplicemente di usare quelli che abbiamo a bilancio per bloccare ogni aumento almeno per tutto il 2026\u201d, conclude.<br \/>(ITALPRESS).<br \/>-Foto: Ipa Agency-<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) \u2013 \u201cNon so a cosa stiamo assistendo: la situazione \u00e8 gi\u00e0 complicata di suo senza che qualcuno si svegli attaccando il Papa, c\u2019\u00e8 un limite alla pazienza umana\u201d. Cos\u00ec il vicepremier e ministro Matteo Salvini, ospite a Non Stop News su Rtl 102.5. \u201cSe c\u2019\u00e8 una guida morale, spirituale e politica che sta [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":74018,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-74017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salvini \u201cO l\u2019Europa sospende il patto di stabilit\u00e0 o costretti a fare da soli\u201d - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salvini \u201cO l\u2019Europa sospende il patto di stabilit\u00e0 o costretti a fare da soli\u201d - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"ROMA (ITALPRESS) \u2013 \u201cNon so a cosa stiamo assistendo: la situazione \u00e8 gi\u00e0 complicata di suo senza che qualcuno si svegli attaccando il Papa, c\u2019\u00e8 un limite alla pazienza umana\u201d. Cos\u00ec il vicepremier e ministro Matteo Salvini, ospite a Non Stop News su Rtl 102.5. \u201cSe c\u2019\u00e8 una guida morale, spirituale e politica che sta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-14T10:04:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Salvini \u201cO l\u2019Europa sospende il patto di stabilit\u00e0 o costretti a fare da soli\u201d\",\"datePublished\":\"2026-04-14T10:04:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\\\/\"},\"wordCount\":201,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/20260414_0167.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\\\/\",\"name\":\"Salvini \u201cO l\u2019Europa sospende il patto di stabilit\u00e0 o costretti a fare da soli\u201d - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/20260414_0167.jpg\",\"datePublished\":\"2026-04-14T10:04:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/20260414_0167.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/20260414_0167.jpg\",\"width\":830,\"height\":552},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/04\\\/14\\\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salvini \u201cO l\u2019Europa sospende il patto di stabilit\u00e0 o costretti a fare da soli\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salvini \u201cO l\u2019Europa sospende il patto di stabilit\u00e0 o costretti a fare da soli\u201d - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\/","og_locale":"it_IT","og_type":"article","og_title":"Salvini \u201cO l\u2019Europa sospende il patto di stabilit\u00e0 o costretti a fare da soli\u201d - Live Magazine","og_description":"ROMA (ITALPRESS) \u2013 \u201cNon so a cosa stiamo assistendo: la situazione \u00e8 gi\u00e0 complicata di suo senza che qualcuno si svegli attaccando il Papa, c\u2019\u00e8 un limite alla pazienza umana\u201d. Cos\u00ec il vicepremier e ministro Matteo Salvini, ospite a Non Stop News su Rtl 102.5. \u201cSe c\u2019\u00e8 una guida morale, spirituale e politica che sta [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-04-14T10:04:16+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Salvini \u201cO l\u2019Europa sospende il patto di stabilit\u00e0 o costretti a fare da soli\u201d","datePublished":"2026-04-14T10:04:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\/"},"wordCount":201,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/04\/20260414_0167.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\/","name":"Salvini \u201cO l\u2019Europa sospende il patto di stabilit\u00e0 o costretti a fare da soli\u201d - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/04\/20260414_0167.jpg","datePublished":"2026-04-14T10:04:16+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/04\/20260414_0167.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/04\/20260414_0167.jpg","width":830,"height":552},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/04\/14\/salvini-o-leuropa-sospende-il-patto-di-stabilita-o-costretti-a-fare-da-soli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Salvini \u201cO l\u2019Europa sospende il patto di stabilit\u00e0 o costretti a fare da soli\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/04\/20260414_0167.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/74017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=74017"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/74017\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/74018"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=74017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=74017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=74017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}