{"id":72812,"date":"2026-03-28T15:02:56","date_gmt":"2026-03-28T14:02:56","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\/"},"modified":"2026-03-28T15:02:56","modified_gmt":"2026-03-28T14:02:56","slug":"attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\/","title":{"rendered":"Attiviste Peta bloccano papamobile a Monaco per protesta contro le corride"},"content":{"rendered":"<p>    <video-js id=\"videojs6a040277e17ef\" class=\"vjs-big-play-centered\" controls preload=\"auto\" playsinline data-setup='{\"fluid\": true}'>\r\n        <source src=\"https:\/\/video.italpress.com\/play\/mp4\/video\/pjj1\" type=\"video\/mp4\" \/>\r\n    <\/video-js>\r\n           <br \/>\n<\/p>\n<div> MONACO (MONTECARLO) (ITALPRESS) &#8211; La processione di Papa Leone a Monaco \u00e8 stata interrotta da due sostenitrici della PETA che &#8220;si sono gettate davanti alla papamobile per implorare Sua Santit\u00e0 di recidere i legami della Chiesa cattolica con la corrida e condannare questo vile bagno di sangue&#8221;. &#8220;Portando cartelli con la scritta &#8220;Papa Leone: Aiutaci a Porre Fine alla Corrida&#8221;, le difensori degli animali &#8220;si sono inginocchiate davanti al veicolo del pontefice fino a quando la polizia non le ha arrestate e trascinate via&#8221;, si legge in una nota. &#8220;La violenza della corrida \u00e8 totalmente incompatibile con gli insegnamenti cristiani di gentilezza e compassione &#8211; afferma Mimi Bekhechi, Vicepresidente senior della PETA per l&#8217;Europa -. La PETA chiede a Papa Leone di recidere i legami della Chiesa cattolica con questa sanguinosa industria e di denunciarla per quello che \u00e8: un affronto ai valori cristiani&#8221;.<\/p>\n<p>fsc\/mca1<\/p>\n<p>(Fonte video: Profilo Twitter PETA UK)<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>MONACO (MONTECARLO) (ITALPRESS) &#8211; La processione di Papa Leone a Monaco \u00e8 stata interrotta da due sostenitrici della PETA che &#8220;si sono gettate davanti alla papamobile per implorare Sua Santit\u00e0 di recidere i legami della Chiesa cattolica con la corrida e condannare questo vile bagno di sangue&#8221;. &#8220;Portando cartelli con la scritta &#8220;Papa Leone: Aiutaci [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":72813,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1171],"tags":[],"class_list":["post-72812","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-video","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Attiviste Peta bloccano papamobile a Monaco per protesta contro le corride - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Attiviste Peta bloccano papamobile a Monaco per protesta contro le corride - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"MONACO (MONTECARLO) (ITALPRESS) &#8211; La processione di Papa Leone a Monaco \u00e8 stata interrotta da due sostenitrici della PETA che &#8220;si sono gettate davanti alla papamobile per implorare Sua Santit\u00e0 di recidere i legami della Chiesa cattolica con la corrida e condannare questo vile bagno di sangue&#8221;. &#8220;Portando cartelli con la scritta &#8220;Papa Leone: Aiutaci [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-28T14:02:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Attiviste Peta bloccano papamobile a Monaco per protesta contro le corride\",\"datePublished\":\"2026-03-28T14:02:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\\\/\"},\"wordCount\":172,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/pjj1.jpg\",\"articleSection\":[\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\\\/\",\"name\":\"Attiviste Peta bloccano papamobile a Monaco per protesta contro le corride - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/pjj1.jpg\",\"datePublished\":\"2026-03-28T14:02:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/pjj1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/pjj1.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Attiviste Peta bloccano papamobile a Monaco per protesta contro le corride\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Attiviste Peta bloccano papamobile a Monaco per protesta contro le corride - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\/","og_locale":"it_IT","og_type":"article","og_title":"Attiviste Peta bloccano papamobile a Monaco per protesta contro le corride - Live Magazine","og_description":"MONACO (MONTECARLO) (ITALPRESS) &#8211; La processione di Papa Leone a Monaco \u00e8 stata interrotta da due sostenitrici della PETA che &#8220;si sono gettate davanti alla papamobile per implorare Sua Santit\u00e0 di recidere i legami della Chiesa cattolica con la corrida e condannare questo vile bagno di sangue&#8221;. &#8220;Portando cartelli con la scritta &#8220;Papa Leone: Aiutaci [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-03-28T14:02:56+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Attiviste Peta bloccano papamobile a Monaco per protesta contro le corride","datePublished":"2026-03-28T14:02:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\/"},"wordCount":172,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/pjj1.jpg","articleSection":["Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\/","name":"Attiviste Peta bloccano papamobile a Monaco per protesta contro le corride - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/pjj1.jpg","datePublished":"2026-03-28T14:02:56+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/pjj1.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/pjj1.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/attiviste-peta-bloccano-papamobile-a-monaco-per-protesta-contro-le-corride\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Attiviste Peta bloccano papamobile a Monaco per protesta contro le corride"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/pjj1.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/72812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=72812"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/72812\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/72813"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=72812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=72812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=72812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}