{"id":72782,"date":"2026-03-28T09:02:44","date_gmt":"2026-03-28T08:02:44","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\/"},"modified":"2026-03-28T09:02:44","modified_gmt":"2026-03-28T08:02:44","slug":"pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\/","title":{"rendered":"<div>Pecoraro Scanio &#8220;Sovranit\u00e0 digitale ed energetica priorit\u00e0 per sostenibilit\u00e0 Ue&#8221;<\/div>"},"content":{"rendered":"<p>    <video-js id=\"videojs6a041232ebf19\" class=\"vjs-big-play-centered\" controls preload=\"auto\" playsinline data-setup='{\"fluid\": true}'>\r\n        <source src=\"https:\/\/video.italpress.com\/play\/mp4\/video\/3xxr\" type=\"video\/mp4\" \/>\r\n    <\/video-js>\r\n           <br \/>\n<\/p>\n<div> ROMA (ITALPRESS) &#8211; &#8220;Il Governo italiano e le istituzioni europee devono impegnarsi con maggiore determinazione per rafforzare la sovranit\u00e0 digitale europea, una condizione ormai indispensabile per garantire la democrazia, la sicurezza e la sostenibilit\u00e0 del nostro modello di sviluppo&#8221;. Lo dichiara Alfonso Pecoraro Scanio, Presidente della Fondazione UniVerde e promotore della rete EcoDigital dopo la visita all\u2019Innovation Training Summit by Efi. &#8220;Non possiamo essere in balia di poche grandi multinazionali globali che controllano dati, piattaforme digitali e tecnologie strategiche. L\u2019Europa deve rafforzare la propria autonomia su intelligenza artificiale, gestione dei dati, cybersecurity e digitalizzazione, per proteggere la privacy dei cittadini e l\u2019integrit\u00e0 dei processi democratici, inclusa la tutela delle elezioni da possibili interferenze esterne e manipolazioni digitali&#8221;. Secondo Pecoraro Scanio &#8220;la vera sovranit\u00e0 oggi si gioca sulla capacit\u00e0 di controllare infrastrutture digitali, dati e tecnologie strategiche. Per questo serve una forte politica industriale europea sul cloud, sull\u2019intelligenza artificiale e sulle infrastrutture critiche digitali&#8221;. Il Presidente della Fondazione UniVerde sottolinea inoltre il legame tra transizione digitale e transizione ecologica: &#8220;La sfida EcoDigital consiste proprio nel coniugare innovazione tecnologica e sostenibilit\u00e0 ambientale. I data center, ad esempio, devono essere sempre pi\u00f9 alimentati da energie rinnovabili e progettati secondo criteri di efficienza energetica, perch\u00e9 il consumo energetico del digitale \u00e8 in forte crescita&#8221;. &#8220;Non possiamo dipendere da multinazionali straniere per i dati e allo stesso tempo da scenari geopolitici instabili per l\u2019energia. Sovranit\u00e0 digitale e sovranit\u00e0 energetica devono diventare due pilastri della strategia europea, da sviluppare attraverso rinnovabili, efficienza energetica e innovazione tecnologica&#8221;. Infine Pecoraro Scanio, rilanciando la necessit\u00e0 della formazione per l\u2019innovazione conclude: &#8220;Chi si definisce sovranista dovrebbe mettere al primo posto proprio questi obiettivi: rafforzare la sovranit\u00e0 digitale ed energetica dell\u2019Europa e dell\u2019Italia significa difendere concretamente l\u2019interesse nazionale, la competitivit\u00e0 del sistema economico e la qualit\u00e0 della nostra democrazia&#8221;. <\/p>\n<p>pc\/mca1<\/p>\n<p>(Fonte video: Fondazione UniVerde)<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) &#8211; &#8220;Il Governo italiano e le istituzioni europee devono impegnarsi con maggiore determinazione per rafforzare la sovranit\u00e0 digitale europea, una condizione ormai indispensabile per garantire la democrazia, la sicurezza e la sostenibilit\u00e0 del nostro modello di sviluppo&#8221;. Lo dichiara Alfonso Pecoraro Scanio, Presidente della Fondazione UniVerde e promotore della rete EcoDigital dopo la [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":72783,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1171],"tags":[],"class_list":["post-72782","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-video","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pecoraro Scanio &quot;Sovranit\u00e0 digitale ed energetica priorit\u00e0 per sostenibilit\u00e0 Ue&quot; - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pecoraro Scanio &quot;Sovranit\u00e0 digitale ed energetica priorit\u00e0 per sostenibilit\u00e0 Ue&quot; - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"ROMA (ITALPRESS) &#8211; &#8220;Il Governo italiano e le istituzioni europee devono impegnarsi con maggiore determinazione per rafforzare la sovranit\u00e0 digitale europea, una condizione ormai indispensabile per garantire la democrazia, la sicurezza e la sostenibilit\u00e0 del nostro modello di sviluppo&#8221;. Lo dichiara Alfonso Pecoraro Scanio, Presidente della Fondazione UniVerde e promotore della rete EcoDigital dopo la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-28T08:02:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Pecoraro Scanio &#8220;Sovranit\u00e0 digitale ed energetica priorit\u00e0 per sostenibilit\u00e0 Ue&#8221;\",\"datePublished\":\"2026-03-28T08:02:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\\\/\"},\"wordCount\":333,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/3xxr.jpg\",\"articleSection\":[\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\\\/\",\"name\":\"Pecoraro Scanio \\\"Sovranit\u00e0 digitale ed energetica priorit\u00e0 per sostenibilit\u00e0 Ue\\\" - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/3xxr.jpg\",\"datePublished\":\"2026-03-28T08:02:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/3xxr.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/3xxr.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/28\\\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pecoraro Scanio &#8220;Sovranit\u00e0 digitale ed energetica priorit\u00e0 per sostenibilit\u00e0 Ue&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pecoraro Scanio \"Sovranit\u00e0 digitale ed energetica priorit\u00e0 per sostenibilit\u00e0 Ue\" - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\/","og_locale":"it_IT","og_type":"article","og_title":"Pecoraro Scanio \"Sovranit\u00e0 digitale ed energetica priorit\u00e0 per sostenibilit\u00e0 Ue\" - Live Magazine","og_description":"ROMA (ITALPRESS) &#8211; &#8220;Il Governo italiano e le istituzioni europee devono impegnarsi con maggiore determinazione per rafforzare la sovranit\u00e0 digitale europea, una condizione ormai indispensabile per garantire la democrazia, la sicurezza e la sostenibilit\u00e0 del nostro modello di sviluppo&#8221;. Lo dichiara Alfonso Pecoraro Scanio, Presidente della Fondazione UniVerde e promotore della rete EcoDigital dopo la [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-03-28T08:02:44+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Pecoraro Scanio &#8220;Sovranit\u00e0 digitale ed energetica priorit\u00e0 per sostenibilit\u00e0 Ue&#8221;","datePublished":"2026-03-28T08:02:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\/"},"wordCount":333,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/3xxr.jpg","articleSection":["Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\/","name":"Pecoraro Scanio \"Sovranit\u00e0 digitale ed energetica priorit\u00e0 per sostenibilit\u00e0 Ue\" - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/3xxr.jpg","datePublished":"2026-03-28T08:02:44+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/3xxr.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/3xxr.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/28\/pecoraro-scanio-sovranita-digitale-ed-energetica-priorita-per-sostenibilita-ue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Pecoraro Scanio &#8220;Sovranit\u00e0 digitale ed energetica priorit\u00e0 per sostenibilit\u00e0 Ue&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/3xxr.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/72782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=72782"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/72782\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/72783"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=72782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=72782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=72782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}