{"id":72722,"date":"2026-03-26T21:03:11","date_gmt":"2026-03-26T20:03:11","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\/"},"modified":"2026-03-26T21:03:11","modified_gmt":"2026-03-26T20:03:11","slug":"cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\/","title":{"rendered":"Cina-Repubblica Ceca, incontro a Praga sulla cooperazione nella Supply-chain"},"content":{"rendered":"<div>\n<p>PRAGA (REPUBBLICA CECA) (XINHUA\/ITALPRESS) \u2013 Esponenti del mondo imprenditoriale, rappresentanti del settore e funzionari governativi provenienti da Cina e Repubblica Ceca si sono riuniti 24 Mar a Praga per un evento di promozione della quarta edizione della China International Supply Chain Expo (CISCE), mettendo in evidenza il crescente interesse nel rafforzamento della cooperazione economica e commerciale tra i due Paesi.<\/p>\n<p>\u201cL\u2019economia globale \u00e8 pi\u00f9 interconnessa che mai. Le catene di approvvigionamento sono la linfa vitale del commercio internazionale e la loro resilienza, efficienza e sostenibilit\u00e0 sono fondamentali per una prosperit\u00e0, un\u2019innovazione e una crescita condivise\u201d, ha affermato Richard Hlavaty, direttore del Dipartimento per i Paesi non europei del ministero dell\u2019Industria e del Commercio della Repubblica Ceca.<\/p>\n<p>Hlavaty ha affermato che la Repubblica Ceca attribuisce valore al suo partenariato con la Cina, sviluppatosi in settori che vanno da quello automobilistico e della manifattura fino a quello tecnologico e logistico. Eventi di questo tipo rafforzano la fiducia, il dialogo e la crescita reciproca e contribuiscono a creare catene di approvvigionamento efficienti, resilienti e sostenibili, ha aggiunto il direttore.<\/p>\n<p>L\u2019evento ha attirato rappresentanti di circa 70 aziende ceche e di circa 30 imprese cinesi gi\u00e0 operative o attive sul mercato ceco.<\/p>\n<p>I partecipanti hanno sottolineato l\u2019importanza di rafforzare la cooperazione nelle catene di approvvigionamento globali e hanno individuato nuove opportunit\u00e0 nella manifattura avanzata, nello sviluppo verde e nell\u2019innovazione.<\/p>\n<p>Frantisek Chaloupecky, vice presidente della Confederazione dell\u2019industria della Repubblica Ceca, ha dichiarato che la sua istituzione, che rappresenta oltre 11.000 aziende associate, sostiene attivamente la cooperazione tra le imprese ceche e cinesi e continuer\u00e0 a sostenere le aziende ceche nell\u2019ampliamento della cooperazione e delle attivit\u00e0 di investimento con partner cinesi.<\/p>\n<p>Durante l\u2019evento, l\u2019ambasciatore cinese nella Repubblica Ceca, Feng Biao, ha evidenziato i solidi legami economici tra i due Paesi, osservando che nel 2025 il commercio bilaterale ha raggiunto i 44,2 miliardi di dollari USA, pari a oltre l\u20198% del commercio estero complessivo della Repubblica Ceca.<\/p>\n<p>Feng ha sottolineato che la cooperazione economica e commerciale tra i due Paesi presenta un significativo potenziale, con nuove opportunit\u00e0 che emergono in settori come energia, infrastrutture, manifattura intelligente e veicoli a nuova energia, aggiungendo che entrambe le parti continueranno a sostenere la partecipazione delle imprese alle principali fiere commerciali, compresa la CISCE.<\/p>\n<p>Chen Limiao, responsabile della filiale di Praga della Industrial and Commercial Bank of China (ICBC), ha dichiarato che l\u2019ICBC continuer\u00e0 a sostenere le aziende ceche nell\u2019esplorazione delle opportunit\u00e0 offerte dal mercato cinese, in particolare nei settori della nuova energia e dell\u2019alta tecnologia.<\/p>\n<p>L\u2019evento \u00e8 stato organizzato dal Consiglio cinese per la promozione del commercio internazionale, dall\u2019ambasciata cinese nella Repubblica Ceca, dal ministero dell\u2019Industria e del Commercio della Repubblica Ceca, dalla filiale di Praga dell\u2019ICBC e dalla Confederazione dell\u2019industria della Repubblica Ceca.<br \/>(ITALPRESS).<br \/> -Foto Xinhua-<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>PRAGA (REPUBBLICA CECA) (XINHUA\/ITALPRESS) \u2013 Esponenti del mondo imprenditoriale, rappresentanti del settore e funzionari governativi provenienti da Cina e Repubblica Ceca si sono riuniti 24 Mar a Praga per un evento di promozione della quarta edizione della China International Supply Chain Expo (CISCE), mettendo in evidenza il crescente interesse nel rafforzamento della cooperazione economica e [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":72723,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1129],"tags":[],"class_list":["post-72722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cina-Repubblica Ceca, incontro a Praga sulla cooperazione nella Supply-chain - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cina-Repubblica Ceca, incontro a Praga sulla cooperazione nella Supply-chain - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"PRAGA (REPUBBLICA CECA) (XINHUA\/ITALPRESS) \u2013 Esponenti del mondo imprenditoriale, rappresentanti del settore e funzionari governativi provenienti da Cina e Repubblica Ceca si sono riuniti 24 Mar a Praga per un evento di promozione della quarta edizione della China International Supply Chain Expo (CISCE), mettendo in evidenza il crescente interesse nel rafforzamento della cooperazione economica e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-26T20:03:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Cina-Repubblica Ceca, incontro a Praga sulla cooperazione nella Supply-chain\",\"datePublished\":\"2026-03-26T20:03:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\\\/\"},\"wordCount\":476,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260326_2246.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\\\/\",\"name\":\"Cina-Repubblica Ceca, incontro a Praga sulla cooperazione nella Supply-chain - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260326_2246.jpg\",\"datePublished\":\"2026-03-26T20:03:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260326_2246.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260326_2246.jpg\",\"width\":1000,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cina-Repubblica Ceca, incontro a Praga sulla cooperazione nella Supply-chain\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cina-Repubblica Ceca, incontro a Praga sulla cooperazione nella Supply-chain - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\/","og_locale":"it_IT","og_type":"article","og_title":"Cina-Repubblica Ceca, incontro a Praga sulla cooperazione nella Supply-chain - Live Magazine","og_description":"PRAGA (REPUBBLICA CECA) (XINHUA\/ITALPRESS) \u2013 Esponenti del mondo imprenditoriale, rappresentanti del settore e funzionari governativi provenienti da Cina e Repubblica Ceca si sono riuniti 24 Mar a Praga per un evento di promozione della quarta edizione della China International Supply Chain Expo (CISCE), mettendo in evidenza il crescente interesse nel rafforzamento della cooperazione economica e [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-03-26T20:03:11+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Cina-Repubblica Ceca, incontro a Praga sulla cooperazione nella Supply-chain","datePublished":"2026-03-26T20:03:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\/"},"wordCount":476,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260326_2246.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\/","name":"Cina-Repubblica Ceca, incontro a Praga sulla cooperazione nella Supply-chain - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260326_2246.jpg","datePublished":"2026-03-26T20:03:11+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260326_2246.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260326_2246.jpg","width":1000,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/cina-repubblica-ceca-incontro-a-praga-sulla-cooperazione-nella-supply-chain\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Cina-Repubblica Ceca, incontro a Praga sulla cooperazione nella Supply-chain"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260326_2246.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/72722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=72722"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/72722\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/72723"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=72722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=72722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=72722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}