{"id":72686,"date":"2026-03-26T15:03:05","date_gmt":"2026-03-26T14:03:05","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\/"},"modified":"2026-03-26T15:03:05","modified_gmt":"2026-03-26T14:03:05","slug":"webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\/","title":{"rendered":"Webuild, nuove opportunit\u00e0 dal piano di infrastrutture dell\u2019Australia"},"content":{"rendered":"<div>\n<p>MILANO (ITALPRESS) \u2013 L\u2019Australia ha definito le sue priorit\u00e0 infrastrutturali per sostenere la crescita della popolazione e dell\u2019economia, pubblicando la nuova Infrastructure Priority List che individua 68 proposte ad alta priorit\u00e0 nei settori trasporti, acqua, energia pulita e logistica. In questo scenario, Webuild emerge come uno dei protagonisti gi\u00e0 attivi nei progetti pi\u00f9 strategici del Paese, e si conferma in una posizione competitiva per cogliere le opportunit\u00e0 del prossimo decennio.<br \/>Con una pipeline infrastrutturale nazionale che ha raggiunto i 242 miliardi di dollari australiani fino al 2029, il mercato australiano continua a offrire prospettive di crescita considerevoli.<br \/>Tra le opere gi\u00e0 inserite nella lista e oggi in costruzione spiccano il Suburban Rail Loop (SRL) e il North East Link (NEL), entrambi nello Stato di Victoria. Il primo \u00e8 destinato a rivoluzionare la mobilit\u00e0 di Melbourne con una linea ferroviaria circolare il cui tratto orientale \u00e8 realizzato dalla joint venture Terra Verde guidata da Webuild. Il secondo \u00e8 il pi\u00f9 grande progetto stradale dello Stato, dove Webuild partecipa alla realizzazione dei tunnel gemelli che diventeranno i pi\u00f9 lunghi del Victoria.<br \/>L\u2019Infrastructure Priority List include anche proposte per future infrastrutture strategiche, come una linea ferroviaria ad alta velocit\u00e0 fra Brisbane, Sydney, Canberra e Melbourne. Un progetto sostenuto dal governo federale e per il quale Webuild vanta una comprovata esperienza maturata in Europa, con opere quali Napoli-Bari, il Terzo Valico dei Giovi, il Tunnel di Base del Brennero e la tratta transfrontaliera Torino-Lione.<br \/>Un altro ambito particolarmente rilevante per l\u2019Australia \u00e8 quello idrico. Essendo il continente abitato pi\u00f9 arido al mondo, il Paese necessita di infrastrutture idriche resilienti, indipendenti dal clima e capaci di rispondere alla crescita demografica. In questo settore Webuild dispone delle competenze della controllata Fisia Italimpianti, che ha gi\u00e0 realizzato impianti di livello mondiale come la desalinizzazione Jebel Ali M a Dubai e il sistema di trattamento delle acque reflue di Riachuelo a Buenos Aires. Tale know-how pu\u00f2 rappresentare una risorsa decisiva per i futuri investimenti australiani in desalinizzazione, riuso delle acque e ammodernamento degli impianti.<br \/>L\u2019Australia \u00e8 oggi il secondo mercato al mondo per Webuild, con il 12% del portafoglio ordini e il 30% dei ricavi annuali. Un risultato reso possibile da una presenza consolidata nel Paese e dalla capacit\u00e0 di affrontare progetti complessi che spaziano dalle grandi infrastrutture di trasporto alle opere idriche, fino alle strutture sociali come l\u2019ospedale Women and Babies Hospital di Perth.<\/p>\n<p>\u2013 foto ufficio stampa Webuild \u2013<br \/>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>MILANO (ITALPRESS) \u2013 L\u2019Australia ha definito le sue priorit\u00e0 infrastrutturali per sostenere la crescita della popolazione e dell\u2019economia, pubblicando la nuova Infrastructure Priority List che individua 68 proposte ad alta priorit\u00e0 nei settori trasporti, acqua, energia pulita e logistica. In questo scenario, Webuild emerge come uno dei protagonisti gi\u00e0 attivi nei progetti pi\u00f9 strategici del [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":72687,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1129],"tags":[],"class_list":["post-72686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Webuild, nuove opportunit\u00e0 dal piano di infrastrutture dell\u2019Australia - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Webuild, nuove opportunit\u00e0 dal piano di infrastrutture dell\u2019Australia - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"MILANO (ITALPRESS) \u2013 L\u2019Australia ha definito le sue priorit\u00e0 infrastrutturali per sostenere la crescita della popolazione e dell\u2019economia, pubblicando la nuova Infrastructure Priority List che individua 68 proposte ad alta priorit\u00e0 nei settori trasporti, acqua, energia pulita e logistica. In questo scenario, Webuild emerge come uno dei protagonisti gi\u00e0 attivi nei progetti pi\u00f9 strategici del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-26T14:03:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Webuild, nuove opportunit\u00e0 dal piano di infrastrutture dell\u2019Australia\",\"datePublished\":\"2026-03-26T14:03:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\\\/\"},\"wordCount\":406,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260326_1098.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\\\/\",\"name\":\"Webuild, nuove opportunit\u00e0 dal piano di infrastrutture dell\u2019Australia - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260326_1098.jpg\",\"datePublished\":\"2026-03-26T14:03:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260326_1098.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260326_1098.jpg\",\"width\":1024,\"height\":623},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Webuild, nuove opportunit\u00e0 dal piano di infrastrutture dell\u2019Australia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Webuild, nuove opportunit\u00e0 dal piano di infrastrutture dell\u2019Australia - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\/","og_locale":"it_IT","og_type":"article","og_title":"Webuild, nuove opportunit\u00e0 dal piano di infrastrutture dell\u2019Australia - Live Magazine","og_description":"MILANO (ITALPRESS) \u2013 L\u2019Australia ha definito le sue priorit\u00e0 infrastrutturali per sostenere la crescita della popolazione e dell\u2019economia, pubblicando la nuova Infrastructure Priority List che individua 68 proposte ad alta priorit\u00e0 nei settori trasporti, acqua, energia pulita e logistica. In questo scenario, Webuild emerge come uno dei protagonisti gi\u00e0 attivi nei progetti pi\u00f9 strategici del [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-03-26T14:03:05+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Webuild, nuove opportunit\u00e0 dal piano di infrastrutture dell\u2019Australia","datePublished":"2026-03-26T14:03:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\/"},"wordCount":406,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260326_1098.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\/","name":"Webuild, nuove opportunit\u00e0 dal piano di infrastrutture dell\u2019Australia - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260326_1098.jpg","datePublished":"2026-03-26T14:03:05+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260326_1098.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260326_1098.jpg","width":1024,"height":623},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/webuild-nuove-opportunita-dal-piano-di-infrastrutture-dellaustralia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Webuild, nuove opportunit\u00e0 dal piano di infrastrutture dell\u2019Australia"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260326_1098.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/72686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=72686"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/72686\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/72687"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=72686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=72686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=72686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}