{"id":72665,"date":"2026-03-26T12:03:10","date_gmt":"2026-03-26T11:03:10","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\/"},"modified":"2026-03-26T12:03:10","modified_gmt":"2026-03-26T11:03:10","slug":"f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\/","title":{"rendered":"F1 a Suzuka, Leclerc \u201cArriveranno aggiornamenti, Mercedes in vantaggio\u201d"},"content":{"rendered":"<div>\n<p>SUZUKA (GIAPPONE) (ITALPRESS) \u2013 La Formula 1 fa tappa in Giappone, terzo appuntamento del Mondiale 2026 e ultima gara prima della sosta forzata di aprile, con le cancellazioni di Bahrain e Arabia Saudita a causa del conflitto in Medio Oriente. Dopo i problemi riscontrati in qualifica nell\u2019utilizzo della batteria, la Fia si presenta a Suzuka con una piccola modifica regolamentare: per garantire una minore gestione della parte elettrica \u00e8 stato deciso di ridurre di un joule (da 9 a 8) la ricarica massima della batteria. \u201cLa modifica garantir\u00e0 il mantenimento dell\u2019equilibrio previsto tra l\u2019utilizzo dell\u2019energia e le prestazioni dei piloti, accumuleranno meno energia per caricare la batteria sui rettilinei durante le qualifiche e, di conseguenza, toglieranno meno volte il piede dall\u2019acceleratore\u201d, spiega la Fia in un comunicato. La grande favorita resta la Mercedes, reduce da due doppietta tra Australia e Cina. \u201cLa squadra ha lavorato duro per metterci in questa posizione e la squadra migliore dovrebbe vincere. Abbiamo un vantaggio e siamo partiti alla grande, ma non c\u2019\u00e8 nulla di garantito\u201d, le parole, nel corso del media day, del leader del Mondiale George Russell. Il britannico guida la classifica con 4 punti di vantaggio sul compagno di squadra Andrea Kimi Antonelli, che in Cina ha conquistato la prima vittoria della carriera in F1: \u201cCi sono tante gare da disputare, voglio mantenere lo slancio positivo di Shanghai. Ho subito spostato l\u2019attenzione su questo fine  settimana, nonostante probabilmente in Cina sia stato il giorno pi\u00f9 bello della mia vita\u201d, afferma il 19enne bolognese, diventato il pilota pi\u00f9 giovane della storia a salire sul gradino pi\u00f9 alto del podio in gara. La Ferrari si candida ad essere la prima delle \u201caltre\u201d. Un terzo e un quarto posto a Melbourne e un terzo e un quarto posto a Shanghai per la scuderia di Maranello, che prover\u00e0 ad inserirsi nel dominio Mercedes sul tortuoso tracciato di Suzuka, dove il successo per la Rossa manca dai tempi di Michael Schumacher (2004). \u201cStiamo cercando di migliorare le nostre prestazioni, ma la Mercedes \u00e8 ancora davanti. Abbiamo ancora un distacco da colmare, ma ci proveremo con tutte le nostre forze. Sono orgoglioso del team e del lavoro che abbiamo fatto per arrivare fino qui. Siamo vicini a Mercedes e potremo lottare per il titolo\u201d, le dichiarazioni di un sempre positivo Lewis Hamilton, reduce dal primo podio con il Cavallino ottenuto in Cina battendo proprio il compagno di marca Charles Leclerc. Il monegasco mantiene i piedi ben saldi a terra, consapevole del gap di Mercedes sulla concorrenza: \u201cIn questa stagione sar\u00e0 fondamentale lo sviluppo della macchina. In questo momento siamo in una buona posizione, vogliamo vincere delle gare ma la Mercedes sta ottenendo risultati di alto livello e ha un vantaggio significativo. Arriveranno presto degli aggiornamenti,  ma noi dobbiamo concentrarci su noi stessi\u201d, sottolinea il monegasco, che occupa il terzo posto in classifica piloti con 34 punti con una sola lunghezza di margine su Hamilton. La McLaren resta lontana da Ferrari e Mercedes, ma Lando Norris confida negli sviluppi della scuderia di Woking: \u201cCi sono progressi, ma ci vuole tempo. Al momento siamo la terza forza della griglia e ci sono tanti progetti in cantiere. Vogliamo salire sul podio e poi vincere le gare, possiamo arrivare ad avere la migliore macchina del campionato\u201d, rivela il campione del mondo in carica, attualmente sesto in classifica con 15 punti all\u2019attivo. In difficolt\u00e0 la Red Bull, costretta al ritiro a Melbourne con Isack Hadjar e a Shanghai con Max Verstappen. \u201cDobbiamo essere realisti e ammettere che al momento siamo lontani. Cercheremo di sfruttare la pausa di aprile per capire meglio la nostra macchina. Dobbiamo imparare dalle gare precedenti e cercare di essere pi\u00f9 vicini alla testa della corsa. Credo che questo sia il nostro obiettivo\u201d, l\u2019analisi dell\u2019olandese quattro volte campione del mondo. Domani, venerd\u00ec, prima giornata in pista con due sessioni di prove libere (3.30 e 7.00). Sabato toccher\u00e0 alle qualifiche  alle 7.00, anticipate dalle FP3 alle 3.30. Domenica alle 7.00 il semaforo verde per i 53 giri del Gp del Giappone.<br \/>\u2013 Foto Image \u2013<br \/>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SUZUKA (GIAPPONE) (ITALPRESS) \u2013 La Formula 1 fa tappa in Giappone, terzo appuntamento del Mondiale 2026 e ultima gara prima della sosta forzata di aprile, con le cancellazioni di Bahrain e Arabia Saudita a causa del conflitto in Medio Oriente. Dopo i problemi riscontrati in qualifica nell\u2019utilizzo della batteria, la Fia si presenta a Suzuka [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":72666,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1129],"tags":[],"class_list":["post-72665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>F1 a Suzuka, Leclerc \u201cArriveranno aggiornamenti, Mercedes in vantaggio\u201d - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F1 a Suzuka, Leclerc \u201cArriveranno aggiornamenti, Mercedes in vantaggio\u201d - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"SUZUKA (GIAPPONE) (ITALPRESS) \u2013 La Formula 1 fa tappa in Giappone, terzo appuntamento del Mondiale 2026 e ultima gara prima della sosta forzata di aprile, con le cancellazioni di Bahrain e Arabia Saudita a causa del conflitto in Medio Oriente. Dopo i problemi riscontrati in qualifica nell\u2019utilizzo della batteria, la Fia si presenta a Suzuka [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-26T11:03:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"F1 a Suzuka, Leclerc \u201cArriveranno aggiornamenti, Mercedes in vantaggio\u201d\",\"datePublished\":\"2026-03-26T11:03:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\\\/\"},\"wordCount\":674,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260326_0180.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\\\/\",\"name\":\"F1 a Suzuka, Leclerc \u201cArriveranno aggiornamenti, Mercedes in vantaggio\u201d - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260326_0180.jpg\",\"datePublished\":\"2026-03-26T11:03:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260326_0180.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260326_0180.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F1 a Suzuka, Leclerc \u201cArriveranno aggiornamenti, Mercedes in vantaggio\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F1 a Suzuka, Leclerc \u201cArriveranno aggiornamenti, Mercedes in vantaggio\u201d - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\/","og_locale":"it_IT","og_type":"article","og_title":"F1 a Suzuka, Leclerc \u201cArriveranno aggiornamenti, Mercedes in vantaggio\u201d - Live Magazine","og_description":"SUZUKA (GIAPPONE) (ITALPRESS) \u2013 La Formula 1 fa tappa in Giappone, terzo appuntamento del Mondiale 2026 e ultima gara prima della sosta forzata di aprile, con le cancellazioni di Bahrain e Arabia Saudita a causa del conflitto in Medio Oriente. Dopo i problemi riscontrati in qualifica nell\u2019utilizzo della batteria, la Fia si presenta a Suzuka [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-03-26T11:03:10+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"F1 a Suzuka, Leclerc \u201cArriveranno aggiornamenti, Mercedes in vantaggio\u201d","datePublished":"2026-03-26T11:03:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\/"},"wordCount":674,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260326_0180.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\/","name":"F1 a Suzuka, Leclerc \u201cArriveranno aggiornamenti, Mercedes in vantaggio\u201d - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260326_0180.jpg","datePublished":"2026-03-26T11:03:10+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260326_0180.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260326_0180.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/f1-a-suzuka-leclerc-arriveranno-aggiornamenti-mercedes-in-vantaggio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"F1 a Suzuka, Leclerc \u201cArriveranno aggiornamenti, Mercedes in vantaggio\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260326_0180.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/72665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=72665"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/72665\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/72666"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=72665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=72665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=72665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}