{"id":72647,"date":"2026-03-26T10:41:44","date_gmt":"2026-03-26T09:41:44","guid":{"rendered":"https:\/\/www.livemag.it\/?p=72647"},"modified":"2026-03-26T10:42:24","modified_gmt":"2026-03-26T09:42:24","slug":"alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\/","title":{"rendered":"Alessandro Cucinotta dice la sua sulla terza puntata di GF Vip"},"content":{"rendered":"\n<p><strong><br><br>GRANDE FRATELLO VIP \u2013 LE 3 COSE CHE ABBIAMO CAPITO IERI SERA<\/strong><\/p>\n\n\n\n<p>La terza puntata del\u00a0Grande Fratello VIP\u00a0ci ha lasciato tre certezze. Tre. E non tutte rassicuranti. Al Grande Fratello\u2026 chi urla di pi\u00f9 non ha sempre ragione.<\/p>\n\n\n\n<p>Lo scontro ormai \u00e8 diventato linguaggio. Alzi la voce, entri nel dibattito, fai clip\u2026 e diventi protagonista. Il problema? Che il pubblico oggi ti guarda\u2026 ma domani ti giudica e spesso chi fa pi\u00f9 rumore\u2026 \u00e8 il primo che paga il conto.<\/p>\n\n\n\n<p>Tutti giocano. Anche chi dice di non farlo. C\u2019\u00e8 chi gioca di strategia, chi finge di no, e chi va di strategia dicendo che non sopporta chi lo fa.<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"478\" style=\"aspect-ratio: 848 \/ 478;\" width=\"848\" controls src=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Video-2026-03-25-at-19.01.03.mp4\"><\/video><\/figure>\n\n\n\n<p>Un capolavoro. Ma la verit\u00e0 \u00e8 semplice: oggi al Grande Fratello non vince il pi\u00f9 forte bens\u00ec vince chi costruisce meglio il proprio racconto. L\u2019amore\u2026 funziona sempre. Ma non basta pi\u00f9. E qui arriviamo alla storia tra\u00a0Antonella Elia\u00a0e Pietro. Perch\u00e9 diciamolo: le dinamiche sentimentali in un reality sono benzina pura.<\/p>\n\n\n\n<p>Il pubblico si affeziona, si divide, commenta. Ma oggi non basta pi\u00f9 dire \u2018c\u2019\u00e8 una storia\u2019.<br>Il pubblico vuole capire se \u00e8 vera, se evolve\u2026 o se \u00e8 solo una parentesi televisiva. Perch\u00e9 l\u2019amore in TV funziona\u2026ma solo se \u00e8 credibile. E allora la vera domanda \u00e8 una:\u00a0stiamo guardando persone\u2026o personaggi? Perch\u00e9 la differenza, prima o poi\u2026 si vede.<\/p>\n\n\n\n<p>E al Grande Fratello, ricordatevelo: non vince chi si espone di pi\u00f9\u2026 vince chi resta.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>GRANDE FRATELLO VIP \u2013 LE 3 COSE CHE ABBIAMO CAPITO IERI SERA La terza puntata del\u00a0Grande Fratello VIP\u00a0ci ha lasciato tre certezze. Tre. E non tutte rassicuranti. Al Grande Fratello\u2026 chi urla di pi\u00f9 non ha sempre ragione. Lo scontro ormai \u00e8 diventato linguaggio. Alzi la voce, entri nel dibattito, fai clip\u2026 e diventi protagonista. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31922,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[3,83],"tags":[4091,1753,7487],"class_list":["post-72647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-livenews","category-livevip","tag-alessandro-cucinotta","tag-antonella-elia","tag-ilary-blasi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alessandro Cucinotta dice la sua sulla terza puntata di GF Vip - Live Magazine<\/title>\n<meta name=\"description\" content=\"La terza puntata del\u00a0Grande Fratello VIP\u00a0ci ha lasciato tre certezze. Tre. E non tutte rassicuranti. Al Grande Fratello\u2026 chi urla di p\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alessandro Cucinotta dice la sua sulla terza puntata di GF Vip - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"La terza puntata del\u00a0Grande Fratello VIP\u00a0ci ha lasciato tre certezze. Tre. E non tutte rassicuranti. Al Grande Fratello\u2026 chi urla di p\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-26T09:41:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-26T09:42:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/Alessandro-Cucinotta-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/7191e402a6eb1110174f9d71f53edea9\"},\"headline\":\"Alessandro Cucinotta dice la sua sulla terza puntata di GF Vip\",\"datePublished\":\"2026-03-26T09:41:44+00:00\",\"dateModified\":\"2026-03-26T09:42:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\\\/\"},\"wordCount\":244,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Alessandro-Cucinotta-.jpg\",\"keywords\":[\"Alessandro Cucinotta\",\"Antonella Elia\",\"Ilary Blasi\"],\"articleSection\":[\"LiveNews\",\"LiveVIP\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\\\/\",\"name\":\"Alessandro Cucinotta dice la sua sulla terza puntata di GF Vip - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Alessandro-Cucinotta-.jpg\",\"datePublished\":\"2026-03-26T09:41:44+00:00\",\"dateModified\":\"2026-03-26T09:42:24+00:00\",\"description\":\"La terza puntata del\u00a0Grande Fratello VIP\u00a0ci ha lasciato tre certezze. Tre. E non tutte rassicuranti. Al Grande Fratello\u2026 chi urla di p\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Alessandro-Cucinotta-.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Alessandro-Cucinotta-.jpg\",\"width\":1200,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/26\\\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alessandro Cucinotta dice la sua sulla terza puntata di GF Vip\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/7191e402a6eb1110174f9d71f53edea9\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b20eb33510695f1259c3f61c8dfc966b174a5d33f605fb2d514d9b271222597e?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b20eb33510695f1259c3f61c8dfc966b174a5d33f605fb2d514d9b271222597e?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b20eb33510695f1259c3f61c8dfc966b174a5d33f605fb2d514d9b271222597e?s=96&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/admin6640\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alessandro Cucinotta dice la sua sulla terza puntata di GF Vip - Live Magazine","description":"La terza puntata del\u00a0Grande Fratello VIP\u00a0ci ha lasciato tre certezze. Tre. E non tutte rassicuranti. Al Grande Fratello\u2026 chi urla di p","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\/","og_locale":"it_IT","og_type":"article","og_title":"Alessandro Cucinotta dice la sua sulla terza puntata di GF Vip - Live Magazine","og_description":"La terza puntata del\u00a0Grande Fratello VIP\u00a0ci ha lasciato tre certezze. Tre. E non tutte rassicuranti. Al Grande Fratello\u2026 chi urla di p","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-03-26T09:41:44+00:00","article_modified_time":"2026-03-26T09:42:24+00:00","og_image":[{"width":1200,"height":750,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/Alessandro-Cucinotta-.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\/"},"author":{"name":"Redazione","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/7191e402a6eb1110174f9d71f53edea9"},"headline":"Alessandro Cucinotta dice la sua sulla terza puntata di GF Vip","datePublished":"2026-03-26T09:41:44+00:00","dateModified":"2026-03-26T09:42:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\/"},"wordCount":244,"commentCount":0,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/Alessandro-Cucinotta-.jpg","keywords":["Alessandro Cucinotta","Antonella Elia","Ilary Blasi"],"articleSection":["LiveNews","LiveVIP"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\/","name":"Alessandro Cucinotta dice la sua sulla terza puntata di GF Vip - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/Alessandro-Cucinotta-.jpg","datePublished":"2026-03-26T09:41:44+00:00","dateModified":"2026-03-26T09:42:24+00:00","description":"La terza puntata del\u00a0Grande Fratello VIP\u00a0ci ha lasciato tre certezze. Tre. E non tutte rassicuranti. Al Grande Fratello\u2026 chi urla di p","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/Alessandro-Cucinotta-.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/Alessandro-Cucinotta-.jpg","width":1200,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/26\/alessandro-cucinotta-dice-la-sua-sulla-terza-puntata-di-gf-vip\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Alessandro Cucinotta dice la sua sulla terza puntata di GF Vip"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/7191e402a6eb1110174f9d71f53edea9","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b20eb33510695f1259c3f61c8dfc966b174a5d33f605fb2d514d9b271222597e?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b20eb33510695f1259c3f61c8dfc966b174a5d33f605fb2d514d9b271222597e?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b20eb33510695f1259c3f61c8dfc966b174a5d33f605fb2d514d9b271222597e?s=96&r=g","caption":"Redazione"},"url":"https:\/\/www.livemag.it\/index.php\/author\/admin6640\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/Alessandro-Cucinotta-.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/72647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=72647"}],"version-history":[{"count":1,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/72647\/revisions"}],"predecessor-version":[{"id":72649,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/72647\/revisions\/72649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/31922"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=72647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=72647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=72647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}