{"id":72625,"date":"2026-03-25T21:03:21","date_gmt":"2026-03-25T20:03:21","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/03\/25\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\/"},"modified":"2026-03-25T21:03:21","modified_gmt":"2026-03-25T20:03:21","slug":"medio-oriente-meloni-litalia-lavora-per-la-stabilita","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/03\/25\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\/","title":{"rendered":"Medio Oriente, Meloni \u201cL\u2019Italia lavora per la stabilit\u00e0\u201d"},"content":{"rendered":"<div>\n<p>ALGERI (ALGERIA) (ITALPRESS) \u2013 \u201cSono moltissimi gli ambiti della nostra cooperazione. Sicuramente c\u2019\u00e8 l\u2019ambito energetico. Con il presidente Tebboune abbiamo deciso di rafforzare la nostra solidissima collaborazione, che coinvolge anche i nostri due campioni nazionali, Eni e Sonatrach, anche lavorando su nuovi fronti come lo shale gas e l\u2019esplorazione offshore. Questo consentir\u00e0 anche in prospettiva di rafforzare il flusso di fornitura di gas dall\u2019Algeria all\u2019Italia\u201d. Lo ha detto il presidente del Consiglio, Giorgia Meloni, nel corso delle dichiarazioni congiunte alla stampa ad Algeri con il presidente della Repubblica di Algeria, Abdelmadjid Tebboune.<br \/>\u201cLa nostra cooperazione non si esaurisce a questo aspetto, ne sta esplorando da tempo molti \u2013 ha aggiunto -. Mi riferisco al tema dello sviluppo delle energie rinnovabili, alla realizzazione di infrastrutture strategiche che sono sempre pi\u00f9 capaci di unire le due sponde del Mediterraneo, aumentando l\u2019interconnessione e quindi anche la sicurezza energetica, con il TransMed, il famoso gasdotto Mattei che dagli anni 80 collega Italia e Algeria siamo stati dei pionieri, l\u2019idea \u00e8 che lo si possa essere ancora\u201d.<br \/>\u201cAbbiamo parlato anche, ovviamente, dei molti dossier internazionali che sono sul tavolo, a partire dalla crisi in Medi Oriente. Una crisi che coinvolge tutti, e che se dovesse prolungarsi nel tempo potrebbe causare chiaramente conseguenze economiche e sociali che finirebbero per colpire, pi\u00f9 di altre, le nazioni pi\u00f9 vulnerabili, a partire proprio dal continente africano \u2013 ha sottolineato il premier -. Chiaramente credo che l\u2019ipotesi di colloquio in corso tra Stati Uniti e Iran costituirebbe un\u2019ottima notizia. L\u2019Italia sosterr\u00e0 e intende sostenere anche grazie alla solida rete di relazioni che ha con le nazioni del Golfo ogni iniziativa che possa riportare stabilit\u00e0 nell\u2019area\u201d.<br \/>\u201cAbbiamo condiviso la preoccupazione per l\u2019escalation militare in Libano, che deve dal nostro punto di vista cessare immediatamente, per una situazione a Gaza che rimane estremamente difficile per la popolazione civile, soprattutto sotto il profilo umanitario, e sul lavoro complesso che la comunit\u00e0 internazionale deve continuare a fare per stabilizzare la regione e per arrivare alla soluzione dei due Stati\u201d, ha proseguito Meloni.<\/p>\n<p>\u2013 Foto IPA Agency \u2013<\/p>\n<p>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ALGERI (ALGERIA) (ITALPRESS) \u2013 \u201cSono moltissimi gli ambiti della nostra cooperazione. Sicuramente c\u2019\u00e8 l\u2019ambito energetico. Con il presidente Tebboune abbiamo deciso di rafforzare la nostra solidissima collaborazione, che coinvolge anche i nostri due campioni nazionali, Eni e Sonatrach, anche lavorando su nuovi fronti come lo shale gas e l\u2019esplorazione offshore. Questo consentir\u00e0 anche in prospettiva [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":72626,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1129],"tags":[],"class_list":["post-72625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Medio Oriente, Meloni \u201cL\u2019Italia lavora per la stabilit\u00e0\u201d - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/03\/25\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medio Oriente, Meloni \u201cL\u2019Italia lavora per la stabilit\u00e0\u201d - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"ALGERI (ALGERIA) (ITALPRESS) \u2013 \u201cSono moltissimi gli ambiti della nostra cooperazione. Sicuramente c\u2019\u00e8 l\u2019ambito energetico. Con il presidente Tebboune abbiamo deciso di rafforzare la nostra solidissima collaborazione, che coinvolge anche i nostri due campioni nazionali, Eni e Sonatrach, anche lavorando su nuovi fronti come lo shale gas e l\u2019esplorazione offshore. Questo consentir\u00e0 anche in prospettiva [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/03\/25\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-25T20:03:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/25\\\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/25\\\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Medio Oriente, Meloni \u201cL\u2019Italia lavora per la stabilit\u00e0\u201d\",\"datePublished\":\"2026-03-25T20:03:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/25\\\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\\\/\"},\"wordCount\":357,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/25\\\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260325_2999.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/25\\\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/25\\\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\\\/\",\"name\":\"Medio Oriente, Meloni \u201cL\u2019Italia lavora per la stabilit\u00e0\u201d - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/25\\\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/25\\\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260325_2999.jpg\",\"datePublished\":\"2026-03-25T20:03:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/25\\\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/25\\\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/25\\\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260325_2999.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260325_2999.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/25\\\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medio Oriente, Meloni \u201cL\u2019Italia lavora per la stabilit\u00e0\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Medio Oriente, Meloni \u201cL\u2019Italia lavora per la stabilit\u00e0\u201d - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/03\/25\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\/","og_locale":"it_IT","og_type":"article","og_title":"Medio Oriente, Meloni \u201cL\u2019Italia lavora per la stabilit\u00e0\u201d - Live Magazine","og_description":"ALGERI (ALGERIA) (ITALPRESS) \u2013 \u201cSono moltissimi gli ambiti della nostra cooperazione. Sicuramente c\u2019\u00e8 l\u2019ambito energetico. Con il presidente Tebboune abbiamo deciso di rafforzare la nostra solidissima collaborazione, che coinvolge anche i nostri due campioni nazionali, Eni e Sonatrach, anche lavorando su nuovi fronti come lo shale gas e l\u2019esplorazione offshore. Questo consentir\u00e0 anche in prospettiva [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/03\/25\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-03-25T20:03:21+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/25\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/25\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Medio Oriente, Meloni \u201cL\u2019Italia lavora per la stabilit\u00e0\u201d","datePublished":"2026-03-25T20:03:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/25\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\/"},"wordCount":357,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/25\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260325_2999.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/25\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/03\/25\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\/","name":"Medio Oriente, Meloni \u201cL\u2019Italia lavora per la stabilit\u00e0\u201d - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/25\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/25\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260325_2999.jpg","datePublished":"2026-03-25T20:03:21+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/25\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/03\/25\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/25\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260325_2999.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260325_2999.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/25\/medio-oriente-meloni-litalia-lavora-per-la-stabilita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Medio Oriente, Meloni \u201cL\u2019Italia lavora per la stabilit\u00e0\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260325_2999.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/72625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=72625"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/72625\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/72626"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=72625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=72625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=72625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}