{"id":72527,"date":"2026-03-24T21:03:22","date_gmt":"2026-03-24T20:03:22","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/03\/24\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\/"},"modified":"2026-03-24T21:03:22","modified_gmt":"2026-03-24T20:03:22","slug":"meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/03\/24\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\/","title":{"rendered":"Meloni \u201cAuspico che Santanch\u00e8 condivida stessa scelta di Delmastro e Bartolozzi\u201d"},"content":{"rendered":"<div>\n<p>ROMA (ITALPRESS) \u2013 Il presidente del Consiglio dei Ministri, Giorgia Meloni, esprime \u201capprezzamento per la scelta del sottosegretario alla Giustizia Andrea Delmastro e del capo di Gabinetto Giusi Bartolozzi di rimettere gli incarichi finora ricoperti e li ringrazia per il lavoro svolto con dedizione.<br \/>Auspica che, sulla medesima linea di sensibilit\u00e0 istituzionale, analoga scelta sia condivisa dal ministro del Turismo Daniela Santanch\u00e8\u201d. Lo rende noto Palazzo Chigi.<\/p>\n<p>\u2013 Foto IPA Agency \u2013<\/p>\n<p>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) \u2013 Il presidente del Consiglio dei Ministri, Giorgia Meloni, esprime \u201capprezzamento per la scelta del sottosegretario alla Giustizia Andrea Delmastro e del capo di Gabinetto Giusi Bartolozzi di rimettere gli incarichi finora ricoperti e li ringrazia per il lavoro svolto con dedizione.Auspica che, sulla medesima linea di sensibilit\u00e0 istituzionale, analoga scelta sia condivisa [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":72528,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1129],"tags":[],"class_list":["post-72527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Meloni \u201cAuspico che Santanch\u00e8 condivida stessa scelta di Delmastro e Bartolozzi\u201d - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/03\/24\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meloni \u201cAuspico che Santanch\u00e8 condivida stessa scelta di Delmastro e Bartolozzi\u201d - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"ROMA (ITALPRESS) \u2013 Il presidente del Consiglio dei Ministri, Giorgia Meloni, esprime \u201capprezzamento per la scelta del sottosegretario alla Giustizia Andrea Delmastro e del capo di Gabinetto Giusi Bartolozzi di rimettere gli incarichi finora ricoperti e li ringrazia per il lavoro svolto con dedizione.Auspica che, sulla medesima linea di sensibilit\u00e0 istituzionale, analoga scelta sia condivisa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/03\/24\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-24T20:03:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/24\\\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/24\\\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Meloni \u201cAuspico che Santanch\u00e8 condivida stessa scelta di Delmastro e Bartolozzi\u201d\",\"datePublished\":\"2026-03-24T20:03:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/24\\\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\\\/\"},\"wordCount\":81,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/24\\\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260324_2025.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/24\\\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/24\\\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\\\/\",\"name\":\"Meloni \u201cAuspico che Santanch\u00e8 condivida stessa scelta di Delmastro e Bartolozzi\u201d - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/24\\\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/24\\\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260324_2025.jpg\",\"datePublished\":\"2026-03-24T20:03:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/24\\\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/24\\\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/24\\\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260324_2025.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260324_2025.jpg\",\"width\":1200,\"height\":799},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/03\\\/24\\\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Meloni \u201cAuspico che Santanch\u00e8 condivida stessa scelta di Delmastro e Bartolozzi\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Meloni \u201cAuspico che Santanch\u00e8 condivida stessa scelta di Delmastro e Bartolozzi\u201d - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/03\/24\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\/","og_locale":"it_IT","og_type":"article","og_title":"Meloni \u201cAuspico che Santanch\u00e8 condivida stessa scelta di Delmastro e Bartolozzi\u201d - Live Magazine","og_description":"ROMA (ITALPRESS) \u2013 Il presidente del Consiglio dei Ministri, Giorgia Meloni, esprime \u201capprezzamento per la scelta del sottosegretario alla Giustizia Andrea Delmastro e del capo di Gabinetto Giusi Bartolozzi di rimettere gli incarichi finora ricoperti e li ringrazia per il lavoro svolto con dedizione.Auspica che, sulla medesima linea di sensibilit\u00e0 istituzionale, analoga scelta sia condivisa [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/03\/24\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-03-24T20:03:22+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/24\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/24\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Meloni \u201cAuspico che Santanch\u00e8 condivida stessa scelta di Delmastro e Bartolozzi\u201d","datePublished":"2026-03-24T20:03:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/24\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\/"},"wordCount":81,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/24\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260324_2025.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/24\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/03\/24\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\/","name":"Meloni \u201cAuspico che Santanch\u00e8 condivida stessa scelta di Delmastro e Bartolozzi\u201d - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/24\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/24\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260324_2025.jpg","datePublished":"2026-03-24T20:03:22+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/24\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/03\/24\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/24\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260324_2025.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260324_2025.jpg","width":1200,"height":799},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/03\/24\/meloni-auspico-che-santanche-condivida-stessa-scelta-di-delmastro-e-bartolozzi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Meloni \u201cAuspico che Santanch\u00e8 condivida stessa scelta di Delmastro e Bartolozzi\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/03\/20260324_2025.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/72527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=72527"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/72527\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/72528"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=72527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=72527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=72527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}