{"id":70536,"date":"2026-02-28T18:03:08","date_gmt":"2026-02-28T17:03:08","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\/"},"modified":"2026-02-28T18:03:08","modified_gmt":"2026-02-28T17:03:08","slug":"allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\/","title":{"rendered":"Allegri \u201cMilan, adesso si decide tutto. Futuro? Con la societ\u00e0 c\u2019\u00e8 sintonia\u201d"},"content":{"rendered":"<div>\n<p>MILANO (ITALPRESS) \u2013 <strong><em>\u201cOra si decide la stagione, gli ultimi due mesi e mezzo\u201d.<\/em> <\/strong>Alla vigilia della sfida contro la Cremonese, in programma domani alle 12.30 allo stadio Giovanni Zini, il tecnico del Milan <strong>Massimiliano Allegri<\/strong> ha fatto il punto sulla situazione della squadra in conferenza stampa, sottolineando come occorra subito ripartire dopo il ko col Parma. <em>\u201cDopo mesi che non perdevamo, un p\u00f2 tutti abbiamo preso il contraccolpo. Comunque bisogna ritornare a correre. Affrontiamo una squadra che ha ottime qualit\u00e0. Nelle ultime tre partite a Cremona il Milan non ha segnato. Sar\u00e0 una partita complicata ma dobbiamo tornare alla vittoria. Gabbia ha ancora l\u2019infiammazione, a Loftus hanno rimesso i denti, Gimenez da questa settimana potrebbe iniziare a riallenarsi con la squadra\u201d.<\/em><\/p>\n<p>Il tecnico rossonero ha poi ribadito come l\u2019impegno quotidiano del gruppo sia orientato al raggiungimento degli obiettivi stagionali. <em>\u201c<strong>La squadra ogni giorno viene a Milanello e lavora per vincere.<\/strong> I punti che abbiamo sono quelli che ci meritiamo. Dobbiamo pensare partita dopo partita ed a fine maggio vedremo dove saremo\u201d.<\/em> Allegri ha quindi approfondito il tema delle scelte offensive, lasciando aperti diversi scenari per l\u2019attacco rossonero. <em>\u201cTutti e 4 gli attaccanti che ho stanno tutti bene. Domani non so chi far giocare\u201d.<\/em> Poi per quanto riguarda il Var a chiamata: <em>\u201cSono arrivate delle nuove regole, significa che vogliono migliorare. Sulla chiamata ci sono pro e contro, \u00e8 una cosa che va studiata e provata\u201d.<\/em><\/p>\n<p>L\u2019allenatore del Milan ha parlato ancora dell\u2019episodio accaduto nella sfida contro il Parma: <em><strong>\u201cL\u2019indicazione mia \u00e8 che comunque bisogna noi squadra pensare a quello che dobbiamo fare. Un episodio non pu\u00f2 condizionare la partita.<\/strong> Non dobbiamo avere l\u2019alibi del gol, del rigore, del fallo e non fallo, altrimenti andiamo in una direzione sbagliata. Bisogna essere bravi a gestire l\u2019imprevisto\u201d.<\/em> Spazio anche alle domande sul suo futuro sulla panchina rossonera, tema su cui Allegri ha voluto ribadire l\u2019allineamento con il club. <em>\u201cCon la societ\u00e0 c\u2019\u00e8 totale sintonia. Poi com\u2019\u00e8 normale che sia in un confronto, ci possono essere punti di vista diversi. E\u2019 importante che tutti si lavori per il bene del Milan, sono molto contento di essere tornato al Milan dopo 15 anni e aver iniziato un lavoro con un gruppo di ragazzi splendidi. La societ\u00e0 sta programmando e strutturando il futuro del Milan. Per fare questo bisogna ottenere il risultato pi\u00f9 importante. A marzo per ora stiamo abbastanza bene. Ora dobbiamo vedere se siamo bravi a rimanere l\u00ec o a fare l\u2019ultimo scalino. C\u2019\u00e8 sintonia tra me e la societ\u00e0\u201d. <\/em><\/p>\n<p>Infine, uno sguardo pi\u00f9 ampio alla corsa in campionato e al quadro europeo, con un riferimento alle italiane:<em><strong> \u201cJuve e Inter fuori da Champions adesso forzano in campionato? Questo lo dir\u00e0 solo la classifica.<\/strong> Innanzitutto \u00e8 un dispiacere che le italiane siano uscite dalla Champions. Speriamo che Atalanta, Bologna, Roma e Fiorentina vadano pi\u00f9 avanti possibile visto che ci danno la possibilit\u00e0 del quinto posto in Champions. Finch\u00e8 le squadre italiane vanno avanti \u00e8 un bene per il calcio italiano. Ora inizia un campionato da 12 partite con questa classifica. Abbiamo punti di vantaggio sulle inseguitrici\u2026 Il mantenimento non esiste quindi dobbiamo incrementarli. Il campionato lo vince sempre la migliore dell\u2019annata. In questo momento l\u2019Inter \u00e8 la migliore, ha dieci punti di vantaggio. Credo che per un club come il Milan sia molto importante giocare la Champions: arrivare a marzo dentro le competizioni \u00e8 un risultato molto importante. Quello \u00e8 il primo obiettivo che deve avere una grande squadra. Noi dobbiamo lavorare per far s\u00ec che l\u2019anno prossimo a marzo siamo in questa situazione, ma non solo in campionato\u201d.<\/em><\/p>\n<p>\u2013 Foto: Ipa Agency \u2013<br \/>\n(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>MILANO (ITALPRESS) \u2013 \u201cOra si decide la stagione, gli ultimi due mesi e mezzo\u201d. Alla vigilia della sfida contro la Cremonese, in programma domani alle 12.30 allo stadio Giovanni Zini, il tecnico del Milan Massimiliano Allegri ha fatto il punto sulla situazione della squadra in conferenza stampa, sottolineando come occorra subito ripartire dopo il ko [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":70537,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-70536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Allegri \u201cMilan, adesso si decide tutto. Futuro? Con la societ\u00e0 c\u2019\u00e8 sintonia\u201d - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Allegri \u201cMilan, adesso si decide tutto. Futuro? Con la societ\u00e0 c\u2019\u00e8 sintonia\u201d - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"MILANO (ITALPRESS) \u2013 \u201cOra si decide la stagione, gli ultimi due mesi e mezzo\u201d. Alla vigilia della sfida contro la Cremonese, in programma domani alle 12.30 allo stadio Giovanni Zini, il tecnico del Milan Massimiliano Allegri ha fatto il punto sulla situazione della squadra in conferenza stampa, sottolineando come occorra subito ripartire dopo il ko [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-28T17:03:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Allegri \u201cMilan, adesso si decide tutto. Futuro? Con la societ\u00e0 c\u2019\u00e8 sintonia\u201d\",\"datePublished\":\"2026-02-28T17:03:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\\\/\"},\"wordCount\":613,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260228_1598.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\\\/\",\"name\":\"Allegri \u201cMilan, adesso si decide tutto. Futuro? Con la societ\u00e0 c\u2019\u00e8 sintonia\u201d - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260228_1598.jpg\",\"datePublished\":\"2026-02-28T17:03:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260228_1598.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260228_1598.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Allegri \u201cMilan, adesso si decide tutto. Futuro? Con la societ\u00e0 c\u2019\u00e8 sintonia\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Allegri \u201cMilan, adesso si decide tutto. Futuro? Con la societ\u00e0 c\u2019\u00e8 sintonia\u201d - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\/","og_locale":"it_IT","og_type":"article","og_title":"Allegri \u201cMilan, adesso si decide tutto. Futuro? Con la societ\u00e0 c\u2019\u00e8 sintonia\u201d - Live Magazine","og_description":"MILANO (ITALPRESS) \u2013 \u201cOra si decide la stagione, gli ultimi due mesi e mezzo\u201d. Alla vigilia della sfida contro la Cremonese, in programma domani alle 12.30 allo stadio Giovanni Zini, il tecnico del Milan Massimiliano Allegri ha fatto il punto sulla situazione della squadra in conferenza stampa, sottolineando come occorra subito ripartire dopo il ko [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-02-28T17:03:08+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Allegri \u201cMilan, adesso si decide tutto. Futuro? Con la societ\u00e0 c\u2019\u00e8 sintonia\u201d","datePublished":"2026-02-28T17:03:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\/"},"wordCount":613,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260228_1598.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\/","name":"Allegri \u201cMilan, adesso si decide tutto. Futuro? Con la societ\u00e0 c\u2019\u00e8 sintonia\u201d - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260228_1598.jpg","datePublished":"2026-02-28T17:03:08+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260228_1598.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260228_1598.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/allegri-milan-adesso-si-decide-tutto-futuro-con-la-societa-ce-sintonia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Allegri \u201cMilan, adesso si decide tutto. Futuro? Con la societ\u00e0 c\u2019\u00e8 sintonia\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260228_1598.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/70536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=70536"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/70536\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/70537"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=70536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=70536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=70536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}