{"id":70481,"date":"2026-02-28T03:02:45","date_gmt":"2026-02-28T02:02:45","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\/"},"modified":"2026-02-28T03:02:45","modified_gmt":"2026-02-28T02:02:45","slug":"sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\/","title":{"rendered":"Sanremo, Ditonellapiaga con TonyPitony vince serata cover. Morandi a sorpresa sul palco per duettare con il figlio. Premio alla carriera a Caterina Caselli"},"content":{"rendered":"<div>\n<p>SANREMO (ITALPRESS) \u2013 Ditonellapiaga e TonyPitony con \u201cThe Lady is a Tramp\u201d vincono la serata delle cover del Festival di Sanremo. Al secondo posto Sayf con Alex Britti e Mario Biondi con \u201cHit the Road Jack\u201d, terza Arisa con il Coro del Teatro Regio di Parma con \u201cQuello che le donne non dicono\u201d.<br \/>\nLaura Pausini d\u00e0 il via alla quarta serata, quella delle cover, la pi\u00f9 attesa da qualche anno a questa parte, dal carpet. Fasciata di nero con guanti fucsia e occhiali a mosca, il suo medley tratto dal suo ultimo album \u201cIo Canto 2\u201d, partito con \u201cRitorno ad amare\u201d continua in platea con \u201cImmensamente\u201d e \u201cIo canto\u201d mentre gli sbandieratori mostrano la scritta \u201cMake music not war\u201d. \u201cCantare \u00e8 la cosa che mi fa sentire pi\u00f9 libera. Ognuno di noi ha il diritto di essere ascoltato, libero, rispettato\u201d, dice Pausini prima di ricevere l\u2019applauso dell\u2019Ariston.<br \/>\nSul palco con lei anche il marito Paolo Carta, chitarrista della sua band. In una serata con poco spazio per il \u201ccote\u201d, a co-condurre \u00e8 Bianca Balti, di ritorno all\u2019Ariston: \u201cE\u2019 passato un anno ma sembra un giorno. E si vede dai miei capelli!\u201d, dice la modella che un anno fa, per gli effetti della cura contro il tumore che l\u2019ha colpita, si mostr\u00f2 calva. \u201cDa 21 anni faccio la modella ma la malattia \u00e8 una cosa che vivono in tantissimi. Questo palco mi ha dato l\u2019opportunit\u00e0 di lanciare un messaggio, \u00e8 stato un impatto grandissimo e sono qui per godermela non solo per me ma per tutti coloro che hanno sofferto e soffrono\u201d, ha aggiunto.<br \/>\nDalla scala dell\u2019Ariston \u00e8 sceso anche Alessandro Siani, fino alle 20,30 il \u201cMister X\u201d della serata.<br \/>\nSiani costruisce un duetto con Carlo Conti sul gioco di parole \u00abSanremo \u00e8 Sanremo\u00bb, snocciolando una serie di motivi che rendono il Festival unico. \u00abQui una canzone dura tre minuti ma pu\u00f2 restare per una vita\u00bb, dice, contrapponendola alle serate che \u00abdurano tre ore ma possono sembrare una vita\u00bb. Non mancano i riferimenti alla memoria recente: \u00abMarco se n\u2019\u00e8 andato e non ritorna pi\u00f9\u2026 No, quello \u00e8 Bugo\u00bb, scherza, ricordando anche che \u00abMorgan \u00e8 tornato, poi se n\u2019\u00e8 andato, poi \u00e8 ritornato\u00bb. E ancora: \u00abNon dici Sanremo citt\u00e0, dici Sanremo. Puoi dire ho fatto Sanremo, ho vinto Sanremo\u00bb. Fino alla chiusura: \u00abNon \u00e8 una citt\u00e0, \u00e8 una condizione permanente\u00bb. Dopo Fausto Leali e Mogol, il premio alla carriera viene consegnato a Caterina Caselli, protagonista della musica italiana da oltre sessant\u2019anni, prima come interprete e poi come produttrice e talent scout. Visibilmente emozionata, l\u2019ex \u201cCaschetto d\u2019oro\u201d ha ripercorso l\u2019inizio della sua storia artistica, ricordando il Festival del 1966 con \u201cNessuno mi pu\u00f2 giudicare\u201d. \u201cSono arrivata a Sanremo con quella canzone, che ancora oggi contiene un messaggio importante\u201d, ha detto lasciando il palco con un auspicio: \u201cA tutte le generazioni, a tutti i ragazzi e a tutte le ragazze: sentitevi liberi dal giudizio\u201d. Sul fronte gara si parte con Elettra Lamborghini che trasforma l\u2019Ariston in una discoteca degli Anni 2000 con \u201cAserej\u00e8\u201d scatenando la platea con le Las Ketchup. \u201cArriba Espa\u00f1a\u201d \u00e8 il grido con cui la cantante lascia il palco tra gli applausi. Eddie Brock ospita Fabrizio Moro per riportare all\u2019Ariston \u201cPortami via\u201d, brano con cui Moro partecip\u00f2 a Sanremo nel 2017.<br \/>\nL\u2019esibizione si chiude con abbraccio e bacio finale di Eddie Brock al suo ospite. Si incrocia poi la voce di Mara Sattei con le barre di Mecna, insieme ne \u201cL\u2019ultimo bacio\u201d di Carmen Consoli. Patty Pravo, in abito di velluto blu, omaggia Ornella Vanoni salutandola con un \u201cCiao Ornella\u201d alla fine di \u201cTi lascio una canzone\u201d.<br \/>\nIntorno a lei ha danzato Timofej Andrijashenko, primo ballerino della Scala di Milano. Levante e Gaia hanno grande sintonia di sguardi e corpi mentre cantano i \u201cI maschi\u201d in chiave lesbo chiudendo abbracciate e suggellando l\u2019esecuzione con un bacio.<br \/>\nComplicit\u00e0 anche tra Malika Ayane e Claudio Santamaria nel successo di Mina, \u201cMi sei scoppiato dentro il cuore\u201d. Echi metal nella versione di \u201cOcchi di gatto\u201d delle Bambole di pezza con Cristina D\u2019Avena che viene mescolata a \u201cWhole Lotta Love\u201d dei Led Zeppelin. \u201cSu di noi\u201d \u00e8 solo il tappeto musicale scelto da Dargen D\u2019Amico che con Pupo e Fabrizio Bosso porta l\u2019antimilitarismo all\u2019Ariston: nel brano si mescolano \u201cIl disertore\u201d di Boris Vian, \u201cGam Gam\u201d di Elie Botbol, canzone ebraica basata sul Salmo 23, cantata dai bambini ebrei nei campi di concentramento, e citazioni da \u201cIl grande dittatore\u201d di Charlie Chaplin e di papa Francesco, \u201cCi vuole buona volont\u00e0. Non rassegniamoci alla guerra\u201d. Tommaso Paradiso e gli Stadio ricordano Lucio Dalla e lo storico batterista dello stesso gruppo Giovanni Pezzoli con \u201cL\u2019ultima luna\u201d. Elegante l\u2019esecuzione di \u201cDomani \u00e8 un altro giorno\u201d di Michele Bravi che ringrazia Fiorella Mannoia, che sul bavero della giacca indossa la spilla con la bandiera palestinese. Grande sorpresa per tutto l\u2019Ariston e per il pubblico che durante l\u2019esecuzione di \u201cVita\u201d, cover di Tredici Pietro con Galeffi, Fudasca &amp; Band, vede irrompere sul palco \u201cpap\u00e0\u201d Gianni Morandi. Il cantante, che Sanremo l\u2019ha frequentato in tutti i ruoli, alla fine chiede al figlio: \u201cCome sono andato?\u201d e confessa la sua emozione.<br \/>\nBrunori Sas torna all\u2019Ariston con la sua chitarra dopo il terzo posto dello scorso anno per accompagnare Maria Antonietta &amp; Colombre con \u201cIl mondo\u201d accompagnata dalle immagini della terra viste dallo spazio concesse dall\u2019Esa. A parti invertite Fulminacci e Francesca Fagnani cantano \u201cParole Parole\u201d di Mina e Alberto Lupo. LDA &amp; AKA 7EVEN con Tullio De Piscopo, novello 80enne e celebrato con il coro \u201cTullio, Tullio\u201d e una standing ovation, regalano energia con \u201cAndamento lento\u201d coreografata da ballerine in abiti argento. E\u2019 abbigliato in bianco, invece, il corpo di ballo che accompagna Raf e i The Kolors che portano \u201cThe riddle\u201d; tra le ballerine anche Bianca Riefoli, figlia di Raf. E\u2019 tutta milanese la Ligera County Fam, di cui fanno parte Cochi Ponzoni, Paolo Rossi, Ale e Franz e Paolo Jannacci, che celebra con J-Ax \u201cE la vita, la vita\u201d di Cochi e Renato, sigla di \u201cCanzonissima\u201d 1974.<br \/>\nE\u2019 qui che Carlo Conti ricorda il deragliamento del tram che nel pomeriggio di oggi ha fatto due vittime e 48 feriti a Milano, dicendo: \u201cUn abbraccio all\u2019incidente del tram di Milano\u201d. L\u2019atteso TonyPitony, artista irriverente, accompagna Ditonellapiaga e insieme trasformano \u201cThe Lady is a Tramp\u201d in un numero da musical in cui innestano \u201cBaciami piccina\u201d e pure l\u2019annosa questione tutta siciliana sul genere dell&#8217;\u201darancin\u201d. Delicati Enrico Nigiotti e ALFA che nella loro riproposizione di \u201cEn e Xanax\u201d di Samuele Bersani inseriscono anche il bugiardino dello psicofarmaco.<br \/>\nAtmosfere jazz per la \u201cBesame Mucho\u201d di Serena Brancale, Gregory Porter e Delia. Potente la performance di Sayf con Alex Britti e Mario Biondi con \u201cHit the Road Jack\u201d: sul palco il cantautore genovese suona la tromba e porta anche \u201cmamma\u201d Samia. Gli altri duetti sono: Sayf con Alex Britti e Mario Biondi, Francesco Renga con Giusy Ferreri \u201cRagazzo solo, ragazza sola\u201d, Arisa con Coro del Teatro Regio di Parma \u201cQuello che le donne non dicono\u201d, Samurai Jay con Bel\u00e8n Rodr\u00ecguez e Roy Paci \u201cBaila Morena\u201d, Sal Da Vinci con Michele Zarrillo\u201dCinque giorni\u201d, Fedez &amp; Masini con Stjepan Hauser \u201cMeravigliosa Creatura\u201d, Ermal Meta con Dardust \u201cGolden Hour\u201d, Nayt con Joan Thiele \u201cLa canzone dell\u2019amore perduto\u201d, Luch\u00e8 con Gianluca Grignani \u201cFalco a met\u00e0\u201d, Chiello con maestro Saverio Cigarini \u201cMi sono innamorato di te\u201d, Leo Gassmann con Aiello \u201cEra gi\u00e0 tutto previsto\u201d.<br \/>\n-foto Ipa Agency \u2013<br \/>\n(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SANREMO (ITALPRESS) \u2013 Ditonellapiaga e TonyPitony con \u201cThe Lady is a Tramp\u201d vincono la serata delle cover del Festival di Sanremo. Al secondo posto Sayf con Alex Britti e Mario Biondi con \u201cHit the Road Jack\u201d, terza Arisa con il Coro del Teatro Regio di Parma con \u201cQuello che le donne non dicono\u201d. Laura Pausini [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":70482,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-70481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sanremo, Ditonellapiaga con TonyPitony vince serata cover. Morandi a sorpresa sul palco per duettare con il figlio. Premio alla carriera a Caterina Caselli - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sanremo, Ditonellapiaga con TonyPitony vince serata cover. Morandi a sorpresa sul palco per duettare con il figlio. Premio alla carriera a Caterina Caselli - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"SANREMO (ITALPRESS) \u2013 Ditonellapiaga e TonyPitony con \u201cThe Lady is a Tramp\u201d vincono la serata delle cover del Festival di Sanremo. Al secondo posto Sayf con Alex Britti e Mario Biondi con \u201cHit the Road Jack\u201d, terza Arisa con il Coro del Teatro Regio di Parma con \u201cQuello che le donne non dicono\u201d. Laura Pausini [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-28T02:02:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Sanremo, Ditonellapiaga con TonyPitony vince serata cover. Morandi a sorpresa sul palco per duettare con il figlio. Premio alla carriera a Caterina Caselli\",\"datePublished\":\"2026-02-28T02:02:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\\\/\"},\"wordCount\":1261,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260228_0050.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\\\/\",\"name\":\"Sanremo, Ditonellapiaga con TonyPitony vince serata cover. Morandi a sorpresa sul palco per duettare con il figlio. Premio alla carriera a Caterina Caselli - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260228_0050.jpg\",\"datePublished\":\"2026-02-28T02:02:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260228_0050.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260228_0050.jpg\",\"width\":1200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/28\\\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sanremo, Ditonellapiaga con TonyPitony vince serata cover. Morandi a sorpresa sul palco per duettare con il figlio. Premio alla carriera a Caterina Caselli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sanremo, Ditonellapiaga con TonyPitony vince serata cover. Morandi a sorpresa sul palco per duettare con il figlio. Premio alla carriera a Caterina Caselli - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\/","og_locale":"it_IT","og_type":"article","og_title":"Sanremo, Ditonellapiaga con TonyPitony vince serata cover. Morandi a sorpresa sul palco per duettare con il figlio. Premio alla carriera a Caterina Caselli - Live Magazine","og_description":"SANREMO (ITALPRESS) \u2013 Ditonellapiaga e TonyPitony con \u201cThe Lady is a Tramp\u201d vincono la serata delle cover del Festival di Sanremo. Al secondo posto Sayf con Alex Britti e Mario Biondi con \u201cHit the Road Jack\u201d, terza Arisa con il Coro del Teatro Regio di Parma con \u201cQuello che le donne non dicono\u201d. Laura Pausini [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-02-28T02:02:45+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Sanremo, Ditonellapiaga con TonyPitony vince serata cover. Morandi a sorpresa sul palco per duettare con il figlio. Premio alla carriera a Caterina Caselli","datePublished":"2026-02-28T02:02:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\/"},"wordCount":1261,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260228_0050.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\/","name":"Sanremo, Ditonellapiaga con TonyPitony vince serata cover. Morandi a sorpresa sul palco per duettare con il figlio. Premio alla carriera a Caterina Caselli - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260228_0050.jpg","datePublished":"2026-02-28T02:02:45+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260228_0050.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260228_0050.jpg","width":1200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/28\/sanremo-ditonellapiaga-con-tonypitony-vince-serata-cover-morandi-a-sorpresa-sul-palco-per-duettare-con-il-figlio-premio-alla-carriera-a-caterina-caselli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Sanremo, Ditonellapiaga con TonyPitony vince serata cover. Morandi a sorpresa sul palco per duettare con il figlio. Premio alla carriera a Caterina Caselli"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260228_0050.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/70481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=70481"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/70481\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/70482"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=70481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=70481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=70481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}