{"id":70477,"date":"2026-02-27T21:05:06","date_gmt":"2026-02-27T20:05:06","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/02\/27\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\/"},"modified":"2026-02-27T21:05:06","modified_gmt":"2026-02-27T20:05:06","slug":"cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/02\/27\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\/","title":{"rendered":"Cina, nel 2025 Xinjiang leader nazionale nel commercio frontaliero"},"content":{"rendered":"<div>\n<p>URUMQI (CINA) (XINHUA\/ITALPRESS) \u2013 Il commercio frontaliero su piccola scala nella regione autonoma uigura dello Xinjiang, nel nord-ovest della Cina, nel 2025 ha registrato un volume di importazioni ed esportazioni pari a 209,09 miliardi di yuan (30,2 miliardi di dollari USA), collocandosi al primo posto a livello nazionale per il quarto anno consecutivo, mostrano i dati ufficiali.<\/p>\n<p>Regione chiave per l\u2019apertura della Cina verso ovest, lo Xinjiang ha sfruttato il suo vantaggio geografico per approfondire la cooperazione commerciale frontaliera con i Paesi vicini. Nel 2025, il commercio estero totale della regione ha superato per la prima volta i 500 miliardi di yuan, con un aumento del 19,9% su base annua, il tasso di crescita pi\u00f9 rapido in Cina. Il commercio frontaliero su piccola scala ha svolto un ruolo centrale in questa espansione.<\/p>\n<p>Per migliorare l\u2019agevolazione degli scambi, lo Xinjiang ha portato avanti l\u2019ammodernamento delle infrastrutture portuali e innovato i modelli di sdoganamento. Tra i progressi nella costruzione di porti intelligenti figura l\u2019attivazione di un sistema operativo 24 ore su 24, 7 giorni su 7, per il primo canale merci tra Cina e Kirghizistan, con un significativo aumento dell\u2019efficienza.<\/p>\n<p>Ad oggi, lo Xinjiang ha istituito otto meccanismi locali di cooperazione economica con regioni adiacenti nei Paesi confinanti.<\/p>\n<p>Nel 2026, la regione prevede di accelerare la modernizzazione dei porti, prolungare gli orari operativi dei principali valichi stradali e migliorare le condizioni di stoccaggio e logistica per garantire uno sviluppo sano e sostenuto del commercio frontaliero, secondo quanto emerso da una conferenza sull\u2019ottimizzazione dell\u2019ambiente imprenditoriale regionale tenutasi mercoled\u00ec.<br \/>(ITALPRESS).<br \/> -Foto Xinhua-<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>URUMQI (CINA) (XINHUA\/ITALPRESS) \u2013 Il commercio frontaliero su piccola scala nella regione autonoma uigura dello Xinjiang, nel nord-ovest della Cina, nel 2025 ha registrato un volume di importazioni ed esportazioni pari a 209,09 miliardi di yuan (30,2 miliardi di dollari USA), collocandosi al primo posto a livello nazionale per il quarto anno consecutivo, mostrano i [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":70478,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-70477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cina, nel 2025 Xinjiang leader nazionale nel commercio frontaliero - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/27\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cina, nel 2025 Xinjiang leader nazionale nel commercio frontaliero - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"URUMQI (CINA) (XINHUA\/ITALPRESS) \u2013 Il commercio frontaliero su piccola scala nella regione autonoma uigura dello Xinjiang, nel nord-ovest della Cina, nel 2025 ha registrato un volume di importazioni ed esportazioni pari a 209,09 miliardi di yuan (30,2 miliardi di dollari USA), collocandosi al primo posto a livello nazionale per il quarto anno consecutivo, mostrano i [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/27\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-27T20:05:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/27\\\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/27\\\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Cina, nel 2025 Xinjiang leader nazionale nel commercio frontaliero\",\"datePublished\":\"2026-02-27T20:05:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/27\\\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\\\/\"},\"wordCount\":262,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/27\\\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260227_2766.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/27\\\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/27\\\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\\\/\",\"name\":\"Cina, nel 2025 Xinjiang leader nazionale nel commercio frontaliero - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/27\\\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/27\\\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260227_2766.jpg\",\"datePublished\":\"2026-02-27T20:05:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/27\\\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/27\\\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/27\\\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260227_2766.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260227_2766.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/27\\\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cina, nel 2025 Xinjiang leader nazionale nel commercio frontaliero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cina, nel 2025 Xinjiang leader nazionale nel commercio frontaliero - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/02\/27\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\/","og_locale":"it_IT","og_type":"article","og_title":"Cina, nel 2025 Xinjiang leader nazionale nel commercio frontaliero - Live Magazine","og_description":"URUMQI (CINA) (XINHUA\/ITALPRESS) \u2013 Il commercio frontaliero su piccola scala nella regione autonoma uigura dello Xinjiang, nel nord-ovest della Cina, nel 2025 ha registrato un volume di importazioni ed esportazioni pari a 209,09 miliardi di yuan (30,2 miliardi di dollari USA), collocandosi al primo posto a livello nazionale per il quarto anno consecutivo, mostrano i [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/27\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-02-27T20:05:06+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/27\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/27\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Cina, nel 2025 Xinjiang leader nazionale nel commercio frontaliero","datePublished":"2026-02-27T20:05:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/27\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\/"},"wordCount":262,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/27\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260227_2766.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/27\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/27\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\/","name":"Cina, nel 2025 Xinjiang leader nazionale nel commercio frontaliero - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/27\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/27\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260227_2766.jpg","datePublished":"2026-02-27T20:05:06+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/27\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/02\/27\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/27\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260227_2766.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260227_2766.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/27\/cina-nel-2025-xinjiang-leader-nazionale-nel-commercio-frontaliero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Cina, nel 2025 Xinjiang leader nazionale nel commercio frontaliero"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260227_2766.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/70477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=70477"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/70477\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/70478"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=70477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=70477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=70477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}