{"id":70058,"date":"2026-02-22T18:02:33","date_gmt":"2026-02-22T17:02:33","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\/"},"modified":"2026-02-22T18:02:33","modified_gmt":"2026-02-22T17:02:33","slug":"malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\/","title":{"rendered":"<div>Malag\u00f2 &#8220;Aspetto pi\u00f9 complicato di questi Giochi consegna delle venue e budget&#8221;<\/div>"},"content":{"rendered":"<p>    <video-js id=\"videojs6a987cc27b1c1\" class=\"vjs-big-play-centered\" controls preload=\"auto\" playsinline data-setup='{\"fluid\": true}'>\r\n        <source src=\"https:\/\/video.italpress.com\/play\/mp4\/video\/qng2\" type=\"video\/mp4\" \/>\r\n    <\/video-js>\r\n           <br \/>\n<\/p>\n<div> MILANO (ITALPRESS) &#8211; &#8220;L&#8217;aspetto pi\u00f9 complicato da risolvere in queste Olimpiadi? Diciamo la delivery, ovviamente, delle venue. Chi si occupa del comitato organizzatore entra quando qualcun altro ti d\u00e0 le chiavi. Per\u00f2 non \u00e8 che tu la costruisci la venue, erano tutte gi\u00e0 esistenti, bisognava adattarle a quello che sono le esigenze delle federazioni internazionali del CIO&#8221;. Lo ha dichiarato il presidente della Fondazione Milano Cortina 2026 Giovanni Malag\u00f2 a margine della conferenza stampa di chiusura delle Olimpiadi di Milano Cortina 2026. &#8220;Insomma, diciamo che noi siamo semplicemente i campioni del photo finish, questo \u00e8 poco ma sicuro. Pi\u00f9 tutto quello che \u00e8, ovviamente, relativo alle dinamiche riguardanti gli aspetti di budget: se tu parti in un&#8217;avventura a giugno del 2019 e poi ti ritrovi nel febbraio del 2026, nel frattempo non ci \u00e8 mancato niente. Mi sento di dire che questi sono stati i due problemi pi\u00f9 grandi&#8221;.<\/p>\n<p>pia\/gm\/mca3<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>MILANO (ITALPRESS) &#8211; &#8220;L&#8217;aspetto pi\u00f9 complicato da risolvere in queste Olimpiadi? Diciamo la delivery, ovviamente, delle venue. Chi si occupa del comitato organizzatore entra quando qualcun altro ti d\u00e0 le chiavi. Per\u00f2 non \u00e8 che tu la costruisci la venue, erano tutte gi\u00e0 esistenti, bisognava adattarle a quello che sono le esigenze delle federazioni internazionali [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":70059,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1171],"tags":[],"class_list":["post-70058","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-video","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Malag\u00f2 &quot;Aspetto pi\u00f9 complicato di questi Giochi consegna delle venue e budget&quot; - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Malag\u00f2 &quot;Aspetto pi\u00f9 complicato di questi Giochi consegna delle venue e budget&quot; - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"MILANO (ITALPRESS) &#8211; &#8220;L&#8217;aspetto pi\u00f9 complicato da risolvere in queste Olimpiadi? Diciamo la delivery, ovviamente, delle venue. Chi si occupa del comitato organizzatore entra quando qualcun altro ti d\u00e0 le chiavi. Per\u00f2 non \u00e8 che tu la costruisci la venue, erano tutte gi\u00e0 esistenti, bisognava adattarle a quello che sono le esigenze delle federazioni internazionali [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-22T17:02:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Malag\u00f2 &#8220;Aspetto pi\u00f9 complicato di questi Giochi consegna delle venue e budget&#8221;\",\"datePublished\":\"2026-02-22T17:02:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\\\/\"},\"wordCount\":169,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/qng2.jpg\",\"articleSection\":[\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\\\/\",\"name\":\"Malag\u00f2 \\\"Aspetto pi\u00f9 complicato di questi Giochi consegna delle venue e budget\\\" - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/qng2.jpg\",\"datePublished\":\"2026-02-22T17:02:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/qng2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/qng2.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Malag\u00f2 &#8220;Aspetto pi\u00f9 complicato di questi Giochi consegna delle venue e budget&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Malag\u00f2 \"Aspetto pi\u00f9 complicato di questi Giochi consegna delle venue e budget\" - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\/","og_locale":"it_IT","og_type":"article","og_title":"Malag\u00f2 \"Aspetto pi\u00f9 complicato di questi Giochi consegna delle venue e budget\" - Live Magazine","og_description":"MILANO (ITALPRESS) &#8211; &#8220;L&#8217;aspetto pi\u00f9 complicato da risolvere in queste Olimpiadi? Diciamo la delivery, ovviamente, delle venue. Chi si occupa del comitato organizzatore entra quando qualcun altro ti d\u00e0 le chiavi. Per\u00f2 non \u00e8 che tu la costruisci la venue, erano tutte gi\u00e0 esistenti, bisognava adattarle a quello che sono le esigenze delle federazioni internazionali [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-02-22T17:02:33+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Malag\u00f2 &#8220;Aspetto pi\u00f9 complicato di questi Giochi consegna delle venue e budget&#8221;","datePublished":"2026-02-22T17:02:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\/"},"wordCount":169,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/qng2.jpg","articleSection":["Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\/","name":"Malag\u00f2 \"Aspetto pi\u00f9 complicato di questi Giochi consegna delle venue e budget\" - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/qng2.jpg","datePublished":"2026-02-22T17:02:33+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/qng2.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/qng2.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/malago-aspetto-piu-complicato-di-questi-giochi-consegna-delle-venue-e-budget\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Malag\u00f2 &#8220;Aspetto pi\u00f9 complicato di questi Giochi consegna delle venue e budget&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/qng2.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/70058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=70058"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/70058\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/70059"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=70058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=70058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=70058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}