{"id":70056,"date":"2026-02-22T15:02:58","date_gmt":"2026-02-22T14:02:58","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\/"},"modified":"2026-02-22T15:02:58","modified_gmt":"2026-02-22T14:02:58","slug":"genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\/","title":{"rendered":"Genoa travolge Torino 3-0 nello scontro salvezza del Marassi"},"content":{"rendered":"<div>\n<p>GENOVA (ITALPRESS) \u2013 Il Genoa si prende uno scontro salvezza fondamentale, il Torino sprofonda. Gli uomini di Daniele De Rossi travolgono al \u2018Marass\u00ec 3-0 i granata nel match della 26esima giornata di Serie A: a segno Norton-Cuffy, Ekuban e Messias. Le due squadre si concedono un\u2019iniziale fase di studio, ma a prendere le maggiori iniziative sono i padroni di casa, pur senza riuscire a rendersi pericolosi sotto porta. Al 22\u2032 arriva il lampo della formazione rossobl\u00f9, che passa in vantaggio con Brooke Norton-Cuffy: Ekuban calcia, Paleari respinge centralmente e l\u2019esterno ne approfitta per depositare la sfera in fondo al sacco. I granata fanno fatica a reagire, cos\u00ec il Genoa prova a sfruttare il momento e al 33\u2032 si rende pericoloso con un colpo di testa di Vasquez, che termina di poco a lato. Due minuti pi\u00f9 tardi c\u2019\u00e8 il primo squillo del Torino con tiro dalla distanza di Obrador, su cui Bijlow si distende per sventare la minaccia. L\u2019iniziativa dei piemontesi si rivela un fuoco di paglia, poich\u00e8 al 40\u2032 sono ancora i liguri ad andare a segno con Caleb Ekuban: Baldanzi va al tiro dopo una grande azione personale e Paleari compie una respinta imprecisa che favorisce il tap-in dell\u2019attaccante. Qualche minuto dopo i ragazzi di Baroni lamentano un tocco di mano in area di Ekuban, ma il Var non ravvisa nulla. In pieno recupero Ilkhan commette un brutto fallo su Colombo e viene espulso, lasciando i suoi in dieci uomini. In apertura di ripresa sono ancora i padroni di casa a rendersi pericolosi con una conclusione di Ekuban, che termina sul fondo. Il Torino, spinto  anche dai cambi di Marco Baroni, prova a riaprire la contesa con delle conclusioni di Prati, Gineitis e Zapata, ma nessuno riesce ad impensierire Bijlow. Al 67\u2032 il colombiano, imbeccato da Vlasic, va al tiro ma trova l\u2019opposizione del portiere avversario. Due minuti pi\u00f9 tardi Norton-Cuffy sfiora la doppietta, ma Prati compie un salvataggio provvidenziale. Nell\u2019ultima fase del match il Genoa torna a spingere con decisione, tanto che all\u201983\u2019 cala il tris con Junior Messias, che approfitta dell\u2019errore di Pedersen per battere Paleari. I rossobl\u00f9, dunque, si impongono 3-0 e tornano alla vittoria dopo quasi un mese; secondo ko di fila per i granata. In virt\u00f9 di questo successo il Genoa si porta a 27 punti in classifica e aggancia proprio il Torino. Nel prossimo turno i liguri saranno impegnati sabato al Meazza di Milano contro l\u2019Inter; i piemontesi ospiteranno invece la Lazio domenica 1\u00b0 marzo.<br \/>\u2013 Foto Ipa Agency \u2013<br \/>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>GENOVA (ITALPRESS) \u2013 Il Genoa si prende uno scontro salvezza fondamentale, il Torino sprofonda. Gli uomini di Daniele De Rossi travolgono al \u2018Marass\u00ec 3-0 i granata nel match della 26esima giornata di Serie A: a segno Norton-Cuffy, Ekuban e Messias. Le due squadre si concedono un\u2019iniziale fase di studio, ma a prendere le maggiori iniziative [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":70057,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-70056","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Genoa travolge Torino 3-0 nello scontro salvezza del Marassi - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Genoa travolge Torino 3-0 nello scontro salvezza del Marassi - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"GENOVA (ITALPRESS) \u2013 Il Genoa si prende uno scontro salvezza fondamentale, il Torino sprofonda. Gli uomini di Daniele De Rossi travolgono al \u2018Marass\u00ec 3-0 i granata nel match della 26esima giornata di Serie A: a segno Norton-Cuffy, Ekuban e Messias. Le due squadre si concedono un\u2019iniziale fase di studio, ma a prendere le maggiori iniziative [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-22T14:02:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Genoa travolge Torino 3-0 nello scontro salvezza del Marassi\",\"datePublished\":\"2026-02-22T14:02:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\\\/\"},\"wordCount\":427,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260222_0378.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\\\/\",\"name\":\"Genoa travolge Torino 3-0 nello scontro salvezza del Marassi - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260222_0378.jpg\",\"datePublished\":\"2026-02-22T14:02:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260222_0378.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260222_0378.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/22\\\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Genoa travolge Torino 3-0 nello scontro salvezza del Marassi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Genoa travolge Torino 3-0 nello scontro salvezza del Marassi - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\/","og_locale":"it_IT","og_type":"article","og_title":"Genoa travolge Torino 3-0 nello scontro salvezza del Marassi - Live Magazine","og_description":"GENOVA (ITALPRESS) \u2013 Il Genoa si prende uno scontro salvezza fondamentale, il Torino sprofonda. Gli uomini di Daniele De Rossi travolgono al \u2018Marass\u00ec 3-0 i granata nel match della 26esima giornata di Serie A: a segno Norton-Cuffy, Ekuban e Messias. Le due squadre si concedono un\u2019iniziale fase di studio, ma a prendere le maggiori iniziative [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-02-22T14:02:58+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Genoa travolge Torino 3-0 nello scontro salvezza del Marassi","datePublished":"2026-02-22T14:02:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\/"},"wordCount":427,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260222_0378.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\/","name":"Genoa travolge Torino 3-0 nello scontro salvezza del Marassi - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260222_0378.jpg","datePublished":"2026-02-22T14:02:58+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260222_0378.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260222_0378.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/22\/genoa-travolge-torino-3-0-nello-scontro-salvezza-del-marassi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Genoa travolge Torino 3-0 nello scontro salvezza del Marassi"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260222_0378.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/70056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=70056"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/70056\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/70057"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=70056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=70056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=70056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}