{"id":69998,"date":"2026-02-21T15:02:45","date_gmt":"2026-02-21T14:02:45","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/02\/21\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\/"},"modified":"2026-02-21T15:02:45","modified_gmt":"2026-02-21T14:02:45","slug":"nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/02\/21\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\/","title":{"rendered":"<div>Nadalini &#8220;La gente ora vede i successi, ma dietro c&#8217;\u00e8 un gran percorso&#8221;<\/div>"},"content":{"rendered":"<p>    <video-js id=\"videojs6a97e2ce7e2db\" class=\"vjs-big-play-centered\" controls preload=\"auto\" playsinline data-setup='{\"fluid\": true}'>\r\n        <source src=\"https:\/\/video.italpress.com\/play\/mp4\/video\/2NYN\" type=\"video\/mp4\" \/>\r\n    <\/video-js>\r\n           <br \/>\n<\/p>\n<div> MILANO (ITALPRESS) &#8211; &#8220;Cosa mi porto dietro di questa Olimpiade? Sicuramente tutto quello che ho vissuto con i miei amici e la mia squadra, quindi penso che i ricordi sono tutto quello che mi porter\u00f2 dietro per sempre. Penso che non mi dimenticher\u00f2 mai questa fantastica esperienza, non voglio assolutamente dimenticarmi di questa esperienza, me la porter\u00f2 per sempre nel cuore&#8221;. Lo ha dichiarato il pattinatore azzurro Thomas Nadalini, medaglia di bronzo nella staffetta maschile di short track e oro nella staffetta mista alle Olimpiadi di Milano Cortina 2026. &#8220;Non potrei chiedere di pi\u00f9, ovvero cominciare un ciclo olimpico in casa con una squadra e risultati del genere. Sono veramente soddisfatto di tutto il lavoro che abbiamo fatto. Lavoro che, come abbiamo gi\u00e0 detto, non \u00e8 frutto di una settimana allenamento &#8211; ha aggiunto -, ma di qualcosa di molto pi\u00f9 lungo, di lavoro fatto soprattutto dietro le quinte. La gente adesso ci vede vincere, ci vede essere campioni olimpici e dicono &#8220;che fortunati&#8221;, per\u00f2 non sanno tutto quello che c&#8217;\u00e8 dietro, quindi incentivo veramente le persone a seguirci per tutto il nostro percorso, non solo durante le Olimpiadi, perch\u00e9 siamo cresciuti veramente molto nell&#8217;ultimo quadriennio. Penso che chi ci ha seguito dal 2022 fino adesso pu\u00f2 apprezzare ancora molto di pi\u00f9 questo traguardo perch\u00e9 ci ha visto crescere e ci ha visto non solo come campioni olimpici, ma partire dal basso per arrivare al top&#8221;.<\/p>\n<p>pia\/gm\/mca3<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>MILANO (ITALPRESS) &#8211; &#8220;Cosa mi porto dietro di questa Olimpiade? Sicuramente tutto quello che ho vissuto con i miei amici e la mia squadra, quindi penso che i ricordi sono tutto quello che mi porter\u00f2 dietro per sempre. Penso che non mi dimenticher\u00f2 mai questa fantastica esperienza, non voglio assolutamente dimenticarmi di questa esperienza, me [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":69999,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1171],"tags":[],"class_list":["post-69998","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-video","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nadalini &quot;La gente ora vede i successi, ma dietro c&#039;\u00e8 un gran percorso&quot; - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/21\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nadalini &quot;La gente ora vede i successi, ma dietro c&#039;\u00e8 un gran percorso&quot; - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"MILANO (ITALPRESS) &#8211; &#8220;Cosa mi porto dietro di questa Olimpiade? Sicuramente tutto quello che ho vissuto con i miei amici e la mia squadra, quindi penso che i ricordi sono tutto quello che mi porter\u00f2 dietro per sempre. Penso che non mi dimenticher\u00f2 mai questa fantastica esperienza, non voglio assolutamente dimenticarmi di questa esperienza, me [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/21\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-21T14:02:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/21\\\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/21\\\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Nadalini &#8220;La gente ora vede i successi, ma dietro c&#8217;\u00e8 un gran percorso&#8221;\",\"datePublished\":\"2026-02-21T14:02:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/21\\\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\\\/\"},\"wordCount\":261,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/21\\\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/2NYN.jpg\",\"articleSection\":[\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/21\\\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/21\\\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\\\/\",\"name\":\"Nadalini \\\"La gente ora vede i successi, ma dietro c'\u00e8 un gran percorso\\\" - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/21\\\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/21\\\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/2NYN.jpg\",\"datePublished\":\"2026-02-21T14:02:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/21\\\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/21\\\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/21\\\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/2NYN.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/2NYN.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/21\\\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nadalini &#8220;La gente ora vede i successi, ma dietro c&#8217;\u00e8 un gran percorso&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nadalini \"La gente ora vede i successi, ma dietro c'\u00e8 un gran percorso\" - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/02\/21\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\/","og_locale":"it_IT","og_type":"article","og_title":"Nadalini \"La gente ora vede i successi, ma dietro c'\u00e8 un gran percorso\" - Live Magazine","og_description":"MILANO (ITALPRESS) &#8211; &#8220;Cosa mi porto dietro di questa Olimpiade? Sicuramente tutto quello che ho vissuto con i miei amici e la mia squadra, quindi penso che i ricordi sono tutto quello che mi porter\u00f2 dietro per sempre. Penso che non mi dimenticher\u00f2 mai questa fantastica esperienza, non voglio assolutamente dimenticarmi di questa esperienza, me [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/21\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-02-21T14:02:45+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/21\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/21\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Nadalini &#8220;La gente ora vede i successi, ma dietro c&#8217;\u00e8 un gran percorso&#8221;","datePublished":"2026-02-21T14:02:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/21\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\/"},"wordCount":261,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/21\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/2NYN.jpg","articleSection":["Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/21\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/21\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\/","name":"Nadalini \"La gente ora vede i successi, ma dietro c'\u00e8 un gran percorso\" - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/21\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/21\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/2NYN.jpg","datePublished":"2026-02-21T14:02:45+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/21\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/02\/21\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/21\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/2NYN.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/2NYN.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/21\/nadalini-la-gente-ora-vede-i-successi-ma-dietro-ce-un-gran-percorso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Nadalini &#8220;La gente ora vede i successi, ma dietro c&#8217;\u00e8 un gran percorso&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/2NYN.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/69998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=69998"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/69998\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/69999"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=69998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=69998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=69998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}