{"id":69892,"date":"2026-02-19T21:02:59","date_gmt":"2026-02-19T20:02:59","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\/"},"modified":"2026-02-19T21:02:59","modified_gmt":"2026-02-19T20:02:59","slug":"meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\/","title":{"rendered":"Meloni \u201cLa campagna referendaria resti nel merito, non sia una lotta nel fango\u201d"},"content":{"rendered":"<div>\n<p>ROMA (ITALPRESS) \u2013 \u201cPenso che sia molto importante che questa campagna referendaria rimanga sul merito e sul contenuto di ci\u00f2 di cui stiamo parlando, senza cercare di trasformarla in altro: una polarizzazione o un referendum sul governo interessa chi non pu\u00f2 stare nel merito, non noi perch\u00e8 la conferma della riforma pu\u00f2 solo fare il bene dell\u2019Italia\u201d. Cos\u00ec la presidente del Consiglio Giorgia Meloni, intervistata dal direttore di Sky Tg24 Fabio Vitale. \u201cVedo un tentativo di trascinarla in una sorta di lotta nel fango, che interessa pi\u00f9 quelli che hanno una difficolt\u00e0 ad attaccare una riforma che in passato hanno per varie parti sostenuto e proposto \u2013 aggiunge Meloni -. Credo che sicuramente non convenga a chi, come noi, ritiene di aver fatto una riforma di buon senso. Questa non \u00e8 una riforma di destra o di sinistra, lo dimostra il fatto che \u00e8 stata nei decenni proposta dalle pi\u00f9 svariate componenti politiche: essa consente di avere una giustizia pi\u00f9 giusta, liberare il merito dei magistrati dal giogo delle correnti e stabilire il principio che anche il magistrato quando sbaglia deve essere giudicato da un organismo terzo\u201d. <br \/>\u201cCredo nella democrazia, quindi pi\u00f9 gente partecipa e pi\u00f9 penso di aver fatto bene il mio lavoro: penso valga lo stesso per tutti i partiti politici. A sei settimane dal voto, quando sappiamo bene che la maggior parte dei cittadini decidono negli ultimi giorni se andare a votare o no e cosa, i sondaggi lasciano il tempo che trovano: la vera campagna referendaria deve ancora cominciare \u2013 sottolinea la presidente del Consiglio -. Siamo a un mese dalla data del voto e faremo quello che possiamo, per fare in modo che ci sia pi\u00f9 gente possibile che vada a votare e che vota consapevolmente. A me fa molto sorridere chi dice che se il governo perde il referendum va a casa, chi non pu\u00f2 parlare del merito della riforma deve spostare l\u2019obiettivo per fare in modo di portare i suoi sostenitori a votare; le elezioni politiche saranno fra un anno, l\u00ec gli italiani decideranno se mandarmi a casa o no. Io, a differenza di altri, non rimango abbarbicata al potere se gli italiani non vogliono che continui a governare: dopo tutto il lavoro che \u00e8 stato fatto credo che sia giusto che il giudizio sia sul complesso di ci\u00f2 che abbiamo fatto, la riforma della giustizia \u00e8 importantissima ma \u00e8 una cosa sola tra altre 500\u201d.<br \/>\u201cIl 22 e 23 marzo non si vota sul governo, ma sulla giustizia: qualunque sia la decisione che gli italiani prenderanno incider\u00e0 sulle loro vite molto oltre la durata di questo governo, perch\u00e8 una riforma costituzionale su un tema cos\u00ec importante incide sulla vita nostra e dei nostri figli. Il mio consiglio agli italiani \u00e8 \u2018andate a votare, ma votate con coscienza guardando a quello che state votando e non ad altr\u00f2: non personalizzo un tema cos\u00ec importante per la vita dei cittadini, penso banalmente che migliorare lo stato della giustizia italiana non si fa per il governo ma per se stessi, per l\u2019Italia, per avere una nazione pi\u00f9 moderna \u2013 conclude Meloni -. Ogni volta che si cerca di far qualcosa per migliorare lo stato della giustizia i toni diventano apocalittici: migliorarla vale anche per i magistrati, questa non \u00e8 una riforma contro i giudici. Si pu\u00f2 non essere d\u2019accordo, ma senza toni da fine del mondo\u201d.<\/p>\n<p>\u2013 Foto IPA Agency \u2013<\/p>\n<p>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) \u2013 \u201cPenso che sia molto importante che questa campagna referendaria rimanga sul merito e sul contenuto di ci\u00f2 di cui stiamo parlando, senza cercare di trasformarla in altro: una polarizzazione o un referendum sul governo interessa chi non pu\u00f2 stare nel merito, non noi perch\u00e8 la conferma della riforma pu\u00f2 solo fare il [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":69893,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-69892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Meloni \u201cLa campagna referendaria resti nel merito, non sia una lotta nel fango\u201d - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meloni \u201cLa campagna referendaria resti nel merito, non sia una lotta nel fango\u201d - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"ROMA (ITALPRESS) \u2013 \u201cPenso che sia molto importante che questa campagna referendaria rimanga sul merito e sul contenuto di ci\u00f2 di cui stiamo parlando, senza cercare di trasformarla in altro: una polarizzazione o un referendum sul governo interessa chi non pu\u00f2 stare nel merito, non noi perch\u00e8 la conferma della riforma pu\u00f2 solo fare il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-19T20:02:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Meloni \u201cLa campagna referendaria resti nel merito, non sia una lotta nel fango\u201d\",\"datePublished\":\"2026-02-19T20:02:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\\\/\"},\"wordCount\":568,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260219_3243.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\\\/\",\"name\":\"Meloni \u201cLa campagna referendaria resti nel merito, non sia una lotta nel fango\u201d - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260219_3243.jpg\",\"datePublished\":\"2026-02-19T20:02:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260219_3243.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260219_3243.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Meloni \u201cLa campagna referendaria resti nel merito, non sia una lotta nel fango\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Meloni \u201cLa campagna referendaria resti nel merito, non sia una lotta nel fango\u201d - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\/","og_locale":"it_IT","og_type":"article","og_title":"Meloni \u201cLa campagna referendaria resti nel merito, non sia una lotta nel fango\u201d - Live Magazine","og_description":"ROMA (ITALPRESS) \u2013 \u201cPenso che sia molto importante che questa campagna referendaria rimanga sul merito e sul contenuto di ci\u00f2 di cui stiamo parlando, senza cercare di trasformarla in altro: una polarizzazione o un referendum sul governo interessa chi non pu\u00f2 stare nel merito, non noi perch\u00e8 la conferma della riforma pu\u00f2 solo fare il [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-02-19T20:02:59+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Meloni \u201cLa campagna referendaria resti nel merito, non sia una lotta nel fango\u201d","datePublished":"2026-02-19T20:02:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\/"},"wordCount":568,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260219_3243.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\/","name":"Meloni \u201cLa campagna referendaria resti nel merito, non sia una lotta nel fango\u201d - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260219_3243.jpg","datePublished":"2026-02-19T20:02:59+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260219_3243.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260219_3243.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/meloni-la-campagna-referendaria-resti-nel-merito-non-sia-una-lotta-nel-fango\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Meloni \u201cLa campagna referendaria resti nel merito, non sia una lotta nel fango\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260219_3243.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/69892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=69892"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/69892\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/69893"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=69892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=69892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=69892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}