{"id":69890,"date":"2026-02-19T21:02:57","date_gmt":"2026-02-19T20:02:57","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\/"},"modified":"2026-02-19T21:02:57","modified_gmt":"2026-02-19T20:02:57","slug":"arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\/","title":{"rendered":"Arditti e Gallicola, in \u201cPiumini e catene\u201d il racconto sul fenomeno maranza"},"content":{"rendered":"<div>\n<p>ROMA (ITALPRESS) \u2013 Un viaggio all\u2019interno di 12 storie di cronaca per raccontare uno dei fenomeni pi\u00f9 discussi negli ultimi anni, quello dei maranza. E\u2019 \u201cPiumini e catene. Storie di maranza\u201d (Armando Curcio Editore), libro scritto da Roberto Arditti e Alessio Gallicola, con i contributi di Tommaso Cerno e Maria Rita Parsi, psicoterapeuta scomparsa il 2 febbraio.<br \/>\nArditti e Gallicola, intervistati da Claudio Brachino per la rubrica Primo Piano dell\u2019agenzia Italpress, raccontano da dove nasce questo libro: \u201cLo scorso anno c\u2019\u00e8 stata una chiamata alle armi di un capo maranza di Torino, dove in occasione della partita Napoli-Inter fa un post sui social invitando ad andare al Sud per \u2018far vedere a questi meridionali chi comand\u00e0; si organizzano, partono in 20 ma non arrivano perch\u00e8 vengono fermati a Roma dalla Polfer. Questo fa scattare un allarme\u201d, racconta Alessio Gallicola.<br \/>\n\u201cQuesti ragazzi sono essenzialmente dei delinquenti \u2013 spiega Arditti -, una scelta voluta, cercata e pensata, loro non vengono da famiglie disastrose e la maggior parte di questi ragazzi sono cresciuti in Italia. Sono tutti accomunati da una precisa provenienza di carattere etnico, vengono soprattutto dai Paesi del Nord Africa e hanno metabolizzato l\u2019uso pericoloso di pezzetti di rivendicazione islamica, un elemento di diversit\u00e0 e lo usano strumentalmente per dire \u2018noi siamo quelli che comanderemo tra poc\u00f2\u201d, prosegue Arditti, che racconta una delle storie: \u201cUn piccolo gruppo di maranza, questa volta proveniente da un campo rom, tutti ragazzi tra i 12 e i 15 anni, rompono il bagagliaio della macchina di turisti francesi e rubano il trolley; lo portano nel campo rom e trovano al suo interno una copia delle chiavi della macchina, nessuno ha la patente ma tornano a prendere la macchina e guidarla e investono una anziana signora sulle strisce uccidendola. Questa \u00e8 una storia emblematica \u2013 spiega Arditti -, perch\u00e8 racconta anche la funzione dei genitori che, in questo caso, \u00e8 quella di incoraggiarli verso la cattiva strada\u201d.<br \/>\nNon solo un libro, un racconto, ma anche l\u2019intento di coinvolgere le istituzioni a tutti i livelli.<br \/>\n\u201cPresenteremo il libro con il ministro dell\u2019Istruzione, Giuseppe Valditara, con il ministro dell\u2019Interno, Matteo Piantedosi, e il sottosegretario Andrea Delmastro. Io sono stato anche in audizione alla Commissione periferie della Camera che lavora in modo bipartisan sul tema \u2013 aggiunge Gallicola -, abbiamo gi\u00e0 portato in sede istituzionale questo tema. Siamo convinti che vada assunto qualche provvedimento che coinvolga anche i genitori che spesso giustificano i loro figli, altrimenti siamo coscienti del fatto che questo fenomeno ce lo vedremo sfuggire di mano\u201d. Per Arditti serve \u201cuna mano molto ferma per questi fenomeni, loro hanno imparato a usare le pieghe del nostro sistema morbido e comprensivo a loro vantaggio e ci marciano\u201d, conclude.<\/p>\n<p>\u2013 Foto Italpress \u2013<\/p>\n<p>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) \u2013 Un viaggio all\u2019interno di 12 storie di cronaca per raccontare uno dei fenomeni pi\u00f9 discussi negli ultimi anni, quello dei maranza. E\u2019 \u201cPiumini e catene. Storie di maranza\u201d (Armando Curcio Editore), libro scritto da Roberto Arditti e Alessio Gallicola, con i contributi di Tommaso Cerno e Maria Rita Parsi, psicoterapeuta scomparsa il [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":69891,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-69890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arditti e Gallicola, in \u201cPiumini e catene\u201d il racconto sul fenomeno maranza - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arditti e Gallicola, in \u201cPiumini e catene\u201d il racconto sul fenomeno maranza - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"ROMA (ITALPRESS) \u2013 Un viaggio all\u2019interno di 12 storie di cronaca per raccontare uno dei fenomeni pi\u00f9 discussi negli ultimi anni, quello dei maranza. E\u2019 \u201cPiumini e catene. Storie di maranza\u201d (Armando Curcio Editore), libro scritto da Roberto Arditti e Alessio Gallicola, con i contributi di Tommaso Cerno e Maria Rita Parsi, psicoterapeuta scomparsa il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-19T20:02:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Arditti e Gallicola, in \u201cPiumini e catene\u201d il racconto sul fenomeno maranza\",\"datePublished\":\"2026-02-19T20:02:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\\\/\"},\"wordCount\":459,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260219_3043.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\\\/\",\"name\":\"Arditti e Gallicola, in \u201cPiumini e catene\u201d il racconto sul fenomeno maranza - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260219_3043.jpg\",\"datePublished\":\"2026-02-19T20:02:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260219_3043.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260219_3043.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/19\\\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arditti e Gallicola, in \u201cPiumini e catene\u201d il racconto sul fenomeno maranza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arditti e Gallicola, in \u201cPiumini e catene\u201d il racconto sul fenomeno maranza - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\/","og_locale":"it_IT","og_type":"article","og_title":"Arditti e Gallicola, in \u201cPiumini e catene\u201d il racconto sul fenomeno maranza - Live Magazine","og_description":"ROMA (ITALPRESS) \u2013 Un viaggio all\u2019interno di 12 storie di cronaca per raccontare uno dei fenomeni pi\u00f9 discussi negli ultimi anni, quello dei maranza. E\u2019 \u201cPiumini e catene. Storie di maranza\u201d (Armando Curcio Editore), libro scritto da Roberto Arditti e Alessio Gallicola, con i contributi di Tommaso Cerno e Maria Rita Parsi, psicoterapeuta scomparsa il [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-02-19T20:02:57+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Arditti e Gallicola, in \u201cPiumini e catene\u201d il racconto sul fenomeno maranza","datePublished":"2026-02-19T20:02:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\/"},"wordCount":459,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260219_3043.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\/","name":"Arditti e Gallicola, in \u201cPiumini e catene\u201d il racconto sul fenomeno maranza - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260219_3043.jpg","datePublished":"2026-02-19T20:02:57+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260219_3043.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260219_3043.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/19\/arditti-e-gallicola-in-piumini-e-catene-il-racconto-sul-fenomeno-maranza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Arditti e Gallicola, in \u201cPiumini e catene\u201d il racconto sul fenomeno maranza"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260219_3043.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/69890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=69890"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/69890\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/69891"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=69890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=69890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=69890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}