{"id":69784,"date":"2026-02-18T15:02:52","date_gmt":"2026-02-18T14:02:52","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\/"},"modified":"2026-02-18T15:02:52","modified_gmt":"2026-02-18T14:02:52","slug":"pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\/","title":{"rendered":"Pattinaggio, storico bronzo per la Cina nell\u2019inseguimento a squadre"},"content":{"rendered":"<div>\n<p>MILANO (ITALPRESS) \u2013 La nazionale cinese di pattinaggio di velocit\u00e0 si \u00e8 messa al collo una storica medaglia di bronzo ai Giochi Invernali di Milano-Cortina. Nella finale B dell\u2019inseguimento a squadre maschile, il terzetto composto da Liu Hanbin, Wu Yu e Li Wenhao ha avuto la meglio sull\u2019Olanda: 3\u201941\u203338 il crono finale e orange battuti per appena 9 centesimi. Per la Cina si tratta della prima medaglia di sempre in questa specialit\u00e0. \u201cRaggiungere questo risultato \u00e8 un enorme spinta per tutta la squadra. Ha un altissimo valore per noi\u201d, ha sottolineato Ning, che aveva preso parte alla semifinale e gi\u00e0 bronzo nei 1000. Per Liu un bronzo speciale visto che aveva promesso alla nonna di tornare a casa con una medaglia: \u201cSpero che mi abbia visto, \u00e8 un risultato che appartiene a tutto il pattinaggio di velocit\u00e0 cinese e al nostro Paese\u201d.<br \/>\u2013 foto Xinhua \u2013<br \/>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>MILANO (ITALPRESS) \u2013 La nazionale cinese di pattinaggio di velocit\u00e0 si \u00e8 messa al collo una storica medaglia di bronzo ai Giochi Invernali di Milano-Cortina. Nella finale B dell\u2019inseguimento a squadre maschile, il terzetto composto da Liu Hanbin, Wu Yu e Li Wenhao ha avuto la meglio sull\u2019Olanda: 3\u201941\u203338 il crono finale e orange battuti [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":69785,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-69784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pattinaggio, storico bronzo per la Cina nell\u2019inseguimento a squadre - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pattinaggio, storico bronzo per la Cina nell\u2019inseguimento a squadre - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"MILANO (ITALPRESS) \u2013 La nazionale cinese di pattinaggio di velocit\u00e0 si \u00e8 messa al collo una storica medaglia di bronzo ai Giochi Invernali di Milano-Cortina. Nella finale B dell\u2019inseguimento a squadre maschile, il terzetto composto da Liu Hanbin, Wu Yu e Li Wenhao ha avuto la meglio sull\u2019Olanda: 3\u201941\u203338 il crono finale e orange battuti [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-18T14:02:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Pattinaggio, storico bronzo per la Cina nell\u2019inseguimento a squadre\",\"datePublished\":\"2026-02-18T14:02:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\\\/\"},\"wordCount\":150,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260218_0935.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\\\/\",\"name\":\"Pattinaggio, storico bronzo per la Cina nell\u2019inseguimento a squadre - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260218_0935.jpg\",\"datePublished\":\"2026-02-18T14:02:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260218_0935.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260218_0935.jpg\",\"width\":1200,\"height\":664},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pattinaggio, storico bronzo per la Cina nell\u2019inseguimento a squadre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pattinaggio, storico bronzo per la Cina nell\u2019inseguimento a squadre - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\/","og_locale":"it_IT","og_type":"article","og_title":"Pattinaggio, storico bronzo per la Cina nell\u2019inseguimento a squadre - Live Magazine","og_description":"MILANO (ITALPRESS) \u2013 La nazionale cinese di pattinaggio di velocit\u00e0 si \u00e8 messa al collo una storica medaglia di bronzo ai Giochi Invernali di Milano-Cortina. Nella finale B dell\u2019inseguimento a squadre maschile, il terzetto composto da Liu Hanbin, Wu Yu e Li Wenhao ha avuto la meglio sull\u2019Olanda: 3\u201941\u203338 il crono finale e orange battuti [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-02-18T14:02:52+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Pattinaggio, storico bronzo per la Cina nell\u2019inseguimento a squadre","datePublished":"2026-02-18T14:02:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\/"},"wordCount":150,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260218_0935.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\/","name":"Pattinaggio, storico bronzo per la Cina nell\u2019inseguimento a squadre - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260218_0935.jpg","datePublished":"2026-02-18T14:02:52+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260218_0935.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260218_0935.jpg","width":1200,"height":664},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/pattinaggio-storico-bronzo-per-la-cina-nellinseguimento-a-squadre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Pattinaggio, storico bronzo per la Cina nell\u2019inseguimento a squadre"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260218_0935.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/69784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=69784"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/69784\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/69785"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=69784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=69784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=69784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}