{"id":69780,"date":"2026-02-18T15:02:46","date_gmt":"2026-02-18T14:02:46","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\/"},"modified":"2026-02-18T15:02:46","modified_gmt":"2026-02-18T14:02:46","slug":"lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\/","title":{"rendered":"<div>Lagalla &#8220;Area Ex Chimica Arenella strategica per la citt\u00e0 di Palermo&#8221;<\/div>"},"content":{"rendered":"<p>    <video-js id=\"videojs6a580e58871e8\" class=\"vjs-big-play-centered\" controls preload=\"auto\" playsinline data-setup='{\"fluid\": true}'>\r\n        <source src=\"https:\/\/video.italpress.com\/play\/mp4\/video\/qnvp\" type=\"video\/mp4\" \/>\r\n    <\/video-js>\r\n           <br \/>\n<\/p>\n<div> PALERMO (ITALPRESS) &#8211;  &#8220;La collaborazione con l&#8217;Agenzia nazionale del demanio ci ha consentito di selezionare fino a questo momento una serie di progetti destinati alla riconversione e al recupero di un&#8217;area che per la nostra citt\u00e0 e per la rigenerazione urbana \u00e8 strategica. Il vantaggio di questa procedura \u00e8 che chi presenta i progetti si impegna a dare piena copertura economica. Il progetto \u00e8 gi\u00e0 assistito dalla copertura finanziaria del partenariato privato, quindi si coniuga un rapporto importante tra Agenzia nazionale del demanio, Comune di Palermo e soggetto privato che sar\u00e0 considerato il pi\u00f9 utile e conforme al modello di sviluppo della nostra citt\u00e0&#8221;. Cos\u00ec Roberto Lagalla, sindaco di Palermo, in merito allo stabilimento dell&#8217;ex Chimica Arenella, a margine della presentazione della seconda fase del progetto Reinventing Cities.  Pi\u00f9 complessa, spiega il sindaco, la procedura di bonifica e di pieno ripristino dell&#8217;area, gravata da un lungo periodo di degrado e incuria:&#8221;L&#8217;amministrazione comunale ha cercato di mettere in sicurezza l&#8217;area e ripulirla almeno superficialmente dai rifiuti: questo purtroppo \u00e8 uno dei tanti esempi di incivilt\u00e0 che caratterizzano alcuni comportamenti a Palermo. \u00c8 chiaro che il tema della bonifica \u00e8 incluso all&#8217;interno dell&#8217;attivit\u00e0 che dovr\u00e0 essere svolta dal vincitore del pubblico concorso&#8221;. xd8\/vbo\/mca3<\/div>\n","protected":false},"excerpt":{"rendered":"<p>PALERMO (ITALPRESS) &#8211; &#8220;La collaborazione con l&#8217;Agenzia nazionale del demanio ci ha consentito di selezionare fino a questo momento una serie di progetti destinati alla riconversione e al recupero di un&#8217;area che per la nostra citt\u00e0 e per la rigenerazione urbana \u00e8 strategica. Il vantaggio di questa procedura \u00e8 che chi presenta i progetti si [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":69781,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1171],"tags":[],"class_list":["post-69780","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-video","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lagalla &quot;Area Ex Chimica Arenella strategica per la citt\u00e0 di Palermo&quot; - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lagalla &quot;Area Ex Chimica Arenella strategica per la citt\u00e0 di Palermo&quot; - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"PALERMO (ITALPRESS) &#8211; &#8220;La collaborazione con l&#8217;Agenzia nazionale del demanio ci ha consentito di selezionare fino a questo momento una serie di progetti destinati alla riconversione e al recupero di un&#8217;area che per la nostra citt\u00e0 e per la rigenerazione urbana \u00e8 strategica. Il vantaggio di questa procedura \u00e8 che chi presenta i progetti si [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-18T14:02:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Lagalla &#8220;Area Ex Chimica Arenella strategica per la citt\u00e0 di Palermo&#8221;\",\"datePublished\":\"2026-02-18T14:02:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\\\/\"},\"wordCount\":228,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/qnvp.jpg\",\"articleSection\":[\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\\\/\",\"name\":\"Lagalla \\\"Area Ex Chimica Arenella strategica per la citt\u00e0 di Palermo\\\" - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/qnvp.jpg\",\"datePublished\":\"2026-02-18T14:02:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/qnvp.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/qnvp.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lagalla &#8220;Area Ex Chimica Arenella strategica per la citt\u00e0 di Palermo&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lagalla \"Area Ex Chimica Arenella strategica per la citt\u00e0 di Palermo\" - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\/","og_locale":"it_IT","og_type":"article","og_title":"Lagalla \"Area Ex Chimica Arenella strategica per la citt\u00e0 di Palermo\" - Live Magazine","og_description":"PALERMO (ITALPRESS) &#8211; &#8220;La collaborazione con l&#8217;Agenzia nazionale del demanio ci ha consentito di selezionare fino a questo momento una serie di progetti destinati alla riconversione e al recupero di un&#8217;area che per la nostra citt\u00e0 e per la rigenerazione urbana \u00e8 strategica. Il vantaggio di questa procedura \u00e8 che chi presenta i progetti si [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-02-18T14:02:46+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Lagalla &#8220;Area Ex Chimica Arenella strategica per la citt\u00e0 di Palermo&#8221;","datePublished":"2026-02-18T14:02:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\/"},"wordCount":228,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/qnvp.jpg","articleSection":["Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\/","name":"Lagalla \"Area Ex Chimica Arenella strategica per la citt\u00e0 di Palermo\" - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/qnvp.jpg","datePublished":"2026-02-18T14:02:46+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/qnvp.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/qnvp.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/lagalla-area-ex-chimica-arenella-strategica-per-la-citta-di-palermo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Lagalla &#8220;Area Ex Chimica Arenella strategica per la citt\u00e0 di Palermo&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/qnvp.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/69780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=69780"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/69780\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/69781"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=69780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=69780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=69780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}