{"id":69734,"date":"2026-02-18T03:02:34","date_gmt":"2026-02-18T02:02:34","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\/"},"modified":"2026-02-18T03:02:34","modified_gmt":"2026-02-18T02:02:34","slug":"atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\/","title":{"rendered":"Atalanta cede 2-0 a Dortmund nell\u2019andata del play-off di Champions"},"content":{"rendered":"<div>\n<p>DORTMUND (GERMANIA) (ITALPRESS) \u2013 Strada in salita per l\u2019Atalanta. Nell\u2019andata dei playoff di Champions League, la Dea si arrende in casa del Borussia Dortmund, che vince 2-0 grazie alle reti di Guirassy e Beier nel primo tempo. Il calcio d\u2019inizio \u00e8 posticipato di 15 minuti per un ritardo dei tedeschi nel raggiungere lo stadio. Kovac schiera in difesa il 2008 italiano Reggiani, che ha esordito in Bundesliga solo dieci giorni fa. Palladino sceglie Scamacca in avanti e Kossonou in difesa. Per quest\u2019ultimo, per\u00f2, l\u2019inizio non \u00e8 dei migliori, perch\u00e8 dopo 120 secondi si fa sovrastare da Guirassy sull\u20191-0 del Dortmund. Beier serve Ryerson, che con un cross perfetto trova la testa del suo centravanti, bravo a svettare sbloccando subito il match. Gli ospiti, gi\u00e0 costretti a rispondere, attaccano soprattutto sulla sinistra con la catena Kolasinac-Bernasconi-Zalewski. Una volta arrivata in area, per\u00f2, la Dea non riesce a rendersi davvero pericolosa. Lo sono molto di pi\u00f9 i gialloneri quando accelerano, come nel caso del raddoppio che arriva al 42\u2032. Guirassy viene lanciato in profondita, brucia Djimsiti e arriva sul fondo, prima di mettere in mezzo dove Beier, lasciato solo, deve solo appoggiare in rete. Le squadre rientrano negli spogliatoi sul 2-0, risultato pesante per la squadra di Palladino. Al rientro in campo l\u2019Atalanta sembra incapace di sfondare la retroguardia del Borussia, che si guarda bene dallo scoprirsi forte delle due reti di vantaggio. Cos\u00ec, anche a inizio ripresa sono i tedeschi a creare le occasioni pi\u00f9 pericolose, pur senza strafare. Al 56\u2032 Krstovic finisce a terra in area dopo un contatto con Anton, ma Gozubuyuk lascia correre. All\u201988\u2019, con gli ultimi 20 metri ben protetti dai gialloneri, il neo entrato Samardzic ci prova da fuori: Kobel blocca senza problemi. L\u2019Atalanta esce dai primi 90 minuti con due reti da recuperare mercoled\u00ec prossimo alle 18:45, quando al Gewiss Stadium si disputer\u00e0 il secondo atto di questi play-off.<br \/>\n\u2013 Foto Ipa Agency \u2013<br \/>\n(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>DORTMUND (GERMANIA) (ITALPRESS) \u2013 Strada in salita per l\u2019Atalanta. Nell\u2019andata dei playoff di Champions League, la Dea si arrende in casa del Borussia Dortmund, che vince 2-0 grazie alle reti di Guirassy e Beier nel primo tempo. Il calcio d\u2019inizio \u00e8 posticipato di 15 minuti per un ritardo dei tedeschi nel raggiungere lo stadio. Kovac [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":69735,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-69734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atalanta cede 2-0 a Dortmund nell\u2019andata del play-off di Champions - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atalanta cede 2-0 a Dortmund nell\u2019andata del play-off di Champions - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"DORTMUND (GERMANIA) (ITALPRESS) \u2013 Strada in salita per l\u2019Atalanta. Nell\u2019andata dei playoff di Champions League, la Dea si arrende in casa del Borussia Dortmund, che vince 2-0 grazie alle reti di Guirassy e Beier nel primo tempo. Il calcio d\u2019inizio \u00e8 posticipato di 15 minuti per un ritardo dei tedeschi nel raggiungere lo stadio. Kovac [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-18T02:02:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Atalanta cede 2-0 a Dortmund nell\u2019andata del play-off di Champions\",\"datePublished\":\"2026-02-18T02:02:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\\\/\"},\"wordCount\":326,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260217_3101.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\\\/\",\"name\":\"Atalanta cede 2-0 a Dortmund nell\u2019andata del play-off di Champions - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260217_3101.jpg\",\"datePublished\":\"2026-02-18T02:02:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260217_3101.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260217_3101.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/18\\\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atalanta cede 2-0 a Dortmund nell\u2019andata del play-off di Champions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atalanta cede 2-0 a Dortmund nell\u2019andata del play-off di Champions - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\/","og_locale":"it_IT","og_type":"article","og_title":"Atalanta cede 2-0 a Dortmund nell\u2019andata del play-off di Champions - Live Magazine","og_description":"DORTMUND (GERMANIA) (ITALPRESS) \u2013 Strada in salita per l\u2019Atalanta. Nell\u2019andata dei playoff di Champions League, la Dea si arrende in casa del Borussia Dortmund, che vince 2-0 grazie alle reti di Guirassy e Beier nel primo tempo. Il calcio d\u2019inizio \u00e8 posticipato di 15 minuti per un ritardo dei tedeschi nel raggiungere lo stadio. Kovac [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-02-18T02:02:34+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Atalanta cede 2-0 a Dortmund nell\u2019andata del play-off di Champions","datePublished":"2026-02-18T02:02:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\/"},"wordCount":326,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260217_3101.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\/","name":"Atalanta cede 2-0 a Dortmund nell\u2019andata del play-off di Champions - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260217_3101.jpg","datePublished":"2026-02-18T02:02:34+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260217_3101.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260217_3101.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/18\/atalanta-cede-2-0-a-dortmund-nellandata-del-play-off-di-champions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Atalanta cede 2-0 a Dortmund nell\u2019andata del play-off di Champions"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260217_3101.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/69734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=69734"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/69734\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/69735"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=69734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=69734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=69734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}