{"id":69676,"date":"2026-02-17T15:02:52","date_gmt":"2026-02-17T14:02:52","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2026\/02\/17\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\/"},"modified":"2026-02-17T15:02:52","modified_gmt":"2026-02-17T14:02:52","slug":"allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2026\/02\/17\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\/","title":{"rendered":"Allegri \u201cInutile parlare delle polemiche, anche il Como per la Champions\u201d"},"content":{"rendered":"<div>\n<p>CARNAGO (ITALPRESS) \u2013 A breve si entrer\u00e0 nel rush finale della stagione e il Milan, intanto, si prepara alla sfida contro il Como con la consapevolezza di non poter pi\u00f9 sbagliare. In conferenza stampa, il tecnico rossonero Massimiliano Allegri ha tracciato la linea in vista della gara in programma domani alle 20.45 a San Siro, recupero della 24esima giornata. <em><strong>\u201cSiamo agli ultimi tre mesi della stagione, dove si decider\u00e0 tutto. Non abbiamo pi\u00f9 margine di errore.<\/strong> Affrontiamo una squadra in piena lotta per la Champions. Dobbiamo esserci bravi a concentrarci e prepararci a questa gara.<strong> A parte Rabiot, squalificato, tutti gli altri stano bene. Saelemaekers sta bene, Pulisic vediamo\u201d.<\/strong><\/em><\/p>\n<p>Il tecnico rossonero ha poi invitato l\u2019ambiente a non disperdere energie sugli episodi arbitrali dell\u2019ultimo weekend, sottolineando come il focus debba restare esclusivamente sul campo e sul percorso della squadra.<strong><em> \u201cInutile parlare ancora della partita di sabato<\/em><\/strong> \u2013 dice riferendosi a Inter-Juventus -, <em>non possiamo disperdere energie nervose su quello che \u00e8 successo. Sono episodi che nel calcio ci sono sempre stati e ci saranno. <strong>Le persone di competenza stanno lavorando per migliorare l\u2019oggettivit\u00e0 del Var.<\/strong> Se serve professionalizzare gli arbitri? Il nostro campionato \u00e8 bellissimo queste cose ci sono sempre state. Togliergli un p\u00f2 di pressione sarebbe importante, poi l\u2019et\u00e0 loro si \u00e8 abbassata e non \u00e8 assolutamente facile. In Italia ci sono tante pressioni perch\u00e8 per una squadra italiana la qualificazione in Champions \u00e8 una questione economica di vita o di morte\u201d.<\/em><\/p>\n<p>Spazio anche alle condizioni dei singoli e al contributo dei giocatori offensivi nel finale di stagione.<em> \u201cCome sta Leao? Faccio fatica a dire la percentuale. Diciamo che sta bene. Ha fatto un buon allenamento anche ieri. E\u2019 un giocatore, cos\u00ec come sar\u00e0 Pulisic, che hanno avuto una stagione con problematiche fisiche ma hanno fatto gol importanti. Nella parte finale della stagione, quando cambier\u00e0 totalmente le partite e ci sar\u00e0 bisogno di giocatori tecnici come loro sicuramente faranno molto bene\u201d.<\/em><\/p>\n<p>La partita con il Como riporta alla grande<strong> diatriba tra risultatisti contro giochisti: <em>\u201cNon credo che ci sia un dibattito<\/em><\/strong> \u2013 ha sottolineato Allegri -. <em>Diciamo che il Como e Fabregas stanno facendo un lavoro importante, sono in lotta per la Champions. Hanno fatto un lavoro in cos\u00ec poco tempo molto buono che c\u2019\u00e8 solo da fare i complimenti. Poi ci sono momenti in cui giochi bene e momenti in cui giochi meno bene. Per noi Milan \u00e8 importante ottenere il risultato attraverso le prestazioni, che possono essere buone o meno buone, e abbiamo un obiettivo da raggiungere che \u00e8 un posto in Champions\u201d.<\/em><\/p>\n<p>Allegri, tornando alle polemiche post Inter-Juve, ha quindi ribadito la complessit\u00e0 del ruolo arbitrale in un calcio sempre pi\u00f9 veloce e fisico, sottolineando la necessit\u00e0 di un miglioramento progressivo del var. \u201c<em><strong>Il calcio \u00e8 diventato velocissimo, per l\u2019arbitro non \u00e8 facile.<\/strong> La velocit\u00e0 della palla, del gioco, la fisicit\u00e0 dei giocatori \u00e8 diversa da 30-40 anni fa. C\u2019\u00e8 da migliorare il var e trovare delle soluzioni, come sicuramente staranno facendo, e non \u00e8 che le trovi in un giorno. Cerchiamo di arrivare all\u2019oggettivit\u00e0. Secondo me una cosa che va assolutamente cambiata \u00e8 quando c\u2019\u00e8 un fuorigioco e l\u2019azione sfocia in calcio d\u2019angolo il calcio d\u2019angolo non pu\u00f2 essere assolutamente dato. Le simulazioni sono soggettive, sono a discrezione dell\u2019arbitro. E l\u00ec non ci si pu\u00f2 fare niente. Io faccio fatica a fare la formazione, figuriamoci se posso dire cosa deve fare il var. Il gioco del calcio non \u00e8 facile spiegarlo, non possiamo indottrinare tutti. E\u2019 bello perch\u00e8 il pi\u00f9 debole pu\u00f2 battere il pi\u00f9 forte. Quello che \u00e8 successo sabato dispiace a tutti, ma penso che i pi\u00f9 dispiaciuti siano i protagonisti\u201d.<\/em><\/p>\n<p>C\u2019\u00e8 chi fa un paragone con il celebre episodio del 2012, molto importante nella lotta scudetto tra Juve e Milan. \u201c<em>Il gol di Muntari era una roba oggettiva. E quello scudetto non l\u2019abbiamo perso per il gol di Muntari, l\u2019abbiamo perso dopo. Un episodio ti condiziona una partita, non un campionato. Quel gol era oggettivo, ma il titolo non l\u2019abbiamo perso per quell\u2019episodio l\u00ec. Per quanto riguarda sabato dobbiamo decidere se il Var pu\u00f2 intervenire\u2026Per il resto l\u2019oggettivit\u00e0 nel tennis \u00e8 se la pallina \u00e8 dentro o fuori. Lasciamoli lavorare, tra qualche anno magari funzioner\u00e0 sicuramente meglio. Indietro non si deve tornare, bisogna avere un pochino di pazienza\u201d<\/em>, ha concluso Allegri.<\/p>\n<p>Sul fronte campionato, l\u2019allenatore invita alla prudenza e alla concentrazione, evitando distrazioni e proiezioni premature. <em><strong>\u201cScudetto? Non siamo l\u2019unica squadra ancora in lotta, mancano ancora 13 giornate e pu\u00f2 succedere di tutto.<\/strong> Bisogna andare molto cauti, sia in testa che in fondo alla classifica. Noi non dobbiamo assolutamente avere dispendio di energie in quelli che sono fattori esterni. In questo momento ci vogliono i paraocchi\u201d<\/em>.<\/p>\n<p>\u2013 Foto Ipa Agency \u2013<br \/>\n(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>CARNAGO (ITALPRESS) \u2013 A breve si entrer\u00e0 nel rush finale della stagione e il Milan, intanto, si prepara alla sfida contro il Como con la consapevolezza di non poter pi\u00f9 sbagliare. In conferenza stampa, il tecnico rossonero Massimiliano Allegri ha tracciato la linea in vista della gara in programma domani alle 20.45 a San Siro, [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":69677,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-69676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Allegri \u201cInutile parlare delle polemiche, anche il Como per la Champions\u201d - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/17\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Allegri \u201cInutile parlare delle polemiche, anche il Como per la Champions\u201d - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"CARNAGO (ITALPRESS) \u2013 A breve si entrer\u00e0 nel rush finale della stagione e il Milan, intanto, si prepara alla sfida contro il Como con la consapevolezza di non poter pi\u00f9 sbagliare. In conferenza stampa, il tecnico rossonero Massimiliano Allegri ha tracciato la linea in vista della gara in programma domani alle 20.45 a San Siro, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2026\/02\/17\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-17T14:02:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/17\\\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/17\\\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Allegri \u201cInutile parlare delle polemiche, anche il Como per la Champions\u201d\",\"datePublished\":\"2026-02-17T14:02:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/17\\\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\\\/\"},\"wordCount\":795,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/17\\\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260217_0739.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/17\\\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/17\\\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\\\/\",\"name\":\"Allegri \u201cInutile parlare delle polemiche, anche il Como per la Champions\u201d - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/17\\\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/17\\\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260217_0739.jpg\",\"datePublished\":\"2026-02-17T14:02:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/17\\\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/17\\\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/17\\\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260217_0739.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20260217_0739.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2026\\\/02\\\/17\\\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Allegri \u201cInutile parlare delle polemiche, anche il Como per la Champions\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Allegri \u201cInutile parlare delle polemiche, anche il Como per la Champions\u201d - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2026\/02\/17\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\/","og_locale":"it_IT","og_type":"article","og_title":"Allegri \u201cInutile parlare delle polemiche, anche il Como per la Champions\u201d - Live Magazine","og_description":"CARNAGO (ITALPRESS) \u2013 A breve si entrer\u00e0 nel rush finale della stagione e il Milan, intanto, si prepara alla sfida contro il Como con la consapevolezza di non poter pi\u00f9 sbagliare. In conferenza stampa, il tecnico rossonero Massimiliano Allegri ha tracciato la linea in vista della gara in programma domani alle 20.45 a San Siro, [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/17\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2026-02-17T14:02:52+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/17\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/17\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Allegri \u201cInutile parlare delle polemiche, anche il Como per la Champions\u201d","datePublished":"2026-02-17T14:02:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/17\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\/"},"wordCount":795,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/17\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260217_0739.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/17\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\/","url":"https:\/\/www.livemag.it\/index.php\/2026\/02\/17\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\/","name":"Allegri \u201cInutile parlare delle polemiche, anche il Como per la Champions\u201d - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/17\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/17\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260217_0739.jpg","datePublished":"2026-02-17T14:02:52+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/17\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2026\/02\/17\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/17\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260217_0739.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260217_0739.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2026\/02\/17\/allegri-inutile-parlare-delle-polemiche-anche-il-como-per-la-champions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Allegri \u201cInutile parlare delle polemiche, anche il Como per la Champions\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2026\/02\/20260217_0739.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/69676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=69676"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/69676\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/69677"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=69676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=69676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=69676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}