{"id":66385,"date":"2025-12-30T03:02:31","date_gmt":"2025-12-30T02:02:31","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2025\/12\/30\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\/"},"modified":"2025-12-30T03:02:31","modified_gmt":"2025-12-30T02:02:31","slug":"la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2025\/12\/30\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\/","title":{"rendered":"La Roma torna alla vittoria, 3-1 al Genoa dell\u2019ex De Rossi"},"content":{"rendered":"<div>\n<p>ROMA (ITALPRESS) \u2013 La Roma non sbaglia e batte 3-1 il Genoa nel posticipo della 17esima giornata di Serie A. Succede tutto nel primo tempo all\u2019Olimpico, con i giallorossi che dilagano tra il 14\u2032 e il 31\u2032 grazie alle reti di Soul\u00e8, Kon\u00e8 e Ferguson. Seconda frazione in gestione per la squadra di Gasperini, che riparte alla grande dopo il ko di Torino contro la Juventus. Del classe 2006 Ekhator (87\u2032) il gol della bandiera dei rossobl\u00f9. Roma che sale in quarta posizione a 33 punti, mentre arriva la terza sconfitta di fila per i ragazzi di De Rossi (dopo Inter e Atalanta), che restano in 17esima piazza a quota 14. Nella prossima giornata i giallorossi voleranno a Bergamo per affrontare l\u2019Atalanta (3 gennaio ore 20.45), mentre il Genoa sar\u00e0 impegnato a Marassi nel pesante scontro salvezza casalingo con il Pisa (sempre sabato, ma alle 15).<br \/>\nAvvio di personalit\u00e0 della squadra di De Rossi, accolto da un boato e da diversi striscioni alla lettura delle formazioni, abile nello sporcare il fraseggio giallorosso nella met\u00e0 campo offensiva. Al primo vero squillo arriva il gol della Roma, che si porta in vantaggio con il solito mancino a giro di Soul\u00e8 (14\u2032). Subita la rete dell\u20191-0, il Genoa esce dalla partita e finisce per trovarsi sotto 2-0 al 19\u2032 con Kon\u00e8 che conclude una grande azione manovrata dei suoi. Al 31\u2032 Ferguson cala il tris approfittando di un errore in disimpegno di Malinovskyi. Nel finale di frazione Kon\u00e8 sfiora la doppietta colpendo un palo e Sommariva salva su Dybala nel recupero, evitando un passivo ancora pi\u00f9 pesante. Nel secondo tempo la Roma entra in gestione e lascia il pallino del gioco in mano ai rossobl\u00f9. Piccolo problema alla caviglia per Soul\u00e8, sostituito al 57\u2032 precauzionalmente da Gasperini, che lancia El Shaarawy. Tanti giovani in campo per De Rossi, che getta nella mischia gli Under 21 Ekhator e Fini per Vitinha e Malinovskyi. Al 72\u2032 bel destro al volo di Cristante, fermato in calcio d\u2019angolo da un reattivo Sommariva. Riposo per i big di Gasperini nell\u2019ultimo quarto d\u2019ora: fuori i diffidati Mancini e Cristante e dentro Ghilardi e Pisilli. Nel finale minuti anche per Dovbyk, al rientro in campo dopo oltre un mese di stop, e Rensch. All\u201987\u2019 il Genoa trova il gol della bandiera: punizione di Martin, sponda aerea di Colombo ed Ekhator, complice la deviazione di Pisilli, batte con un destro al volo l\u2019incolpevole Svilar.<br \/>\n\u2013 foto Ipa Agency \u2013<br \/>\n(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) \u2013 La Roma non sbaglia e batte 3-1 il Genoa nel posticipo della 17esima giornata di Serie A. Succede tutto nel primo tempo all\u2019Olimpico, con i giallorossi che dilagano tra il 14\u2032 e il 31\u2032 grazie alle reti di Soul\u00e8, Kon\u00e8 e Ferguson. Seconda frazione in gestione per la squadra di Gasperini, che [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":66386,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-66385","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Roma torna alla vittoria, 3-1 al Genoa dell\u2019ex De Rossi - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2025\/12\/30\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Roma torna alla vittoria, 3-1 al Genoa dell\u2019ex De Rossi - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"ROMA (ITALPRESS) \u2013 La Roma non sbaglia e batte 3-1 il Genoa nel posticipo della 17esima giornata di Serie A. Succede tutto nel primo tempo all\u2019Olimpico, con i giallorossi che dilagano tra il 14\u2032 e il 31\u2032 grazie alle reti di Soul\u00e8, Kon\u00e8 e Ferguson. Seconda frazione in gestione per la squadra di Gasperini, che [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2025\/12\/30\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-30T02:02:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/12\\\/30\\\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/12\\\/30\\\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"La Roma torna alla vittoria, 3-1 al Genoa dell\u2019ex De Rossi\",\"datePublished\":\"2025-12-30T02:02:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/12\\\/30\\\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\\\/\"},\"wordCount\":410,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/12\\\/30\\\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/20251229_2467.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/12\\\/30\\\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/12\\\/30\\\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\\\/\",\"name\":\"La Roma torna alla vittoria, 3-1 al Genoa dell\u2019ex De Rossi - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/12\\\/30\\\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/12\\\/30\\\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/20251229_2467.jpg\",\"datePublished\":\"2025-12-30T02:02:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/12\\\/30\\\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/12\\\/30\\\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/12\\\/30\\\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/20251229_2467.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/20251229_2467.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/12\\\/30\\\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Roma torna alla vittoria, 3-1 al Genoa dell\u2019ex De Rossi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Roma torna alla vittoria, 3-1 al Genoa dell\u2019ex De Rossi - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2025\/12\/30\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\/","og_locale":"it_IT","og_type":"article","og_title":"La Roma torna alla vittoria, 3-1 al Genoa dell\u2019ex De Rossi - Live Magazine","og_description":"ROMA (ITALPRESS) \u2013 La Roma non sbaglia e batte 3-1 il Genoa nel posticipo della 17esima giornata di Serie A. Succede tutto nel primo tempo all\u2019Olimpico, con i giallorossi che dilagano tra il 14\u2032 e il 31\u2032 grazie alle reti di Soul\u00e8, Kon\u00e8 e Ferguson. Seconda frazione in gestione per la squadra di Gasperini, che [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2025\/12\/30\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2025-12-30T02:02:31+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2025\/12\/30\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/12\/30\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"La Roma torna alla vittoria, 3-1 al Genoa dell\u2019ex De Rossi","datePublished":"2025-12-30T02:02:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/12\/30\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\/"},"wordCount":410,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/12\/30\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/12\/20251229_2467.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2025\/12\/30\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\/","url":"https:\/\/www.livemag.it\/index.php\/2025\/12\/30\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\/","name":"La Roma torna alla vittoria, 3-1 al Genoa dell\u2019ex De Rossi - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/12\/30\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/12\/30\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/12\/20251229_2467.jpg","datePublished":"2025-12-30T02:02:31+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/12\/30\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2025\/12\/30\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2025\/12\/30\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/12\/20251229_2467.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/12\/20251229_2467.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2025\/12\/30\/la-roma-torna-alla-vittoria-3-1-al-genoa-dellex-de-rossi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"La Roma torna alla vittoria, 3-1 al Genoa dell\u2019ex De Rossi"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/12\/20251229_2467.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/66385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=66385"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/66385\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/66386"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=66385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=66385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=66385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}