{"id":53825,"date":"2025-06-24T21:02:49","date_gmt":"2025-06-24T19:02:49","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2025\/06\/24\/pnrr-foti-oltre-135-mila-progetti-ultimati\/"},"modified":"2025-06-24T21:02:49","modified_gmt":"2025-06-24T19:02:49","slug":"pnrr-foti-oltre-135-mila-progetti-ultimati","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2025\/06\/24\/pnrr-foti-oltre-135-mila-progetti-ultimati\/","title":{"rendered":"Pnrr, Foti \u201cOltre 135 mila progetti ultimati\u201d"},"content":{"rendered":"<div>\n<p>ROMA (ITALPRESS) \u2013 Si \u00e8 svolta a Palazzo Chigi la Cabina di regia <strong>PNRR<\/strong>, convocata e presieduta dal ministro per gli Affari europei, le politiche di coesione e il PNRR, <strong>Tommaso Foti<\/strong>, alla presenza dei Ministri e dei sottosegretari preposti, oltre che dell\u2019ANCI, dell\u2019UPI e della Conferenza delle Regioni e delle Province autonome, per la verifica del conseguimento dei quaranta obiettivi connessi all\u2019ottava rata del Piano Nazionale di Ripresa e Resilenza per un importo pari a 12,8 miliardi di euro.<\/p>\n<p>La Cabina di regia, al termine di una circostanziata verifica, ha preso atto dello stato di attuazione delle 12 milestone e dei 28 target previsti nell\u2019ottava rata, \u201ctra i quali figurano riforme e investimenti strategici per la crescita della Nazione che coinvolgono tredici Amministrazioni titolari\u201d.<\/p>\n<p><em>\u201cTra gli interventi pi\u00f9 significativi dell\u2019ottava rata<\/em> \u2013 afferma il ministro <strong>Foti<\/strong> \u2013 <em>1.400 km di infrastrutture ferroviarie sono state dotate del sistema europeo di gestione del traffico ferroviario, il 90% della superficie delle regioni meridionali \u00e8 stato coperto da un sistema avanzato e integrato di monitoraggio e previsione per identificare i rischi idrogeologici, sono stati realizzati interventi per la tutela degli habitat marini e per l\u2019osservazione delle coste, \u00e8 stato avviato l\u2019iter per l\u2019efficientamento energetico dell\u2019edilizia residenziale pubblica, in campo universitario sono stati finanziati 5.000 Progetti di Ricerca di Interesse Nazionale (PRIN), sono stati assunti circa 2.300 nuovi ricercatori e assegnate oltre 550 borse di ricerca, nel comparto Salute sono stati finanziati progetti di ricerca su malattie rare e altamente invalidanti e tumori rari\u201d.<\/em><\/p>\n<p><em>\u201cEd ancora<\/em> \u2013 prosegue <strong>Foti<\/strong> \u2013 <em>la digitalizzazione della Guardia di Finanza con innovativi sistemi informativi per contrastare la criminalit\u00e0 economica, in ambito scolastico sono stati erogati oltre 1.000 corsi linguistici e metodologici ai docenti, attivati in pi\u00f9 di 8.000 scuole progetti per aggiornare l\u2019offerta scolastica ed orientare gi studenti verso le competenze STEM, mentre, in ambito culturale, sono stati portati a compimento progetti di valorizzazione culturale e turistica attraverso il sostegno a circa 2.000 piccole e medie imprese, oltre alla riqualificazione di circa 50 parchi e giardini storici\u201d.<\/em><\/p>\n<p>A questi interventi, inseriti nella ottava rata, si aggiungono anche diverse importanti riforme, tra cui, a titolo esemplificativo, la decisiva riduzione dei ritardi di pagamento delle Amministrazioni centrali e locali, delle Regioni, delle Province autonome e degli enti del Servizio Sanitario Nazionale.<\/p>\n<p><em>\u201cCon l\u2019imminente incasso della settima rata, pari a 18,3 miliardi di euro<\/em> \u2013 continua il Ministro \u2013 <em>confermeremo il primato europeo del Piano italiano, con 140 miliardi di euro ricevuti, corrispondenti al 72% della dotazione complessiva. Nell\u2019anno che ci separa dalla scadenza del PNRR, anche a seguito del via libera dell\u2019Ecofin alla revisione tecnica, saremo impegnati nel proseguire con la massima determinazione per investire le risorse ancora disponibili sia attraverso l\u2019allineamento del Piano con le nuove esigenze dell\u2019Italia reale, sia prevedendo un collegamento costruttivo con le politiche di coesione, che consentiranno di dare maggiore impulso alla nostra economia, gi\u00e0 solida e resiliente\u201d.<\/em><\/p>\n<p>Il ministro <strong>Foti<\/strong>, al termine della Cabina di regia, conclude ricordando <em>\u201cche gli oltre 135.000 progetti ultimati e i 140.000 in corso di realizzazione, di cui pi\u00f9 di 25.000 in fase di conclusione, evidenziano il positivo avanzamento del PNRR, attraverso le riforme e gli investimenti previsti dal Governo sempre pi\u00f9 decisivi per il cambio di paradigma voluto dal Presidente Meloni e per dare continuit\u00e0 alla transizione in corso, passando dalle politiche meramente assistenziali a quelle attive per lo sviluppo e l\u2019occupazione\u201d.<\/em><\/p>\n<p>\u2013 Foto IPA Agency \u2013<\/p>\n<p>(ITALPRESS)<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) \u2013 Si \u00e8 svolta a Palazzo Chigi la Cabina di regia PNRR, convocata e presieduta dal ministro per gli Affari europei, le politiche di coesione e il PNRR, Tommaso Foti, alla presenza dei Ministri e dei sottosegretari preposti, oltre che dell\u2019ANCI, dell\u2019UPI e della Conferenza delle Regioni e delle Province autonome, per la [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":53826,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1129],"tags":[],"class_list":["post-53825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pnrr, Foti \u201cOltre 135 mila progetti ultimati\u201d - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2025\/06\/24\/pnrr-foti-oltre-135-mila-progetti-ultimati\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pnrr, Foti \u201cOltre 135 mila progetti ultimati\u201d - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"ROMA (ITALPRESS) \u2013 Si \u00e8 svolta a Palazzo Chigi la Cabina di regia PNRR, convocata e presieduta dal ministro per gli Affari europei, le politiche di coesione e il PNRR, Tommaso Foti, alla presenza dei Ministri e dei sottosegretari preposti, oltre che dell\u2019ANCI, dell\u2019UPI e della Conferenza delle Regioni e delle Province autonome, per la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2025\/06\/24\/pnrr-foti-oltre-135-mila-progetti-ultimati\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-24T19:02:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/06\\\/24\\\/pnrr-foti-oltre-135-mila-progetti-ultimati\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/06\\\/24\\\/pnrr-foti-oltre-135-mila-progetti-ultimati\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Pnrr, Foti \u201cOltre 135 mila progetti ultimati\u201d\",\"datePublished\":\"2025-06-24T19:02:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/06\\\/24\\\/pnrr-foti-oltre-135-mila-progetti-ultimati\\\/\"},\"wordCount\":562,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/06\\\/24\\\/pnrr-foti-oltre-135-mila-progetti-ultimati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/20250624_2100.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/06\\\/24\\\/pnrr-foti-oltre-135-mila-progetti-ultimati\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/06\\\/24\\\/pnrr-foti-oltre-135-mila-progetti-ultimati\\\/\",\"name\":\"Pnrr, Foti \u201cOltre 135 mila progetti ultimati\u201d - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/06\\\/24\\\/pnrr-foti-oltre-135-mila-progetti-ultimati\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/06\\\/24\\\/pnrr-foti-oltre-135-mila-progetti-ultimati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/20250624_2100.jpg\",\"datePublished\":\"2025-06-24T19:02:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/06\\\/24\\\/pnrr-foti-oltre-135-mila-progetti-ultimati\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/06\\\/24\\\/pnrr-foti-oltre-135-mila-progetti-ultimati\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/06\\\/24\\\/pnrr-foti-oltre-135-mila-progetti-ultimati\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/20250624_2100.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/20250624_2100.jpg\",\"width\":1200,\"height\":799},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/06\\\/24\\\/pnrr-foti-oltre-135-mila-progetti-ultimati\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pnrr, Foti \u201cOltre 135 mila progetti ultimati\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pnrr, Foti \u201cOltre 135 mila progetti ultimati\u201d - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2025\/06\/24\/pnrr-foti-oltre-135-mila-progetti-ultimati\/","og_locale":"it_IT","og_type":"article","og_title":"Pnrr, Foti \u201cOltre 135 mila progetti ultimati\u201d - Live Magazine","og_description":"ROMA (ITALPRESS) \u2013 Si \u00e8 svolta a Palazzo Chigi la Cabina di regia PNRR, convocata e presieduta dal ministro per gli Affari europei, le politiche di coesione e il PNRR, Tommaso Foti, alla presenza dei Ministri e dei sottosegretari preposti, oltre che dell\u2019ANCI, dell\u2019UPI e della Conferenza delle Regioni e delle Province autonome, per la [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2025\/06\/24\/pnrr-foti-oltre-135-mila-progetti-ultimati\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2025-06-24T19:02:49+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2025\/06\/24\/pnrr-foti-oltre-135-mila-progetti-ultimati\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/06\/24\/pnrr-foti-oltre-135-mila-progetti-ultimati\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Pnrr, Foti \u201cOltre 135 mila progetti ultimati\u201d","datePublished":"2025-06-24T19:02:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/06\/24\/pnrr-foti-oltre-135-mila-progetti-ultimati\/"},"wordCount":562,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/06\/24\/pnrr-foti-oltre-135-mila-progetti-ultimati\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/06\/20250624_2100.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2025\/06\/24\/pnrr-foti-oltre-135-mila-progetti-ultimati\/","url":"https:\/\/www.livemag.it\/index.php\/2025\/06\/24\/pnrr-foti-oltre-135-mila-progetti-ultimati\/","name":"Pnrr, Foti \u201cOltre 135 mila progetti ultimati\u201d - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/06\/24\/pnrr-foti-oltre-135-mila-progetti-ultimati\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/06\/24\/pnrr-foti-oltre-135-mila-progetti-ultimati\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/06\/20250624_2100.jpg","datePublished":"2025-06-24T19:02:49+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/06\/24\/pnrr-foti-oltre-135-mila-progetti-ultimati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2025\/06\/24\/pnrr-foti-oltre-135-mila-progetti-ultimati\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2025\/06\/24\/pnrr-foti-oltre-135-mila-progetti-ultimati\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/06\/20250624_2100.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/06\/20250624_2100.jpg","width":1200,"height":799},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2025\/06\/24\/pnrr-foti-oltre-135-mila-progetti-ultimati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Pnrr, Foti \u201cOltre 135 mila progetti ultimati\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/06\/20250624_2100.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/53825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=53825"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/53825\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/53826"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=53825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=53825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=53825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}