{"id":49643,"date":"2025-04-24T18:02:40","date_gmt":"2025-04-24T16:02:40","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2025\/04\/24\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\/"},"modified":"2025-04-24T18:02:40","modified_gmt":"2025-04-24T16:02:40","slug":"nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2025\/04\/24\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\/","title":{"rendered":"<div>Nuovo Parco della salute a Torino, Cirio &#8220;Lavori pronti entro il 2031&#8221;<\/div>"},"content":{"rendered":"<p>    <video-js id=\"videojs6a03d3fd42388\" class=\"vjs-big-play-centered\" controls preload=\"auto\" playsinline data-setup='{\"fluid\": true}'>\r\n        <source src=\"https:\/\/video.italpress.com\/play\/mp4\/video\/Ao0z\" type=\"video\/mp4\" \/>\r\n    <\/video-js>\r\n           <br \/>\n<\/p>\n<div> TORINO (ITALPRESS) &#8211; &#8220;Questo \u00e8 il giorno da cui si parte, l&#8217;impresa vincitrice \u00e8 incaricata e operativa e da qui parte il cronoprogramma. Entro il prossimo novembre si concluder\u00e0 la Conferenza dei servizi, per trasformare il progetto definitivo in esecutivo, da novembre serviranno otto mesi per la presentazione del progetto esecutivo che verr\u00e0 realizzato. L&#8217;inizio dei lavori previsto entro il 2026, per arrivare al 2031 con il nuovo ospedale del Piemonte, che sar\u00e0 fra i pi\u00f9 importanti in Italia&#8221;. Cos\u00ec il presidente della Regione Piemonte, Alberto Cirio, oggi a Torino per la firma del contratto di affidamento per la progettazione, costruzione e gestione del futuro Parco della Salute.<\/p>\n<p>xn3\/trl\/mca2<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>TORINO (ITALPRESS) &#8211; &#8220;Questo \u00e8 il giorno da cui si parte, l&#8217;impresa vincitrice \u00e8 incaricata e operativa e da qui parte il cronoprogramma. Entro il prossimo novembre si concluder\u00e0 la Conferenza dei servizi, per trasformare il progetto definitivo in esecutivo, da novembre serviranno otto mesi per la presentazione del progetto esecutivo che verr\u00e0 realizzato. L&#8217;inizio [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":49644,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1171],"tags":[],"class_list":["post-49643","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-video","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuovo Parco della salute a Torino, Cirio &quot;Lavori pronti entro il 2031&quot; - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2025\/04\/24\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuovo Parco della salute a Torino, Cirio &quot;Lavori pronti entro il 2031&quot; - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"TORINO (ITALPRESS) &#8211; &#8220;Questo \u00e8 il giorno da cui si parte, l&#8217;impresa vincitrice \u00e8 incaricata e operativa e da qui parte il cronoprogramma. Entro il prossimo novembre si concluder\u00e0 la Conferenza dei servizi, per trasformare il progetto definitivo in esecutivo, da novembre serviranno otto mesi per la presentazione del progetto esecutivo che verr\u00e0 realizzato. L&#8217;inizio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2025\/04\/24\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-24T16:02:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/04\\\/24\\\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/04\\\/24\\\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Nuovo Parco della salute a Torino, Cirio &#8220;Lavori pronti entro il 2031&#8221;\",\"datePublished\":\"2025-04-24T16:02:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/04\\\/24\\\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\\\/\"},\"wordCount\":132,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/04\\\/24\\\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Ao0z.jpg\",\"articleSection\":[\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/04\\\/24\\\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/04\\\/24\\\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\\\/\",\"name\":\"Nuovo Parco della salute a Torino, Cirio \\\"Lavori pronti entro il 2031\\\" - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/04\\\/24\\\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/04\\\/24\\\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Ao0z.jpg\",\"datePublished\":\"2025-04-24T16:02:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/04\\\/24\\\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/04\\\/24\\\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/04\\\/24\\\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Ao0z.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Ao0z.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/04\\\/24\\\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuovo Parco della salute a Torino, Cirio &#8220;Lavori pronti entro il 2031&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuovo Parco della salute a Torino, Cirio \"Lavori pronti entro il 2031\" - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2025\/04\/24\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\/","og_locale":"it_IT","og_type":"article","og_title":"Nuovo Parco della salute a Torino, Cirio \"Lavori pronti entro il 2031\" - Live Magazine","og_description":"TORINO (ITALPRESS) &#8211; &#8220;Questo \u00e8 il giorno da cui si parte, l&#8217;impresa vincitrice \u00e8 incaricata e operativa e da qui parte il cronoprogramma. Entro il prossimo novembre si concluder\u00e0 la Conferenza dei servizi, per trasformare il progetto definitivo in esecutivo, da novembre serviranno otto mesi per la presentazione del progetto esecutivo che verr\u00e0 realizzato. L&#8217;inizio [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2025\/04\/24\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2025-04-24T16:02:40+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2025\/04\/24\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/04\/24\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Nuovo Parco della salute a Torino, Cirio &#8220;Lavori pronti entro il 2031&#8221;","datePublished":"2025-04-24T16:02:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/04\/24\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\/"},"wordCount":132,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/04\/24\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/04\/Ao0z.jpg","articleSection":["Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2025\/04\/24\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\/","url":"https:\/\/www.livemag.it\/index.php\/2025\/04\/24\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\/","name":"Nuovo Parco della salute a Torino, Cirio \"Lavori pronti entro il 2031\" - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/04\/24\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/04\/24\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/04\/Ao0z.jpg","datePublished":"2025-04-24T16:02:40+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/04\/24\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2025\/04\/24\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2025\/04\/24\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/04\/Ao0z.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/04\/Ao0z.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2025\/04\/24\/nuovo-parco-della-salute-a-torino-cirio-lavori-pronti-entro-il-2031\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Nuovo Parco della salute a Torino, Cirio &#8220;Lavori pronti entro il 2031&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/04\/Ao0z.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/49643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=49643"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/49643\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/49644"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=49643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=49643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=49643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}