{"id":46093,"date":"2025-03-06T18:02:15","date_gmt":"2025-03-06T17:02:15","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2025\/03\/06\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\/"},"modified":"2025-03-06T18:02:15","modified_gmt":"2025-03-06T17:02:15","slug":"ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2025\/03\/06\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\/","title":{"rendered":"<div>Ue, Manfredi &#8220;A breve nostre proposte su agenda per le citt\u00e0&#8221;<\/div>"},"content":{"rendered":"<p>    <video-js id=\"videojs6a0451a9d35d0\" class=\"vjs-big-play-centered\" controls preload=\"auto\" playsinline data-setup='{\"fluid\": true}'>\r\n        <source src=\"https:\/\/video.italpress.com\/play\/mp4\/video\/m6ZR\" type=\"video\/mp4\" \/>\r\n    <\/video-js>\r\n           <br \/>\n<\/p>\n<div> ROMA (ITALPRESS) &#8211;  &#8220;\u00c8 stato un incontro molto positivo, abbiamo manifestato la massima disponibilit\u00e0 alla collaborazione. Ci sar\u00e0 un altro incontro a Torino in aprile dove cominceremo a presentare le nostre proposte per contribuire alla costruzione dell&#8217;Agenda per le citt\u00e0. Sar\u00e0 una agenda su tre livelli che guarda alle citt\u00e0 metropolitane, alle citt\u00e0 medie e ai piccoli Comuni e le aree interne. Noi dobbiamo avere un maggiore collegamento con le realt\u00e0 territoriali e vogliamo che l&#8217;esperienza del Pnrr, che \u00e8 stata molto positiva, venga riportata anche nella futura politica di coesione&#8221;. Cos\u00ec il presidente dell&#8217;Anci, Gaetano Manfredi, al termine dell&#8217;incontro con il vicepresidente esecutivo e Commissario europeo per la Politica regionale e di Coesione, Raffaele Fitto.<br \/>\nxb1\/ads\/mca2<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) &#8211; &#8220;\u00c8 stato un incontro molto positivo, abbiamo manifestato la massima disponibilit\u00e0 alla collaborazione. Ci sar\u00e0 un altro incontro a Torino in aprile dove cominceremo a presentare le nostre proposte per contribuire alla costruzione dell&#8217;Agenda per le citt\u00e0. Sar\u00e0 una agenda su tre livelli che guarda alle citt\u00e0 metropolitane, alle citt\u00e0 medie e [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":46094,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1171],"tags":[],"class_list":["post-46093","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-video","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ue, Manfredi &quot;A breve nostre proposte su agenda per le citt\u00e0&quot; - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2025\/03\/06\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ue, Manfredi &quot;A breve nostre proposte su agenda per le citt\u00e0&quot; - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"ROMA (ITALPRESS) &#8211; &#8220;\u00c8 stato un incontro molto positivo, abbiamo manifestato la massima disponibilit\u00e0 alla collaborazione. Ci sar\u00e0 un altro incontro a Torino in aprile dove cominceremo a presentare le nostre proposte per contribuire alla costruzione dell&#8217;Agenda per le citt\u00e0. Sar\u00e0 una agenda su tre livelli che guarda alle citt\u00e0 metropolitane, alle citt\u00e0 medie e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2025\/03\/06\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-06T17:02:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/03\\\/06\\\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/03\\\/06\\\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Ue, Manfredi &#8220;A breve nostre proposte su agenda per le citt\u00e0&#8221;\",\"datePublished\":\"2025-03-06T17:02:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/03\\\/06\\\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\\\/\"},\"wordCount\":144,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/03\\\/06\\\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/m6ZR.jpg\",\"articleSection\":[\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/03\\\/06\\\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/03\\\/06\\\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\\\/\",\"name\":\"Ue, Manfredi \\\"A breve nostre proposte su agenda per le citt\u00e0\\\" - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/03\\\/06\\\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/03\\\/06\\\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/m6ZR.jpg\",\"datePublished\":\"2025-03-06T17:02:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/03\\\/06\\\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/03\\\/06\\\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/03\\\/06\\\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/m6ZR.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/m6ZR.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/03\\\/06\\\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ue, Manfredi &#8220;A breve nostre proposte su agenda per le citt\u00e0&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ue, Manfredi \"A breve nostre proposte su agenda per le citt\u00e0\" - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2025\/03\/06\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\/","og_locale":"it_IT","og_type":"article","og_title":"Ue, Manfredi \"A breve nostre proposte su agenda per le citt\u00e0\" - Live Magazine","og_description":"ROMA (ITALPRESS) &#8211; &#8220;\u00c8 stato un incontro molto positivo, abbiamo manifestato la massima disponibilit\u00e0 alla collaborazione. Ci sar\u00e0 un altro incontro a Torino in aprile dove cominceremo a presentare le nostre proposte per contribuire alla costruzione dell&#8217;Agenda per le citt\u00e0. Sar\u00e0 una agenda su tre livelli che guarda alle citt\u00e0 metropolitane, alle citt\u00e0 medie e [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2025\/03\/06\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2025-03-06T17:02:15+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2025\/03\/06\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/03\/06\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Ue, Manfredi &#8220;A breve nostre proposte su agenda per le citt\u00e0&#8221;","datePublished":"2025-03-06T17:02:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/03\/06\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\/"},"wordCount":144,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/03\/06\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/03\/m6ZR.jpg","articleSection":["Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2025\/03\/06\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\/","url":"https:\/\/www.livemag.it\/index.php\/2025\/03\/06\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\/","name":"Ue, Manfredi \"A breve nostre proposte su agenda per le citt\u00e0\" - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/03\/06\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/03\/06\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/03\/m6ZR.jpg","datePublished":"2025-03-06T17:02:15+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/03\/06\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2025\/03\/06\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2025\/03\/06\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/03\/m6ZR.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/03\/m6ZR.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2025\/03\/06\/ue-manfredi-a-breve-nostre-proposte-su-agenda-per-le-citta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Ue, Manfredi &#8220;A breve nostre proposte su agenda per le citt\u00e0&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/03\/m6ZR.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/46093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=46093"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/46093\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/46094"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=46093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=46093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=46093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}