{"id":45601,"date":"2025-02-28T15:01:53","date_gmt":"2025-02-28T14:01:53","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\/"},"modified":"2025-02-28T15:01:53","modified_gmt":"2025-02-28T14:01:53","slug":"colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\/","title":{"rendered":"Colazione, rito irrinunciabile: campagna Kellogg\u2019s celebra i risvegli"},"content":{"rendered":"<div>\n<p>MILANO (ITALPRESS) \u2013 Ogni mattina \u00e8 un nuovo inizio, un rituale fatto di abitudini consolidate e piccoli gesti che preparano al resto della giornata. Tra chi ama assaporare un caff\u00e8 appena fatto e chi cerca ogni scusa per rimanere qualche minuto in pi\u00f9 sotto le coperte, il risveglio racconta molto del nostro rapporto con il tempo e con noi stessi e ogni risveglio \u00e8 unico nel suo genere.<br \/>La ricerca condotta da Kellogg\u2019s e OnePoll (su un campione composto da 2.000 individui rappresentativo della popolazione italiana 18+), infatti, ha fotografato i mille volti delle nostre mattine, svelando che le routine di inizio giornata presentano un\u2019ampia variet\u00e0 di preferenze e rituali. La colazione rappresenta un appuntamento irrinunciabile per iniziare la giornata con il piede giusto, con il 70% dei rispondenti che dedica in media 15 minuti al primo pasto della giornata: il 46% degli italiani inizia la giornata con un momento dedicato a s\u00e8, sorseggiando un caff\u00e8 o gustando la propria colazione preferita, con quasi l\u201985% che fa colazione a casa, spesso in solitudine (55%). Tra chi sceglie di mangiare da solo, quasi la met\u00e0 (46%) lo fa a causa di routine diverse rispetto a quelle degli altri membri della famiglia, mentre il 24% vede in questo momento un\u2019occasione per prendersi cura di s\u00e8. Guardando i gusti, il 36% degli intervistati fa una colazione tradizionale ogni mattina: il caff\u00e8 si conferma la bevanda preferita della colazione, scelto dal 54% degli italiani, molto apprezzati anche latte (34%) e cereali (21%).<br \/>Ma la colazione non \u00e8 solo gusto, \u00e8 anche un\u2019esperienza emotiva. Per il 35% rappresenta un momento di calma e relax, per il 31% una carica di energia per affrontare la giornata, mentre il 28% la vive come un momento dedicato a s\u00e8. Anche se il multitasking \u00e8 presente \u2013 il 18% usa questo momento per controllare e-mail personali o guardare social media \u2013 molti lo considerano un\u2019opportunit\u00e0 per ritrovare equilibrio e concentrazione: pi\u00f9 della met\u00e0 degli italiani (51%), infatti, dichiara di non lavorare mai durante la colazione e il 30% afferma di farlo raramente o a volte.<br \/>Nei fine settimana, la colazione si trasforma in un vero e proprio rituale per quasi la met\u00e0 degli intervistati (49%), che dedica pi\u00f9 tempo a questo momento: circa il 40% celebra momenti importanti organizzando una colazione speciale o un \u201cbrunch\u201d, confermando l\u2019importanza sociale e affettiva di questo momento.<br \/>E\u2019 in questo contesto che si inserisce la nuova campagna dei cereali Kellogg\u2019s, \u201cQualunque sia il tuo risveglio. Kellogg\u2019s, con te ogni mattina\u201d, che vede protagonista il leggendario Gallo Cornelius. Icona dei cereali Kellogg\u2019s e compagno di colazione dal 1906, Cornelius debutta sul grande schermo con un look completamente rinnovato. Protagonista della nuova campagna, Cornelius si mostra per la prima volta sul grande schermo in un formato 3D, camminando per le strade della citt\u00e0 con il suo carisma originale ma sfoggiando una nuova energia per connettersi alle nuove generazioni e alle differenti routine di risveglio. Sul ritmo di una colonna sonora hip-hop ispirata agli anni \u201990, Cornelius accompagna le persone intente a iniziare la giornata a modo proprio: da chi va a correre all\u2019alba, a chi fa colazione con la famiglia prima di una giornata ricca di impegni, a chi si gode momenti di tranquillit\u00e0 per s\u00e8. Ed \u00e8 proprio la variet\u00e0 e la libert\u00e0 dei rituali mattutini che Kellogg\u2019s vuole celebrare con la nuova campagna.<br \/>Secondo la ricerca condotta da Kellogg\u2019s con OnePoll, nonostante il 66% degli italiani si definisca una persona mattiniera, il momento del risveglio resta per molti una piccola sfida quotidiana. Il 48% degli intervistati ammette, infatti, di posticipare la sveglia almeno una volta e molti preferiscono rinunciare ad alcuni rituali mattutini \u2013 come guardare la TV (36%), sistemare la camera e rifare il letto (34%), allenarsi (25%) o leggere le ultime notizie (25%) \u2013 pur di dormire qualche minuto in pi\u00f9.<br \/>Dalla ricerca emerge che sostituire il tradizionale suono della sveglia con il richiamo di un animale potrebbe essere la chiave per un risveglio pi\u00f9 energico: il 22% degli italiani, infatti, preferirebbe il canto del gallo al classico \u201cbip\u201d della propria sveglia. Ed \u00e8 proprio con il suo inconfondibile \u201cchicchirich\u00ec\u201d che il Gallo Cornelius risveglia la citt\u00e0 nello spot TV della nuova campagna Kellogg\u2019s, gi\u00e0 in onda in Italia. La campagna multicanale prosegue anche sui social \u2013 dove Cornelius si unisce ai protagonisti nei loro modi unici di affrontare il risveglio \u2013 e arriver\u00e0 nelle strade di alcune citt\u00e0 italiane con attivit\u00e0 OOH e FOOH, per approdare nei punti vendita.<br \/>\u201cLa nuova campagna di comunicazione \u2018Con Te Ogni Mattin\u00e0 dei nostri iconici cereali Kellogg\u2019s celebra la colazione come un momento profondamente personale: ogni risveglio \u00e8 unico\u201d, dichiara Elisa Tudino, Activation Brand Lead Italia di Kellanova. \u201cOgni alba rappresenta un nuovo inizio e, dal 1906, accompagniamo i nostri consumatori in questo rito quotidiano: c\u2019\u00e8 chi lo affronta di corsa e chi lo condivide con le persone che pi\u00f9 amano. Kellogg\u2019s \u00e8 il compagno di colazione che unisce generazioni, esaltando l\u2019unicit\u00e0 di ogni mattina e il gusto di un nuovo giorno\u201d.<br \/>Ma non solo: Cornelius \u00e8 uscito dal grande schermo. A inizio febbraio ha lasciato la sua inconfondibile impronta a Milano. In alcuni dei luoghi simbolo del capoluogo meneghino, \u00e8 stato possibile seguire le sue tracce, realizzate con graffiti sostenibili, e iniziare la giornata con un assaggio dei pi\u00f9 amati cereali, partecipando a una colazione speciale presso la sede di God Save The Food di Via Tortona 34.<br \/>\u2013 foto ufficio stampa Kellogg\u2019s \u2013 <br \/>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>MILANO (ITALPRESS) \u2013 Ogni mattina \u00e8 un nuovo inizio, un rituale fatto di abitudini consolidate e piccoli gesti che preparano al resto della giornata. Tra chi ama assaporare un caff\u00e8 appena fatto e chi cerca ogni scusa per rimanere qualche minuto in pi\u00f9 sotto le coperte, il risveglio racconta molto del nostro rapporto con il [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":45602,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-45601","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colazione, rito irrinunciabile: campagna Kellogg\u2019s celebra i risvegli - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colazione, rito irrinunciabile: campagna Kellogg\u2019s celebra i risvegli - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"MILANO (ITALPRESS) \u2013 Ogni mattina \u00e8 un nuovo inizio, un rituale fatto di abitudini consolidate e piccoli gesti che preparano al resto della giornata. Tra chi ama assaporare un caff\u00e8 appena fatto e chi cerca ogni scusa per rimanere qualche minuto in pi\u00f9 sotto le coperte, il risveglio racconta molto del nostro rapporto con il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-28T14:01:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Colazione, rito irrinunciabile: campagna Kellogg\u2019s celebra i risvegli\",\"datePublished\":\"2025-02-28T14:01:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\\\/\"},\"wordCount\":887,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20250228_0268.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\\\/\",\"name\":\"Colazione, rito irrinunciabile: campagna Kellogg\u2019s celebra i risvegli - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20250228_0268.jpg\",\"datePublished\":\"2025-02-28T14:01:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20250228_0268.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20250228_0268.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colazione, rito irrinunciabile: campagna Kellogg\u2019s celebra i risvegli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colazione, rito irrinunciabile: campagna Kellogg\u2019s celebra i risvegli - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\/","og_locale":"it_IT","og_type":"article","og_title":"Colazione, rito irrinunciabile: campagna Kellogg\u2019s celebra i risvegli - Live Magazine","og_description":"MILANO (ITALPRESS) \u2013 Ogni mattina \u00e8 un nuovo inizio, un rituale fatto di abitudini consolidate e piccoli gesti che preparano al resto della giornata. Tra chi ama assaporare un caff\u00e8 appena fatto e chi cerca ogni scusa per rimanere qualche minuto in pi\u00f9 sotto le coperte, il risveglio racconta molto del nostro rapporto con il [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2025-02-28T14:01:53+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Colazione, rito irrinunciabile: campagna Kellogg\u2019s celebra i risvegli","datePublished":"2025-02-28T14:01:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\/"},"wordCount":887,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/02\/20250228_0268.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\/","url":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\/","name":"Colazione, rito irrinunciabile: campagna Kellogg\u2019s celebra i risvegli - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/02\/20250228_0268.jpg","datePublished":"2025-02-28T14:01:53+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/02\/20250228_0268.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/02\/20250228_0268.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/colazione-rito-irrinunciabile-campagna-kelloggs-celebra-i-risvegli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Colazione, rito irrinunciabile: campagna Kellogg\u2019s celebra i risvegli"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/02\/20250228_0268.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/45601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=45601"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/45601\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/45602"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=45601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=45601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=45601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}