{"id":45595,"date":"2025-02-28T15:01:40","date_gmt":"2025-02-28T14:01:40","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\/"},"modified":"2025-02-28T15:01:40","modified_gmt":"2025-02-28T14:01:40","slug":"pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\/","title":{"rendered":"<div>Pecoraro Scanio &#8220;Sfida Ecodigital da Bari, stop emigrazione giovani&#8221;<\/div>"},"content":{"rendered":"<p>    <video-js id=\"videojs6a985a59f2316\" class=\"vjs-big-play-centered\" controls preload=\"auto\" playsinline data-setup='{\"fluid\": true}'>\r\n        <source src=\"https:\/\/video.italpress.com\/play\/mp4\/video\/W1Zn\" type=\"video\/mp4\" \/>\r\n    <\/video-js>\r\n           <br \/>\n<\/p>\n<div> BARI (ITALPRESS) &#8211; Il turismo del futuro deve essere ecologico e digitale, capace di generare benessere diffuso senza impattare negativamente sui territori. \u00c8 questo il messaggio lanciato da Alfonso Pecoraro Scanio, Presidente della Fondazione UniVerde e promotore della Rete EcoDigital, in occasione della BTM &#8211; Business Tourism Management, la fiera del turismo in corso in Puglia. \u201cIl turismo non deve essere concentrato in tempi brevi e in aree limitate, trasformandosi in un fenomeno di distruzione ambientale e sociale. Al contrario, deve essere un\u2019opportunit\u00e0 di crescita per le comunit\u00e0 locali, un modello sostenibile che valorizzi le risorse del territorio, favorisca la destagionalizzazione e crei nuove opportunit\u00e0 per giovani e startup innovative\u201d, ha dichiarato Pecoraro Scanio.<\/p>\n<p>pc\/gsl<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>BARI (ITALPRESS) &#8211; Il turismo del futuro deve essere ecologico e digitale, capace di generare benessere diffuso senza impattare negativamente sui territori. \u00c8 questo il messaggio lanciato da Alfonso Pecoraro Scanio, Presidente della Fondazione UniVerde e promotore della Rete EcoDigital, in occasione della BTM &#8211; Business Tourism Management, la fiera del turismo in corso in [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":45596,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1171],"tags":[],"class_list":["post-45595","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-video","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pecoraro Scanio &quot;Sfida Ecodigital da Bari, stop emigrazione giovani&quot; - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pecoraro Scanio &quot;Sfida Ecodigital da Bari, stop emigrazione giovani&quot; - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"BARI (ITALPRESS) &#8211; Il turismo del futuro deve essere ecologico e digitale, capace di generare benessere diffuso senza impattare negativamente sui territori. \u00c8 questo il messaggio lanciato da Alfonso Pecoraro Scanio, Presidente della Fondazione UniVerde e promotore della Rete EcoDigital, in occasione della BTM &#8211; Business Tourism Management, la fiera del turismo in corso in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-28T14:01:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Pecoraro Scanio &#8220;Sfida Ecodigital da Bari, stop emigrazione giovani&#8221;\",\"datePublished\":\"2025-02-28T14:01:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\\\/\"},\"wordCount\":137,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/W1Zn.jpg\",\"articleSection\":[\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\\\/\",\"name\":\"Pecoraro Scanio \\\"Sfida Ecodigital da Bari, stop emigrazione giovani\\\" - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/W1Zn.jpg\",\"datePublished\":\"2025-02-28T14:01:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/W1Zn.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/W1Zn.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pecoraro Scanio &#8220;Sfida Ecodigital da Bari, stop emigrazione giovani&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pecoraro Scanio \"Sfida Ecodigital da Bari, stop emigrazione giovani\" - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\/","og_locale":"it_IT","og_type":"article","og_title":"Pecoraro Scanio \"Sfida Ecodigital da Bari, stop emigrazione giovani\" - Live Magazine","og_description":"BARI (ITALPRESS) &#8211; Il turismo del futuro deve essere ecologico e digitale, capace di generare benessere diffuso senza impattare negativamente sui territori. \u00c8 questo il messaggio lanciato da Alfonso Pecoraro Scanio, Presidente della Fondazione UniVerde e promotore della Rete EcoDigital, in occasione della BTM &#8211; Business Tourism Management, la fiera del turismo in corso in [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2025-02-28T14:01:40+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Pecoraro Scanio &#8220;Sfida Ecodigital da Bari, stop emigrazione giovani&#8221;","datePublished":"2025-02-28T14:01:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\/"},"wordCount":137,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/02\/W1Zn.jpg","articleSection":["Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\/","url":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\/","name":"Pecoraro Scanio \"Sfida Ecodigital da Bari, stop emigrazione giovani\" - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/02\/W1Zn.jpg","datePublished":"2025-02-28T14:01:40+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/02\/W1Zn.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/02\/W1Zn.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/pecoraro-scanio-sfida-ecodigital-da-bari-stop-emigrazione-giovani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Pecoraro Scanio &#8220;Sfida Ecodigital da Bari, stop emigrazione giovani&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/02\/W1Zn.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/45595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=45595"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/45595\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/45596"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=45595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=45595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=45595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}