{"id":45589,"date":"2025-02-28T12:02:14","date_gmt":"2025-02-28T11:02:14","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\/"},"modified":"2025-02-28T12:02:14","modified_gmt":"2025-02-28T11:02:14","slug":"dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\/","title":{"rendered":"Dazi, Dombrovskis \u201cRischio \u00e8 che Pil mondiale crolli del 7%\u201d"},"content":{"rendered":"<div>\n<p>ROMA (ITALPRESS) \u2013 I dazi \u201cli consideriamo ingiustificati. Sar\u00e0 un problema per la crescita economica sia in Europa sia negli Stati Uniti. E anche altri Paesi. C\u2019\u00e8 il rischio che si verifichi una frammentazione economica globale. Ci sono stime del Fmi secondo cui a medio termine il Pil globale scender\u00e0 del 7%. E\u2019 come perdere il Pil complessivo della Germania e della Francia. L\u2019impatto negativo \u00e8 evidente\u201d. Cos\u00ec, in un\u2019intervista a la Repubblica, il commissario Ue agli Affari economici Valdis Dombrovskis. \u201cE\u2019 uno scenario che vogliamo scongiurare. Continueremo a impegnarci con gli Stati Uniti con un approccio positivo. Ma siamo pronti a reagire in modo fermo e proporzionato con dei contro-dazi quando sar\u00e0 necessario. Difenderemo le nostre aziende, i nostri lavoratori e i consumatori. Al momento ci sono diversi annunci del presidente Trump, ma solo quelli. Quindi sar\u00e0 necessario quando queste dichiarazioni si tradurranno in misure concrete\u201d, aggiunge. Comunque osserva Dombrovskis, \u201cgi\u00e0 4-5 anni fa Trump ha imposto dei dazi sull\u2019acciaio e sull\u2019alluminio e noi abbiamo reagito e poi negoziato\u201d.<br \/>(ITALPRESS).<br \/>-Foto: Ipa Agency-<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) \u2013 I dazi \u201cli consideriamo ingiustificati. Sar\u00e0 un problema per la crescita economica sia in Europa sia negli Stati Uniti. E anche altri Paesi. C\u2019\u00e8 il rischio che si verifichi una frammentazione economica globale. Ci sono stime del Fmi secondo cui a medio termine il Pil globale scender\u00e0 del 7%. E\u2019 come perdere [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":45590,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-45589","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dazi, Dombrovskis \u201cRischio \u00e8 che Pil mondiale crolli del 7%\u201d - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dazi, Dombrovskis \u201cRischio \u00e8 che Pil mondiale crolli del 7%\u201d - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"ROMA (ITALPRESS) \u2013 I dazi \u201cli consideriamo ingiustificati. Sar\u00e0 un problema per la crescita economica sia in Europa sia negli Stati Uniti. E anche altri Paesi. C\u2019\u00e8 il rischio che si verifichi una frammentazione economica globale. Ci sono stime del Fmi secondo cui a medio termine il Pil globale scender\u00e0 del 7%. E\u2019 come perdere [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-28T11:02:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Dazi, Dombrovskis \u201cRischio \u00e8 che Pil mondiale crolli del 7%\u201d\",\"datePublished\":\"2025-02-28T11:02:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\\\/\"},\"wordCount\":183,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20250228_0234.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\\\/\",\"name\":\"Dazi, Dombrovskis \u201cRischio \u00e8 che Pil mondiale crolli del 7%\u201d - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20250228_0234.jpg\",\"datePublished\":\"2025-02-28T11:02:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20250228_0234.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20250228_0234.jpg\",\"width\":830,\"height\":552},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/02\\\/28\\\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dazi, Dombrovskis \u201cRischio \u00e8 che Pil mondiale crolli del 7%\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dazi, Dombrovskis \u201cRischio \u00e8 che Pil mondiale crolli del 7%\u201d - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\/","og_locale":"it_IT","og_type":"article","og_title":"Dazi, Dombrovskis \u201cRischio \u00e8 che Pil mondiale crolli del 7%\u201d - Live Magazine","og_description":"ROMA (ITALPRESS) \u2013 I dazi \u201cli consideriamo ingiustificati. Sar\u00e0 un problema per la crescita economica sia in Europa sia negli Stati Uniti. E anche altri Paesi. C\u2019\u00e8 il rischio che si verifichi una frammentazione economica globale. Ci sono stime del Fmi secondo cui a medio termine il Pil globale scender\u00e0 del 7%. E\u2019 come perdere [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2025-02-28T11:02:14+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Dazi, Dombrovskis \u201cRischio \u00e8 che Pil mondiale crolli del 7%\u201d","datePublished":"2025-02-28T11:02:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\/"},"wordCount":183,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/02\/20250228_0234.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\/","url":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\/","name":"Dazi, Dombrovskis \u201cRischio \u00e8 che Pil mondiale crolli del 7%\u201d - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/02\/20250228_0234.jpg","datePublished":"2025-02-28T11:02:14+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/02\/20250228_0234.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/02\/20250228_0234.jpg","width":830,"height":552},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2025\/02\/28\/dazi-dombrovskis-rischio-e-che-pil-mondiale-crolli-del-7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Dazi, Dombrovskis \u201cRischio \u00e8 che Pil mondiale crolli del 7%\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/02\/20250228_0234.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/45589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=45589"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/45589\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/45590"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=45589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=45589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=45589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}