{"id":42546,"date":"2025-01-14T15:02:36","date_gmt":"2025-01-14T14:02:36","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2025\/01\/14\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\/"},"modified":"2025-01-14T15:02:36","modified_gmt":"2025-01-14T14:02:36","slug":"terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2025\/01\/14\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\/","title":{"rendered":"<div>Terzo mandato, Fontana &#8220;Proprio perch\u00e9 c&#8217;\u00e8 elezione diretta \u00e8 giusto&#8221;<\/div>"},"content":{"rendered":"<p>    <video-js id=\"videojs6a5815a6cda56\" class=\"vjs-big-play-centered\" controls preload=\"auto\" playsinline data-setup='{\"fluid\": true}'>\r\n        <source src=\"https:\/\/video.italpress.com\/play\/mp4\/video\/mkY0\" type=\"video\/mp4\" \/>\r\n    <\/video-js>\r\n           <br \/>\n<\/p>\n<div> MILANO (ITALPRESS) &#8211; &#8220;Proprio perch\u00e9 c&#8217;\u00e8 un&#8217;elezione diretta, massima espressione di democrazia, credo che sia un motivo in pi\u00f9 per dire che \u00e8 giusto il terzo mandato. Ribadisco che \u00e8 un errore&#8221; che il governo impugni la legge della Campania. Cos\u00ec il presidente della Regione Lombardia, Attilio Fontana, a margine della presentazione del &#8220;Rapporto Lombardia 2024 \u2013 Sostenibilit\u00e0 \u00e8 Innovazione&#8221;.<br \/>\nxm4\/ads\/mrv<\/div>\n","protected":false},"excerpt":{"rendered":"<p>MILANO (ITALPRESS) &#8211; &#8220;Proprio perch\u00e9 c&#8217;\u00e8 un&#8217;elezione diretta, massima espressione di democrazia, credo che sia un motivo in pi\u00f9 per dire che \u00e8 giusto il terzo mandato. Ribadisco che \u00e8 un errore&#8221; che il governo impugni la legge della Campania. Cos\u00ec il presidente della Regione Lombardia, Attilio Fontana, a margine della presentazione del &#8220;Rapporto Lombardia [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":42547,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1171],"tags":[],"class_list":["post-42546","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-video","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Terzo mandato, Fontana &quot;Proprio perch\u00e9 c&#039;\u00e8 elezione diretta \u00e8 giusto&quot; - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2025\/01\/14\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terzo mandato, Fontana &quot;Proprio perch\u00e9 c&#039;\u00e8 elezione diretta \u00e8 giusto&quot; - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"MILANO (ITALPRESS) &#8211; &#8220;Proprio perch\u00e9 c&#8217;\u00e8 un&#8217;elezione diretta, massima espressione di democrazia, credo che sia un motivo in pi\u00f9 per dire che \u00e8 giusto il terzo mandato. Ribadisco che \u00e8 un errore&#8221; che il governo impugni la legge della Campania. Cos\u00ec il presidente della Regione Lombardia, Attilio Fontana, a margine della presentazione del &#8220;Rapporto Lombardia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2025\/01\/14\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-14T14:02:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/01\\\/14\\\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/01\\\/14\\\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Terzo mandato, Fontana &#8220;Proprio perch\u00e9 c&#8217;\u00e8 elezione diretta \u00e8 giusto&#8221;\",\"datePublished\":\"2025-01-14T14:02:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/01\\\/14\\\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\\\/\"},\"wordCount\":79,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/01\\\/14\\\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/mkY0.jpg\",\"articleSection\":[\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/01\\\/14\\\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/01\\\/14\\\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\\\/\",\"name\":\"Terzo mandato, Fontana \\\"Proprio perch\u00e9 c'\u00e8 elezione diretta \u00e8 giusto\\\" - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/01\\\/14\\\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/01\\\/14\\\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/mkY0.jpg\",\"datePublished\":\"2025-01-14T14:02:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/01\\\/14\\\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/01\\\/14\\\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/01\\\/14\\\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/mkY0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/mkY0.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2025\\\/01\\\/14\\\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terzo mandato, Fontana &#8220;Proprio perch\u00e9 c&#8217;\u00e8 elezione diretta \u00e8 giusto&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Terzo mandato, Fontana \"Proprio perch\u00e9 c'\u00e8 elezione diretta \u00e8 giusto\" - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2025\/01\/14\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\/","og_locale":"it_IT","og_type":"article","og_title":"Terzo mandato, Fontana \"Proprio perch\u00e9 c'\u00e8 elezione diretta \u00e8 giusto\" - Live Magazine","og_description":"MILANO (ITALPRESS) &#8211; &#8220;Proprio perch\u00e9 c&#8217;\u00e8 un&#8217;elezione diretta, massima espressione di democrazia, credo che sia un motivo in pi\u00f9 per dire che \u00e8 giusto il terzo mandato. Ribadisco che \u00e8 un errore&#8221; che il governo impugni la legge della Campania. Cos\u00ec il presidente della Regione Lombardia, Attilio Fontana, a margine della presentazione del &#8220;Rapporto Lombardia [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2025\/01\/14\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2025-01-14T14:02:36+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2025\/01\/14\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/01\/14\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Terzo mandato, Fontana &#8220;Proprio perch\u00e9 c&#8217;\u00e8 elezione diretta \u00e8 giusto&#8221;","datePublished":"2025-01-14T14:02:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/01\/14\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\/"},"wordCount":79,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/01\/14\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/01\/mkY0.jpg","articleSection":["Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2025\/01\/14\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\/","url":"https:\/\/www.livemag.it\/index.php\/2025\/01\/14\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\/","name":"Terzo mandato, Fontana \"Proprio perch\u00e9 c'\u00e8 elezione diretta \u00e8 giusto\" - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/01\/14\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/01\/14\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/01\/mkY0.jpg","datePublished":"2025-01-14T14:02:36+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2025\/01\/14\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2025\/01\/14\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2025\/01\/14\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/01\/mkY0.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/01\/mkY0.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2025\/01\/14\/terzo-mandato-fontana-proprio-perche-ce-elezione-diretta-e-giusto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Terzo mandato, Fontana &#8220;Proprio perch\u00e9 c&#8217;\u00e8 elezione diretta \u00e8 giusto&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2025\/01\/mkY0.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/42546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=42546"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/42546\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/42547"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=42546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=42546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=42546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}