{"id":39440,"date":"2024-11-21T00:03:47","date_gmt":"2024-11-20T23:03:47","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2024\/11\/21\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\/"},"modified":"2024-11-21T00:03:47","modified_gmt":"2024-11-20T23:03:47","slug":"argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2024\/11\/21\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\/","title":{"rendered":"Argentina, Meloni \u201cForte legame con Italia, politiche Milei coraggiose\u201d"},"content":{"rendered":"<div>\n<p>BUENOS AIRES (ARGENTINA) (ITALPRESS) \u2013 \u201cGli italiani e gli argentini sono popoli fratelli. Il legame che unisce le nostre nazioni ha radici profonde. L\u2019amore per la libert\u00e0 \u00e8 un sentimento che ci accomuna da sempre\u201d. Lo dice il premier Giorgia Meloni, nel corso delle dichiarazioni alla stampa a Buenos Aires dopo l\u2019incontro con il presidente argentino Javier Milei.<br \/>\u201cE\u2019 molto forte l\u2019identit\u00e0 di vedute su molti dossier, penso tra l\u2019altro all\u2019Ucraina, al Medio Oriente e al Venezuela \u2013 sottolinea Meloni -. Insieme all\u2019Unione Europea lavoriamo per una transizione democratica e pacifica del Venezuela, affinch\u00e8 la preferenza espressa dal popolo venezuelano per il presidente eletto Gonzalez Urrutia e le legittime aspirazioni di libert\u00e0 e democrazia trovino finalmente realizzazione\u201d.<br \/>\u201cIl potenziale di crescita delle nostre relazioni economiche \u00e8 straordinario, grazie anche alle oltre 300 imprese italiane che sono attive nella nazione, che impiegano pi\u00f9 di 16 mila lavoratori e che generano un giro d\u2019affari di quasi 3 miliardi di euro \u2013 afferma ancora il premier -. Le politiche molto coraggiose di liberalizzazione del mercato e per sostenere gli investimenti che il presidente Milei sta portando avanti possono aprire dal nostro punto di vista nuove opportunit\u00e0, essere un ulteriore incentivo per accrescere la presenza italiana come intendiamo fare\u201d.<\/p>\n<p>\u2013 Foto Agenzia Fotogramma \u2013<\/p>\n<p>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>BUENOS AIRES (ARGENTINA) (ITALPRESS) \u2013 \u201cGli italiani e gli argentini sono popoli fratelli. Il legame che unisce le nostre nazioni ha radici profonde. L\u2019amore per la libert\u00e0 \u00e8 un sentimento che ci accomuna da sempre\u201d. Lo dice il premier Giorgia Meloni, nel corso delle dichiarazioni alla stampa a Buenos Aires dopo l\u2019incontro con il presidente [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":39441,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1129],"tags":[],"class_list":["post-39440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Argentina, Meloni \u201cForte legame con Italia, politiche Milei coraggiose\u201d - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2024\/11\/21\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Argentina, Meloni \u201cForte legame con Italia, politiche Milei coraggiose\u201d - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"BUENOS AIRES (ARGENTINA) (ITALPRESS) \u2013 \u201cGli italiani e gli argentini sono popoli fratelli. Il legame che unisce le nostre nazioni ha radici profonde. L\u2019amore per la libert\u00e0 \u00e8 un sentimento che ci accomuna da sempre\u201d. Lo dice il premier Giorgia Meloni, nel corso delle dichiarazioni alla stampa a Buenos Aires dopo l\u2019incontro con il presidente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2024\/11\/21\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-20T23:03:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/21\\\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/21\\\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Argentina, Meloni \u201cForte legame con Italia, politiche Milei coraggiose\u201d\",\"datePublished\":\"2024-11-20T23:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/21\\\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\\\/\"},\"wordCount\":217,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/21\\\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/20241120_2139.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/21\\\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/21\\\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\\\/\",\"name\":\"Argentina, Meloni \u201cForte legame con Italia, politiche Milei coraggiose\u201d - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/21\\\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/21\\\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/20241120_2139.jpg\",\"datePublished\":\"2024-11-20T23:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/21\\\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/21\\\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/21\\\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/20241120_2139.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/20241120_2139.jpg\",\"width\":1200,\"height\":799},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/21\\\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Argentina, Meloni \u201cForte legame con Italia, politiche Milei coraggiose\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Argentina, Meloni \u201cForte legame con Italia, politiche Milei coraggiose\u201d - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2024\/11\/21\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\/","og_locale":"it_IT","og_type":"article","og_title":"Argentina, Meloni \u201cForte legame con Italia, politiche Milei coraggiose\u201d - Live Magazine","og_description":"BUENOS AIRES (ARGENTINA) (ITALPRESS) \u2013 \u201cGli italiani e gli argentini sono popoli fratelli. Il legame che unisce le nostre nazioni ha radici profonde. L\u2019amore per la libert\u00e0 \u00e8 un sentimento che ci accomuna da sempre\u201d. Lo dice il premier Giorgia Meloni, nel corso delle dichiarazioni alla stampa a Buenos Aires dopo l\u2019incontro con il presidente [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2024\/11\/21\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2024-11-20T23:03:47+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2024\/11\/21\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/11\/21\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Argentina, Meloni \u201cForte legame con Italia, politiche Milei coraggiose\u201d","datePublished":"2024-11-20T23:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/11\/21\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\/"},"wordCount":217,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/11\/21\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/11\/20241120_2139.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2024\/11\/21\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\/","url":"https:\/\/www.livemag.it\/index.php\/2024\/11\/21\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\/","name":"Argentina, Meloni \u201cForte legame con Italia, politiche Milei coraggiose\u201d - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/11\/21\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/11\/21\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/11\/20241120_2139.jpg","datePublished":"2024-11-20T23:03:47+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/11\/21\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2024\/11\/21\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2024\/11\/21\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/11\/20241120_2139.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/11\/20241120_2139.jpg","width":1200,"height":799},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2024\/11\/21\/argentina-meloni-forte-legame-con-italia-politiche-milei-coraggiose\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Argentina, Meloni \u201cForte legame con Italia, politiche Milei coraggiose\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/11\/20241120_2139.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/39440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=39440"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/39440\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/39441"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=39440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=39440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=39440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}