{"id":39424,"date":"2024-11-20T18:05:06","date_gmt":"2024-11-20T17:05:06","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2024\/11\/20\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\/"},"modified":"2024-11-20T18:05:06","modified_gmt":"2024-11-20T17:05:06","slug":"per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2024\/11\/20\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\/","title":{"rendered":"Per una Sanit\u00e0 pi\u00f9 efficace un nuovo patto per l\u2019aderenza terapeutica"},"content":{"rendered":"<div>\n<p>ROMA (ITALPRESS) \u2013 Si \u00e8 tenuto a Roma il convegno \u201cL\u2019importanza dell\u2019aderenza alla terapia: un nuovo patto per la tutela dei pazienti\u201d. La giornata, resa possibile grazie al contributo non condizionante del Gruppo Servier in Italia, ha riunito esponenti delle Istituzioni, del settore sanitario e dell\u2019industria per affrontare il tema dell\u2019aderenza terapeutica, ormai considerata una priorit\u00e0 strategica del Servizio Sanitario Nazionale in un\u2019ottica di miglioramento degli esiti clinici e della qualit\u00e0 di vita dei pazienti.<br \/>I saluti istituzionali sono stati aperti da Ilenia Malavasi, Membro XII Commissione della Camera dei Deputati, che ha evidenziato l\u2019attenzione crescente della politica verso l\u2019aderenza terapeutica, un aspetto che incide sia sulla salute dei pazienti che sulla sostenibilit\u00e0 del sistema sanitario. \u201cL\u2019aderenza terapeutica rappresenta una sfida complessa che richiede una visione sistemica e obiettivi chiari \u2013 ha dichiarato Malavasi -. Rendere misurabile l\u2019aderenza, attraverso strumenti che analizzino i trend e individuino le aree critiche, \u00e8 fondamentale per orientare strategie efficaci. Solo dati concreti e affidabili, definiti attraverso una partnership pubblico \u2013 privata, possono guidare le Istituzioni nella definizione di interventi mirati, migliorando l\u2019efficacia delle terapie e garantendo un accesso equo alle cure\u201d. <br \/>La discussione ha avuto inizio con il contributo di autorevoli esponenti del mondo sanitario, che hanno approfondito le sfide e le priorit\u00e0 per incrementare l\u2019aderenza terapeutica. Manuela Bocchino dell\u2019Istituto Superiore di Sanit\u00e0, Massimo Volpe, Professore emerito di Cardiologia dell\u2019Universit\u00e0 degli Studi di Roma \u201cLa Sapienza\u201d, e Massimo Sabatini, Federazione Italiana dei Medici di Medicina Generale, hanno messo in evidenza l\u2019importanza della telemedicina e del monitoraggio continuo come strumenti strategici, evidenziando altres\u00ec come una comunicazione medico-paziente efficace possa contribuire in modo significativo al miglioramento della loro qualit\u00e0 di vita e al successo delle terapie. <br \/>Mentre Carlotta Lunghi, Ricercatrice presso il Dipartimento di Scienze Mediche e Chirurgiche all\u2019Alma Mater Studiorum dell\u2019Universit\u00e0 di Bologna, ha illustrato il ruolo delle metodologie di analisi e dei sistemi di monitoraggio nel migliorare la persistenza e la copertura terapeutica, con un focus sulle terapie.<br \/>\u201cIl monitoraggio continuativo rappresenta uno strumento essenziale per migliorare l\u2019aderenza terapeutica, soprattutto nelle patologie croniche\u201d, ha dichiarato Bocchino. \u201cIntrodurre un indicatore di aderenza a livello nazionale consentirebbe di rilevare in modo sistematico i trend, offrendo una visione chiara delle aree in cui intervenire per ottimizzare i percorsi terapeutici. Solo un approccio integrato e basato su dati oggettivi pu\u00f2 incidere positivamente sulla salute pubblica e sulla sostenibilit\u00e0 del sistema sanitario, guidandoci verso l\u2019adozione di misure mirate\u201d.<br \/>Sabatini ha sottolineato inoltre il valore della continuit\u00e0 assistenziale del Medico di Medicina Generale: \u201cSolo con un dialogo efficace tra tutte le componenti sanitarie possiamo costruire una risposta solida e sostenibile alle esigenze dei cittadini\u201d. \u201cIl Medico di Medicina Generale \u2013 ha proseguito \u2013 in particolare, pu\u00f2 svolgere un ruolo determinante non solo nell\u2019utilizzo di strumenti digitali e tecnologici, oltre che di soluzioni terapeutiche adatte come le combinazioni fisse per una gestione pi\u00f9 efficace delle terapie, ma anche nel promuovere una comunicazione costante, indispensabile per intercettare i bisogni delle persone in cura e migliorarne la qualit\u00e0 di vita. Inoltre, trovo fondamentale valorizzare, oltre il concetto di aderenza, anche quello di persistenza. L\u2019introduzione di un indicatore di aderenza fornirebbe una base affidabile per monitorare i progressi terapeutici, aiutando i professionisti sanitari a intervenire tempestivamente dove necessario\u201d. <br \/>L\u2019evento si \u00e8 concluso con l\u2019appello delle Istituzioni e dell\u2019industria a collaborare per promuovere un patto di tutela dei pazienti e della sostenibilit\u00e0 sanitaria. E\u2019 emerso come l\u2019aderenza terapeutica non sia solo una responsabilit\u00e0 del paziente, ma un obiettivo condiviso che richiede sinergia e impegno a tutti i livelli, dai decisori politici fino ai professionisti sanitari e ai caregiver. Solo attraverso una collaborazione sistematica e integrata sar\u00e0 possibile garantire una maggiore efficacia delle cure, riducendo al contempo i costi e migliorando la qualit\u00e0 della vita dei pazienti.<\/p>\n<p>\u2013 foto ufficio stampa Esperia Advocacy \u2013<br \/>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) \u2013 Si \u00e8 tenuto a Roma il convegno \u201cL\u2019importanza dell\u2019aderenza alla terapia: un nuovo patto per la tutela dei pazienti\u201d. La giornata, resa possibile grazie al contributo non condizionante del Gruppo Servier in Italia, ha riunito esponenti delle Istituzioni, del settore sanitario e dell\u2019industria per affrontare il tema dell\u2019aderenza terapeutica, ormai considerata una [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":39425,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1129],"tags":[],"class_list":["post-39424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Per una Sanit\u00e0 pi\u00f9 efficace un nuovo patto per l\u2019aderenza terapeutica - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2024\/11\/20\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Per una Sanit\u00e0 pi\u00f9 efficace un nuovo patto per l\u2019aderenza terapeutica - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"ROMA (ITALPRESS) \u2013 Si \u00e8 tenuto a Roma il convegno \u201cL\u2019importanza dell\u2019aderenza alla terapia: un nuovo patto per la tutela dei pazienti\u201d. La giornata, resa possibile grazie al contributo non condizionante del Gruppo Servier in Italia, ha riunito esponenti delle Istituzioni, del settore sanitario e dell\u2019industria per affrontare il tema dell\u2019aderenza terapeutica, ormai considerata una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2024\/11\/20\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-20T17:05:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/20\\\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/20\\\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Per una Sanit\u00e0 pi\u00f9 efficace un nuovo patto per l\u2019aderenza terapeutica\",\"datePublished\":\"2024-11-20T17:05:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/20\\\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\\\/\"},\"wordCount\":655,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/20\\\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/20241120_1015.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/20\\\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/20\\\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\\\/\",\"name\":\"Per una Sanit\u00e0 pi\u00f9 efficace un nuovo patto per l\u2019aderenza terapeutica - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/20\\\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/20\\\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/20241120_1015.jpg\",\"datePublished\":\"2024-11-20T17:05:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/20\\\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/20\\\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/20\\\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/20241120_1015.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/20241120_1015.jpg\",\"width\":1024,\"height\":681},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/11\\\/20\\\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Per una Sanit\u00e0 pi\u00f9 efficace un nuovo patto per l\u2019aderenza terapeutica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Per una Sanit\u00e0 pi\u00f9 efficace un nuovo patto per l\u2019aderenza terapeutica - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2024\/11\/20\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\/","og_locale":"it_IT","og_type":"article","og_title":"Per una Sanit\u00e0 pi\u00f9 efficace un nuovo patto per l\u2019aderenza terapeutica - Live Magazine","og_description":"ROMA (ITALPRESS) \u2013 Si \u00e8 tenuto a Roma il convegno \u201cL\u2019importanza dell\u2019aderenza alla terapia: un nuovo patto per la tutela dei pazienti\u201d. La giornata, resa possibile grazie al contributo non condizionante del Gruppo Servier in Italia, ha riunito esponenti delle Istituzioni, del settore sanitario e dell\u2019industria per affrontare il tema dell\u2019aderenza terapeutica, ormai considerata una [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2024\/11\/20\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2024-11-20T17:05:06+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2024\/11\/20\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/11\/20\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Per una Sanit\u00e0 pi\u00f9 efficace un nuovo patto per l\u2019aderenza terapeutica","datePublished":"2024-11-20T17:05:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/11\/20\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\/"},"wordCount":655,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/11\/20\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/11\/20241120_1015.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2024\/11\/20\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\/","url":"https:\/\/www.livemag.it\/index.php\/2024\/11\/20\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\/","name":"Per una Sanit\u00e0 pi\u00f9 efficace un nuovo patto per l\u2019aderenza terapeutica - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/11\/20\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/11\/20\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/11\/20241120_1015.jpg","datePublished":"2024-11-20T17:05:06+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/11\/20\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2024\/11\/20\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2024\/11\/20\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/11\/20241120_1015.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/11\/20241120_1015.jpg","width":1024,"height":681},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2024\/11\/20\/per-una-sanita-piu-efficace-un-nuovo-patto-per-laderenza-terapeutica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Per una Sanit\u00e0 pi\u00f9 efficace un nuovo patto per l\u2019aderenza terapeutica"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/11\/20241120_1015.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/39424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=39424"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/39424\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/39425"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=39424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=39424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=39424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}