{"id":36228,"date":"2024-10-03T03:03:16","date_gmt":"2024-10-03T01:03:16","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2024\/10\/03\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\/"},"modified":"2024-10-03T03:03:16","modified_gmt":"2024-10-03T01:03:16","slug":"impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2024\/10\/03\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\/","title":{"rendered":"Impresa Juve alla Red Bull Arena, Lipsia piegato per 3-2"},"content":{"rendered":"<div>\n<p>LIPSIA (GERMANIA) (ITALPRESS) \u2013 Al termine di una partita folle e ricca di episodi, la Juventus batte 3-2 il Lipsia, compiendo un\u2019impresa eroica alla Red Bull Arena. La doppietta di Vlahovic e la perla nel finale di Conceicao regalano ai bianconeri la seconda vittoria nel girone di Champions: per i tedeschi va in gol due volte Sesko. Gli infortuni, l\u2019espulsione di Di Gregorio e la vivacit\u00e0 offensiva del Lipsia non scoraggiano una Juve, mai doma e sempre impavida. L\u2019avvio di gara per i bianconeri si rivela alquanto traumatico: gi\u00e0 dopo undici minuti, Motta \u00e8 costretto ad operare due sostituzioni, a causa dei guai fisici prima di Bremer, poi di Nico Gonzalez. Nonostante un primo quarto d\u2019ora psicologicamente traumatico, i ragazzi di Motta si fanno preferire al Lipsia, sul piano della proposta di gioco. Alla prima sbavatura della Juve, per\u00f2, la formazione di casa ringrazia e segna la rete dell\u20191-0: su azione di ripartenza, Openda serve Sesko che, dopo uno splendido aggancio di sinistro, di potenza infila la palla sotto la traversa. Al 36\u2032 la Juve protesta all\u2019indirizzo dell\u2019arbitro Letexier, in seguito al contatto in area tra Vlahovic e Lukeba: nemmeno il Var ravvisa il piede a martello del difensore francese. Nella ripresa la Juve rientra in campo con maggiore ferocia e il palo di Koopmeiners al 49\u2032 \u00e8 anticipatorio del gol bianconero. Un minuto dopo, Vlahovic timbra l\u20191-1, inserendosi in area e deviando in rete il cross di Cambiaso. Proprio quando la partita sembra girare a favore dei bianconeri, due ingenuit\u00e0 complicano nuovamente la situazione. Al  59\u2032 Di Gregorio prende la palla con le mani fuori dall\u2019area e viene espulso dopo il ricorso al Var. Al 65\u2032, invece, il neoentrato Douglas Luiz commette fallo di mano sulla punizione dal limite di Simons: dal dischetto ci pensa Sesko a fare 2-1. Non \u00e8, per\u00f2, finita, perch\u00e8 Vlahovic non ci sta e si carica la squadra sulle spalle, pareggiando nuovamente con un grande mancino da fuori. L\u2019inferiorit\u00e0 numerica non scoraggia la Juve che mantiene un atteggiamento coraggioso, ma rischia a pi\u00f9 ripresa di subire un nuovo svantaggio. Openda \u00e8 semplicemente imprendibile e colpisce ben due pali. Quando meno te l\u2019aspetti, per\u00f2, al 82\u2032 una fiammata di Conceicao vale il clamoroso 3-2 per la Juve: il portoghese salta secco Raum e poi fredda Gulacsi. Il finale \u00e8 di pura sofferenza, ma la retroguardia di Motta regge. Una serata da sogno per la Vecchia Signora, capace di reagire anche agli episodi negativi.<br \/>\u2013 Foto Image \u2013<br \/>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>LIPSIA (GERMANIA) (ITALPRESS) \u2013 Al termine di una partita folle e ricca di episodi, la Juventus batte 3-2 il Lipsia, compiendo un\u2019impresa eroica alla Red Bull Arena. La doppietta di Vlahovic e la perla nel finale di Conceicao regalano ai bianconeri la seconda vittoria nel girone di Champions: per i tedeschi va in gol due [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":36229,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-36228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impresa Juve alla Red Bull Arena, Lipsia piegato per 3-2 - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2024\/10\/03\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impresa Juve alla Red Bull Arena, Lipsia piegato per 3-2 - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"LIPSIA (GERMANIA) (ITALPRESS) \u2013 Al termine di una partita folle e ricca di episodi, la Juventus batte 3-2 il Lipsia, compiendo un\u2019impresa eroica alla Red Bull Arena. La doppietta di Vlahovic e la perla nel finale di Conceicao regalano ai bianconeri la seconda vittoria nel girone di Champions: per i tedeschi va in gol due [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2024\/10\/03\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-03T01:03:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/10\\\/03\\\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/10\\\/03\\\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Impresa Juve alla Red Bull Arena, Lipsia piegato per 3-2\",\"datePublished\":\"2024-10-03T01:03:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/10\\\/03\\\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\\\/\"},\"wordCount\":421,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/10\\\/03\\\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/20241002_2529.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/10\\\/03\\\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/10\\\/03\\\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\\\/\",\"name\":\"Impresa Juve alla Red Bull Arena, Lipsia piegato per 3-2 - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/10\\\/03\\\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/10\\\/03\\\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/20241002_2529.jpg\",\"datePublished\":\"2024-10-03T01:03:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/10\\\/03\\\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/10\\\/03\\\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/10\\\/03\\\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/20241002_2529.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/20241002_2529.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/10\\\/03\\\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impresa Juve alla Red Bull Arena, Lipsia piegato per 3-2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impresa Juve alla Red Bull Arena, Lipsia piegato per 3-2 - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2024\/10\/03\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\/","og_locale":"it_IT","og_type":"article","og_title":"Impresa Juve alla Red Bull Arena, Lipsia piegato per 3-2 - Live Magazine","og_description":"LIPSIA (GERMANIA) (ITALPRESS) \u2013 Al termine di una partita folle e ricca di episodi, la Juventus batte 3-2 il Lipsia, compiendo un\u2019impresa eroica alla Red Bull Arena. La doppietta di Vlahovic e la perla nel finale di Conceicao regalano ai bianconeri la seconda vittoria nel girone di Champions: per i tedeschi va in gol due [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2024\/10\/03\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2024-10-03T01:03:16+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2024\/10\/03\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/10\/03\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Impresa Juve alla Red Bull Arena, Lipsia piegato per 3-2","datePublished":"2024-10-03T01:03:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/10\/03\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\/"},"wordCount":421,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/10\/03\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/10\/20241002_2529.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2024\/10\/03\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\/","url":"https:\/\/www.livemag.it\/index.php\/2024\/10\/03\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\/","name":"Impresa Juve alla Red Bull Arena, Lipsia piegato per 3-2 - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/10\/03\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/10\/03\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/10\/20241002_2529.jpg","datePublished":"2024-10-03T01:03:16+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/10\/03\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2024\/10\/03\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2024\/10\/03\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/10\/20241002_2529.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/10\/20241002_2529.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2024\/10\/03\/impresa-juve-alla-red-bull-arena-lipsia-piegato-per-3-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Impresa Juve alla Red Bull Arena, Lipsia piegato per 3-2"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/10\/20241002_2529.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/36228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=36228"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/36228\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/36229"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=36228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=36228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=36228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}