{"id":34256,"date":"2024-09-06T18:03:52","date_gmt":"2024-09-06T16:03:52","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2024\/09\/06\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\/"},"modified":"2024-09-06T18:03:52","modified_gmt":"2024-09-06T16:03:52","slug":"studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2024\/09\/06\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\/","title":{"rendered":"Studio Siram Veolia, sistema energetico italiano meno competitivo in Ue"},"content":{"rendered":"<div>\n<p>CERNOBBIO (COMO) (ITALPRESS) \u2013 In un contesto in cui \u00e8 necessario accelerare il percorso di decarbonizzazione, l\u2019ottimizzazione energetica \u2013 intesa come la combinazione di efficienza energetica, rinnovabili, fuel switch, storage, flessibilit\u00e0, condivisione e aggregazione di energia distribuita \u2013 e l\u2019adozione di strumenti digitali avanzati sono leve essenziali per la transizione energetica, la salvaguardia della competitivit\u00e0 del Paese e il benessere sociale. Lo Studio \u201cOttimizzazione e autonomia energetica nell\u2019era della generative AI\u201d, realizzato da Siram Veolia e TEHA Group, si pone l\u2019obiettivo di valorizzare il contributo differenziale di un approccio sistemico basato sull\u2019ottimizzazione energetica e sul ruolo di soluzioni digitali per accelerare il processo di decarbonizzazione ed efficientamento del Paese. In particolare, lo Studio pone l\u2019attenzione su due settori strategici che dovranno affrontare importanti sfide trasformative: industria e Pubblica Amministrazione.<br \/>\u201cL\u2019energia pi\u00f9 competitiva e sostenibile \u00e8 quella che non si consuma \u2013 ha commentato Emanuela Trentin, Amministratore Delegato di Siram Veolia -. Parlando di transizione energetica ci si focalizza troppo spesso sul cambio di mix energetico, puntando unicamente sulla generazione da fonti rinnovabili e sull\u2019elettrificazione dei consumi, ma alla base ci deve essere un utilizzo ottimizzato dell\u2019energia, altrimenti non faremo buon uso dell\u2019energia rinnovabile che \u00e8 ancor pi\u00f9 scarsa e preziosa di quella fossile\u201d. Attraverso questo studio, conclude, \u201cvogliamo dimostrare quanto potenziale di ottimizzazione ci sia ancora da cogliere integrando efficienza energetica e fonti rinnovabili, unite all\u2019utilizzo di tecnologie all\u2019avanguardia basate sul digitale\u201d.<br \/>\u201cTra il 2000 e il 2022, il sistema energetico italiano ha perso il suo tradizionale vantaggio competitivo; l\u2019indice di intensit\u00e0 energetica italiano \u00e8 infatti migliorato solo del 14%, a fronte della media UE del 28% e della Francia del 29%. In questo scenario, un approccio sistemico basato sull\u2019ottimizzazione energetica e sull\u2019utilizzo efficiente delle risorse emerge come leva chiave per accelerare il processo di decarbonizzazione e amplificare i benefici economici, ambientali e sociali per il sistema-Paese abilitati dalla transizione energetica\u201d, ha commentato Valerio de Molli, Managing Partner &amp; CEO di The European House \u2013 Ambrosetti e TEHA Group.<br \/>L\u2019iniziativa ha gi\u00e0 visto dei momenti di coinvolgimento e confronto con stakeholder di rilievo, e preveder\u00e0 una Tavola Rotonda dedicata a Roma il prossimo 28 novembre per discutere le proposte di azione.<br \/>Il primo focus dello Studio Strategico riguarda il ruolo dell\u2019ottimizzazione energetica nell\u2019industria, la cui competitivit\u00e0 \u00e8 sempre pi\u00f9 impattata dalle scelte legate ai percorsi di decarbonizzazione. Al 2050 lo Studio stima che il solo meccanismo ETS impatter\u00e0 tra il 15% e il 33% del Valore Aggiunto generato dall\u2019industria energivora italiana. Il ruolo dell\u2019industria \u00e8, inoltre, fondamentale per il raggiungimento degli obiettivi net zero al 2050, essendo responsabile di oltre un quinto delle emissioni di CO 2 e dei consumi energetici del Paese. Attraverso un approccio di filiera, l\u2019ottimizzazione energetica pu\u00f2 permettere di valorizzare il contributo sinergico di soluzioni \u201ctradizionali\u201d come la cogenerazione e lo sviluppo di bioenergie e nuove molecole green, a partire dal biometano. Nell\u2019utilizzo della cogenerazione, l\u2019industria italiana sconta un gap significativo rispetto alla Germania (-15,7 p.p. di produzione di energia da impianti di cogenerazione in rapporto ai consumi energetici finali); colmare questo gap consentir\u00e0, ad esempio, un migliore utilizzo del biometano progressivamente disponibile minimizzando le perdite di efficienza e senza necessit\u00e0 di interventi impiantistici.<br \/>Il secondo focus dello Studio riguarda il ruolo dell\u2019ottimizzazione energetica negli edifici della Pubblica Amministrazione, evidenziandone il potenziale per accelerare il processo di efficientamento nel settore pubblico. Sebbene siano stati fissati obiettivi ambiziosi per la riqualificazione del patrimonio edilizio pubblico, pari al 3% annuo, dal 2019 il tasso di riqualificazione non ha superato l\u20191%. Lo Studio ha identificato alcune criticit\u00e0 nel modello di procurement che contribuiscono a tale rallentamento, tra le quali: le forti discrepanze tra i fondi stanziati e quelli erogati per i progetti completati, il massimo ribasso sul costo del risparmio energetico per kWh che limita la diffusione delle nuove tecnologie, la mancanza di una programmazione uniforme a causa delle difformit\u00e0 regionali, e una generale carenza di risorse e competenze tecniche nella Pubblica Amministrazione. In questo quadro, il modello di Partenariato Pubblico-Privato (PPP) emerge come uno strumento cruciale per promuovere la condivisione di competenze e stimolare l\u2019innovazione, oltre al fatto di consentire tempi di realizzazione pi\u00f9 rapidi e un\u2019efficace condivisione dei rischi. Lo Studio evidenzia quindi la necessit\u00e0 di un modello che promuova la collaborazione sistemica tra pubblico e privato per massimizzare i benefici dell\u2019ottimizzazione energetica. In Italia, infatti, il ricorso a modelli di PPP \u00e8 oggi significativamente inferiore ai peer europei. Il valore dei progetti realizzati con questo strumento dal 1990 ad oggi \u00e8 stato 20 volte inferiore rispetto al Regno Unito e 3 volte inferiore rispetto alla Francia.<br \/>In questo contesto, il digitale e l\u2019Intelligenza Artificiale possono avere un ruolo importante per la creazione di un sistema incentrato sull\u2019ottimizzazione energetica abilitando modelli di analisi, monitoraggio e gestione in tempo reale, con l\u2019erogazione di servizi avanzati che consentano di incrementare sensibilmente il livello di ottimizzazione complessiva dell\u2019energia. Elementi fondamentali per valorizzare il contributo del digitale sono per\u00f2 la disponibilit\u00e0 di dati accurati e sufficienti, una governance che garantisca l\u2019applicazione efficace della tecnologia e il coordinamento tra settori per garantire l\u2019efficienza complessiva. L\u2019utilizzo di strumenti di Intelligenza Artificiale in ambito di ottimizzazione energetica potrebbe, inoltre, fungere da \u201ctest bed\u201d per lo sviluppo digitale della PA grazie alla natura dei dati energetici, che non presentano gli stessi vincoli dei dati personali ed alla presenza di use case di ottimizzazione energetica che possono essere integrati nello sviluppo di PPP. <\/p>\n<p>\u2013 foto ufficio stampa Siram Veolia \u2013<br \/>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>CERNOBBIO (COMO) (ITALPRESS) \u2013 In un contesto in cui \u00e8 necessario accelerare il percorso di decarbonizzazione, l\u2019ottimizzazione energetica \u2013 intesa come la combinazione di efficienza energetica, rinnovabili, fuel switch, storage, flessibilit\u00e0, condivisione e aggregazione di energia distribuita \u2013 e l\u2019adozione di strumenti digitali avanzati sono leve essenziali per la transizione energetica, la salvaguardia della competitivit\u00e0 [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":34257,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1129],"tags":[],"class_list":["post-34256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Studio Siram Veolia, sistema energetico italiano meno competitivo in Ue - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2024\/09\/06\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Studio Siram Veolia, sistema energetico italiano meno competitivo in Ue - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"CERNOBBIO (COMO) (ITALPRESS) \u2013 In un contesto in cui \u00e8 necessario accelerare il percorso di decarbonizzazione, l\u2019ottimizzazione energetica \u2013 intesa come la combinazione di efficienza energetica, rinnovabili, fuel switch, storage, flessibilit\u00e0, condivisione e aggregazione di energia distribuita \u2013 e l\u2019adozione di strumenti digitali avanzati sono leve essenziali per la transizione energetica, la salvaguardia della competitivit\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2024\/09\/06\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-06T16:03:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/09\\\/06\\\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/09\\\/06\\\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Studio Siram Veolia, sistema energetico italiano meno competitivo in Ue\",\"datePublished\":\"2024-09-06T16:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/09\\\/06\\\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\\\/\"},\"wordCount\":919,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/09\\\/06\\\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/20240906_0878.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/09\\\/06\\\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/09\\\/06\\\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\\\/\",\"name\":\"Studio Siram Veolia, sistema energetico italiano meno competitivo in Ue - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/09\\\/06\\\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/09\\\/06\\\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/20240906_0878.jpg\",\"datePublished\":\"2024-09-06T16:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/09\\\/06\\\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/09\\\/06\\\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/09\\\/06\\\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/20240906_0878.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/20240906_0878.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/09\\\/06\\\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Studio Siram Veolia, sistema energetico italiano meno competitivo in Ue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Studio Siram Veolia, sistema energetico italiano meno competitivo in Ue - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2024\/09\/06\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\/","og_locale":"it_IT","og_type":"article","og_title":"Studio Siram Veolia, sistema energetico italiano meno competitivo in Ue - Live Magazine","og_description":"CERNOBBIO (COMO) (ITALPRESS) \u2013 In un contesto in cui \u00e8 necessario accelerare il percorso di decarbonizzazione, l\u2019ottimizzazione energetica \u2013 intesa come la combinazione di efficienza energetica, rinnovabili, fuel switch, storage, flessibilit\u00e0, condivisione e aggregazione di energia distribuita \u2013 e l\u2019adozione di strumenti digitali avanzati sono leve essenziali per la transizione energetica, la salvaguardia della competitivit\u00e0 [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2024\/09\/06\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2024-09-06T16:03:52+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2024\/09\/06\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/09\/06\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Studio Siram Veolia, sistema energetico italiano meno competitivo in Ue","datePublished":"2024-09-06T16:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/09\/06\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\/"},"wordCount":919,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/09\/06\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/09\/20240906_0878.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2024\/09\/06\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\/","url":"https:\/\/www.livemag.it\/index.php\/2024\/09\/06\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\/","name":"Studio Siram Veolia, sistema energetico italiano meno competitivo in Ue - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/09\/06\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/09\/06\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/09\/20240906_0878.jpg","datePublished":"2024-09-06T16:03:52+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/09\/06\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2024\/09\/06\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2024\/09\/06\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/09\/20240906_0878.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/09\/20240906_0878.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2024\/09\/06\/studio-siram-veolia-sistema-energetico-italiano-meno-competitivo-in-ue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Studio Siram Veolia, sistema energetico italiano meno competitivo in Ue"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/09\/20240906_0878.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/34256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=34256"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/34256\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/34257"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=34256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=34256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=34256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}