{"id":32487,"date":"2024-08-07T15:02:56","date_gmt":"2024-08-07T13:02:56","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2024\/08\/07\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\/"},"modified":"2024-08-07T15:02:56","modified_gmt":"2024-08-07T13:02:56","slug":"scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2024\/08\/07\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\/","title":{"rendered":"Scuola, Valditara \u201cBisogna lottare contro il bullismo e la prepotenza\u201d"},"content":{"rendered":"<div>\n<p>ROMA (ITALPRESS) \u2013 \u201cBisogna lottare affinch\u00e8 nelle scuole ci sia la cultura del rispetto. I bulli sono figli di un padre e di una madre e il bullismo va contrastato prima nelle famiglie e poi nella scuola. Proprio in queste ore \u00e8 stato inserito nelle linee guida sull\u2019educazione civica. Ritorna il voto di condotta, perch\u00e8 il voto di condotta significa assumersi delle responsabilit\u00e0 e il bullismo \u00e8 una piaga drammatica\u201d. Lo ha detto il ministro dell\u2019Istruzione e del Merito, Giuseppe Valditara, ad Agor\u00e0 Estate su Rai 3. \u201cBisogna ripensare anche al sistema delle sospensioni. La scuola deve essere punto di riferimento, non soltanto per lo studio  ma anche per lo sport e le attivit\u00e0 ricreative \u2013 ha aggiunto -. La riforma prevista del 4+2 significa dare una opportunit\u00e0 formativa di successo ai giovani e per le imprese essere pi\u00f9 competitive\u201d.<\/p>\n<p>\u2013 foto: Agenzia Fotogramma \u2013<br \/>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) \u2013 \u201cBisogna lottare affinch\u00e8 nelle scuole ci sia la cultura del rispetto. I bulli sono figli di un padre e di una madre e il bullismo va contrastato prima nelle famiglie e poi nella scuola. Proprio in queste ore \u00e8 stato inserito nelle linee guida sull\u2019educazione civica. Ritorna il voto di condotta, perch\u00e8 [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":32488,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-32487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Scuola, Valditara \u201cBisogna lottare contro il bullismo e la prepotenza\u201d - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2024\/08\/07\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scuola, Valditara \u201cBisogna lottare contro il bullismo e la prepotenza\u201d - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"ROMA (ITALPRESS) \u2013 \u201cBisogna lottare affinch\u00e8 nelle scuole ci sia la cultura del rispetto. I bulli sono figli di un padre e di una madre e il bullismo va contrastato prima nelle famiglie e poi nella scuola. Proprio in queste ore \u00e8 stato inserito nelle linee guida sull\u2019educazione civica. Ritorna il voto di condotta, perch\u00e8 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2024\/08\/07\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-07T13:02:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/08\\\/07\\\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/08\\\/07\\\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Scuola, Valditara \u201cBisogna lottare contro il bullismo e la prepotenza\u201d\",\"datePublished\":\"2024-08-07T13:02:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/08\\\/07\\\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\\\/\"},\"wordCount\":150,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/08\\\/07\\\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/20240807_0370.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/08\\\/07\\\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/08\\\/07\\\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\\\/\",\"name\":\"Scuola, Valditara \u201cBisogna lottare contro il bullismo e la prepotenza\u201d - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/08\\\/07\\\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/08\\\/07\\\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/20240807_0370.jpg\",\"datePublished\":\"2024-08-07T13:02:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/08\\\/07\\\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/08\\\/07\\\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/08\\\/07\\\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/20240807_0370.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/20240807_0370.jpg\",\"width\":1024,\"height\":686},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/08\\\/07\\\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Scuola, Valditara \u201cBisogna lottare contro il bullismo e la prepotenza\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scuola, Valditara \u201cBisogna lottare contro il bullismo e la prepotenza\u201d - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2024\/08\/07\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\/","og_locale":"it_IT","og_type":"article","og_title":"Scuola, Valditara \u201cBisogna lottare contro il bullismo e la prepotenza\u201d - Live Magazine","og_description":"ROMA (ITALPRESS) \u2013 \u201cBisogna lottare affinch\u00e8 nelle scuole ci sia la cultura del rispetto. I bulli sono figli di un padre e di una madre e il bullismo va contrastato prima nelle famiglie e poi nella scuola. Proprio in queste ore \u00e8 stato inserito nelle linee guida sull\u2019educazione civica. Ritorna il voto di condotta, perch\u00e8 [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2024\/08\/07\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2024-08-07T13:02:56+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2024\/08\/07\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/08\/07\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Scuola, Valditara \u201cBisogna lottare contro il bullismo e la prepotenza\u201d","datePublished":"2024-08-07T13:02:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/08\/07\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\/"},"wordCount":150,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/08\/07\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/08\/20240807_0370.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2024\/08\/07\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\/","url":"https:\/\/www.livemag.it\/index.php\/2024\/08\/07\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\/","name":"Scuola, Valditara \u201cBisogna lottare contro il bullismo e la prepotenza\u201d - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/08\/07\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/08\/07\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/08\/20240807_0370.jpg","datePublished":"2024-08-07T13:02:56+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/08\/07\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2024\/08\/07\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2024\/08\/07\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/08\/20240807_0370.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/08\/20240807_0370.jpg","width":1024,"height":686},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2024\/08\/07\/scuola-valditara-bisogna-lottare-contro-il-bullismo-e-la-prepotenza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Scuola, Valditara \u201cBisogna lottare contro il bullismo e la prepotenza\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/08\/20240807_0370.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/32487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=32487"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/32487\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/32488"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=32487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=32487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=32487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}