{"id":31127,"date":"2024-07-18T18:02:33","date_gmt":"2024-07-18T16:02:33","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2024\/07\/18\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\/"},"modified":"2024-07-18T18:02:33","modified_gmt":"2024-07-18T16:02:33","slug":"pedemontana-di-palermo-celia-tre-ipotesi-progettuali","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2024\/07\/18\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\/","title":{"rendered":"<div>Pedemontana di Palermo, Celia &#8220;Tre ipotesi progettuali&#8221;<\/div>"},"content":{"rendered":"<p>    <video-js id=\"videojs6a98580a900b3\" class=\"vjs-big-play-centered\" controls preload=\"auto\" playsinline data-setup='{\"fluid\": true}'>\r\n        <source src=\"https:\/\/video.italpress.com\/play\/mp4\/video\/rV3K\" type=\"video\/mp4\" \/>\r\n    <\/video-js>\r\n           <br \/>\n<\/p>\n<div> PALERMO (ITALPRESS) &#8211; &#8220;Su questo corridoio sono state studiate tre possibili soluzioni concettuali. Essenzialmente si differenziano l&#8217;una dall&#8217;altra da quanto tracciato \u00e8 stato posto in galleria piuttosto che in superficie&#8221;. Lo ha detto il responsabile della struttura territoriale Anas in Sicilia Raffaele Celia, a margine del dibattito pubblico sulla Pedemontana di Palermo. <\/p>\n<p>xd8\/pc\/gtr<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>PALERMO (ITALPRESS) &#8211; &#8220;Su questo corridoio sono state studiate tre possibili soluzioni concettuali. Essenzialmente si differenziano l&#8217;una dall&#8217;altra da quanto tracciato \u00e8 stato posto in galleria piuttosto che in superficie&#8221;. Lo ha detto il responsabile della struttura territoriale Anas in Sicilia Raffaele Celia, a margine del dibattito pubblico sulla Pedemontana di Palermo. xd8\/pc\/gtr<\/p>\n","protected":false},"author":16,"featured_media":31128,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1171],"tags":[],"class_list":["post-31127","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-video","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pedemontana di Palermo, Celia &quot;Tre ipotesi progettuali&quot; - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2024\/07\/18\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pedemontana di Palermo, Celia &quot;Tre ipotesi progettuali&quot; - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"PALERMO (ITALPRESS) &#8211; &#8220;Su questo corridoio sono state studiate tre possibili soluzioni concettuali. Essenzialmente si differenziano l&#8217;una dall&#8217;altra da quanto tracciato \u00e8 stato posto in galleria piuttosto che in superficie&#8221;. Lo ha detto il responsabile della struttura territoriale Anas in Sicilia Raffaele Celia, a margine del dibattito pubblico sulla Pedemontana di Palermo. xd8\/pc\/gtr\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2024\/07\/18\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-18T16:02:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/18\\\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/18\\\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Pedemontana di Palermo, Celia &#8220;Tre ipotesi progettuali&#8221;\",\"datePublished\":\"2024-07-18T16:02:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/18\\\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\\\/\"},\"wordCount\":75,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/18\\\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/rV3K.jpg\",\"articleSection\":[\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/18\\\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/18\\\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\\\/\",\"name\":\"Pedemontana di Palermo, Celia \\\"Tre ipotesi progettuali\\\" - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/18\\\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/18\\\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/rV3K.jpg\",\"datePublished\":\"2024-07-18T16:02:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/18\\\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/18\\\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/18\\\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/rV3K.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/rV3K.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/18\\\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pedemontana di Palermo, Celia &#8220;Tre ipotesi progettuali&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pedemontana di Palermo, Celia \"Tre ipotesi progettuali\" - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2024\/07\/18\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\/","og_locale":"it_IT","og_type":"article","og_title":"Pedemontana di Palermo, Celia \"Tre ipotesi progettuali\" - Live Magazine","og_description":"PALERMO (ITALPRESS) &#8211; &#8220;Su questo corridoio sono state studiate tre possibili soluzioni concettuali. Essenzialmente si differenziano l&#8217;una dall&#8217;altra da quanto tracciato \u00e8 stato posto in galleria piuttosto che in superficie&#8221;. Lo ha detto il responsabile della struttura territoriale Anas in Sicilia Raffaele Celia, a margine del dibattito pubblico sulla Pedemontana di Palermo. xd8\/pc\/gtr","og_url":"https:\/\/www.livemag.it\/index.php\/2024\/07\/18\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2024-07-18T16:02:33+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/18\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/18\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Pedemontana di Palermo, Celia &#8220;Tre ipotesi progettuali&#8221;","datePublished":"2024-07-18T16:02:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/18\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\/"},"wordCount":75,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/18\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/rV3K.jpg","articleSection":["Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/18\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\/","url":"https:\/\/www.livemag.it\/index.php\/2024\/07\/18\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\/","name":"Pedemontana di Palermo, Celia \"Tre ipotesi progettuali\" - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/18\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/18\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/rV3K.jpg","datePublished":"2024-07-18T16:02:33+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/18\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2024\/07\/18\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/18\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/rV3K.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/rV3K.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/18\/pedemontana-di-palermo-celia-tre-ipotesi-progettuali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Pedemontana di Palermo, Celia &#8220;Tre ipotesi progettuali&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/rV3K.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/31127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=31127"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/31127\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/31128"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=31127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=31127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=31127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}