{"id":31059,"date":"2024-07-17T21:02:30","date_gmt":"2024-07-17T19:02:30","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2024\/07\/17\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\/"},"modified":"2024-07-17T21:02:30","modified_gmt":"2024-07-17T19:02:30","slug":"il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2024\/07\/17\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\/","title":{"rendered":"Il Milan in festa per i 125 anni con tre partite e una maglia speciale"},"content":{"rendered":"<p>    <video-js id=\"videojs6a987cf330f5e\" class=\"vjs-big-play-centered\" controls preload=\"auto\" playsinline data-setup='{\"fluid\": true}'>\r\n        <source src=\"https:\/\/video.italpress.com\/play\/mp4\/video\/n61E\" type=\"video\/mp4\" \/>\r\n    <\/video-js>\r\n           <br \/>\n<\/p>\n<div> MILANO (ITALPRESS) &#8211; Una festa per celebrare la storia di un club che ha segnato il calcio italiano ed europeo e si appresta a scrivere pagine sempre pi\u00f9 appassionanti della sua storia. Un racconto che parte nella notte del 16 dicembre 1899 all\u2019Hotel du Nord et des Anglais di Piazza della Repubblica, a Milano, dal sogno visionario dell\u2019inglese Herbert Kilpin e di un piccolo gruppo di appassionati amici, fino ad arrivare ai giorni nostri. All\u2019evento, tenutosi nel cuore di Milano, hanno partecipato protagonisti del passato, presente e futuro del Club rossonero, che negli ultimi 125 anni ha attraversato epoche di cambiamento, con spirito pionieristico e senza perdere la propria essenza. Il Milan ha inaugurato la stagione del 125\u00b0 anniversario del club presentando le iniziative dedicate, a partire dalle amichevoli estive. Tre gli appuntamenti in estate: si parte a Vienna contro il Rapid, il 20 luglio e all\u2019M&amp;T Stadium di Baltimora contro Barcellona il 7 agosto, due formazioni storiche del calcio internazionale che festeggiano quest\u2019anno lo stesso traguardo dei 125 anni. Si prosegue il 13 agosto, prima dell&#8217;esordio in campionato, con la seconda edizione del \u201cTrofeo Silvio Berlusconi\u201d, che per la prima volta si disputer\u00e0 a San Siro contro il Monza. Diverse le iniziative benefiche che verranno organizzate da Fondazione Milan. A dicembre invece le due squadre rossonere, quella maschile e quella femminile, indosseranno una maglia speciale creata insieme ai tifosi, un modo per poter rinsaldare un legame unico a tinte rossonere che dura ormai da 125 anni.<\/p>\n<p>col\/pia\/gm\/gtr<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>MILANO (ITALPRESS) &#8211; Una festa per celebrare la storia di un club che ha segnato il calcio italiano ed europeo e si appresta a scrivere pagine sempre pi\u00f9 appassionanti della sua storia. Un racconto che parte nella notte del 16 dicembre 1899 all\u2019Hotel du Nord et des Anglais di Piazza della Repubblica, a Milano, dal [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":31060,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1171],"tags":[],"class_list":["post-31059","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-video","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Milan in festa per i 125 anni con tre partite e una maglia speciale - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2024\/07\/17\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Milan in festa per i 125 anni con tre partite e una maglia speciale - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"MILANO (ITALPRESS) &#8211; Una festa per celebrare la storia di un club che ha segnato il calcio italiano ed europeo e si appresta a scrivere pagine sempre pi\u00f9 appassionanti della sua storia. Un racconto che parte nella notte del 16 dicembre 1899 all\u2019Hotel du Nord et des Anglais di Piazza della Repubblica, a Milano, dal [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2024\/07\/17\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-17T19:02:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/17\\\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/17\\\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Il Milan in festa per i 125 anni con tre partite e una maglia speciale\",\"datePublished\":\"2024-07-17T19:02:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/17\\\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\\\/\"},\"wordCount\":276,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/17\\\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/n61E.jpg\",\"articleSection\":[\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/17\\\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/17\\\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\\\/\",\"name\":\"Il Milan in festa per i 125 anni con tre partite e una maglia speciale - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/17\\\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/17\\\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/n61E.jpg\",\"datePublished\":\"2024-07-17T19:02:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/17\\\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/17\\\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/17\\\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/n61E.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/n61E.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/17\\\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Milan in festa per i 125 anni con tre partite e una maglia speciale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Milan in festa per i 125 anni con tre partite e una maglia speciale - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2024\/07\/17\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\/","og_locale":"it_IT","og_type":"article","og_title":"Il Milan in festa per i 125 anni con tre partite e una maglia speciale - Live Magazine","og_description":"MILANO (ITALPRESS) &#8211; Una festa per celebrare la storia di un club che ha segnato il calcio italiano ed europeo e si appresta a scrivere pagine sempre pi\u00f9 appassionanti della sua storia. Un racconto che parte nella notte del 16 dicembre 1899 all\u2019Hotel du Nord et des Anglais di Piazza della Repubblica, a Milano, dal [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2024\/07\/17\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2024-07-17T19:02:30+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/17\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/17\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Il Milan in festa per i 125 anni con tre partite e una maglia speciale","datePublished":"2024-07-17T19:02:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/17\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\/"},"wordCount":276,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/17\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/n61E.jpg","articleSection":["Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/17\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\/","url":"https:\/\/www.livemag.it\/index.php\/2024\/07\/17\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\/","name":"Il Milan in festa per i 125 anni con tre partite e una maglia speciale - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/17\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/17\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/n61E.jpg","datePublished":"2024-07-17T19:02:30+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/17\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2024\/07\/17\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/17\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/n61E.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/n61E.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/17\/il-milan-in-festa-per-i-125-anni-con-tre-partite-e-una-maglia-speciale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Il Milan in festa per i 125 anni con tre partite e una maglia speciale"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/n61E.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/31059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=31059"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/31059\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/31060"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=31059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=31059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=31059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}