{"id":30301,"date":"2024-07-08T18:01:48","date_gmt":"2024-07-08T16:01:48","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\/"},"modified":"2024-07-08T18:01:48","modified_gmt":"2024-07-08T16:01:48","slug":"eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\/","title":{"rendered":"Eventi climatici estremi, da Fondazione Cariplo bando da 3 milioni"},"content":{"rendered":"<div>\n<p>MILANO (ITALPRESS) \u2013 Non si pu\u00f2 pi\u00f9 attendere. Gli effetti degli eventi estremi, sempre pi\u00f9 frequenti, sono sotto gli occhi di tutti. Fondazione Cariplo propone un nuovo Bando \u201cTerritori Sicuri \u2013 Studiare soluzioni innovative per le comunit\u00e0 a rischio frane o alluvioni\u201d. A disposizione 3 milioni di euro destinati a finanziare progetti e ricerche a livello locale per sviluppare e favorire l\u2019adozione di soluzioni e strategie innovative contro il dissesto idrogeologico.<br \/>Questo strumento fa parte di un intervento pluriennale pi\u00f9 ampio, articolato in due fasi. Nella prima fase, saranno selezionati e sostenuti progetti pilota che svilupperanno soluzioni e strategie innovative per affrontare il rischio di frane e alluvioni in siti sperimentali. Dopo un attento monitoraggio, nella seconda fase saranno sostenuti progetti fellow per estendere le soluzioni di maggior successo in contesti diversi. <br \/>La Fondazione si avvarr\u00e0 anche del supporto delle Fondazioni di Comunit\u00e0 per l\u2019implementazione dell\u2019intervento, antenne sui territori capaci di intercettare situazioni di pericolo e di individuare interventi urgenti da realizzare.<br \/>Per la sua posizione geografica e le caratteristiche morfologiche, l\u2019Italia \u00e8 particolarmente suscettibile a eventi di dissesto idrogeologico, come frane e alluvioni. Nel nostro Paese, 7.423 comuni (93,9% del totale) sono a rischio frane, alluvioni e\/o erosione costiera. Il 18,4% del territorio nazionale \u00e8 classificato a maggiore pericolosit\u00e0 per frane e alluvioni, con 1,3 milioni di abitanti a rischio frane e 6,8 milioni a rischio alluvioni.<br \/>Questi fenomeni causano danni economici significativi, compromettendo attivit\u00e0 agricole, industriali e commerciali, la funzionalit\u00e0 delle infrastrutture e l\u2019agibilit\u00e0 dei complessi residenziali, impattando fortemente sulla popolazione sia in termini di perdite di vite umane che di effetti sulla sfera emotiva.<br \/>I cambiamenti climatici, l\u2019urbanizzazione non sostenibile, la gestione inadeguata delle risorse idriche e la debolezza delle infrastrutture aggravano ulteriormente gli effetti del dissesto idrogeologico. La gestione dei rischi legati a frane e alluvioni richiede una visione integrata che consideri la morfologia del territorio, l\u2019urbanizzazione e le infrastrutture presenti. Una strategia efficace combina misure preventive e di risposta per proteggere al meglio i territori esposti a tali rischi.<br \/>In questo contesto, Fondazione Cariplo ha pensato al coinvolgimento attivo delle comunit\u00e0 locali, un coinvolgimento cruciale per garantire l\u2019efficacia e la sostenibilit\u00e0 delle misure di protezione, creando un senso di responsabilit\u00e0 condivisa e una maggiore resilienza sociale di fronte ai rischi idrogeologici.<br \/>Stimolare una partecipazione attiva e consapevole delle comunit\u00e0 locali pu\u00f2 fare la differenza nella riduzione degli impatti del dissesto idrogeologico sui territori.<br \/>\u201cNon possiamo attendere. Gli effetti degli eventi estremi, sempre pi\u00f9 frequenti, sono sotto gli occhi di tutti. Dobbiamo cercare soluzioni concrete, a partire da una profonda attivit\u00e0 di ricerca. L\u2019idea e che si creino delle task force a livello locale che partano da situazioni specifiche e che diano risposte puntuali. Tecnologia, ricerca, attenzione al territorio sono i pilastri su cui poggia questa iniziativa. Con il fondamentale supporto delle fondazioni di Comunit\u00e0, intendiamo realizzare interventi per la prevenzione, salvaguardia dei luoghi e delle persone\u201d, ha detto il presidente di Fondazione Cariplo, Giovanni Azzone.<br \/>Il bando si rivolge a partenariati multistakeholder, che devono includere almeno un ente di ricerca e un ente pubblico locale, capaci di mobilitare tutte le competenze e le sensibilit\u00e0 necessarie per migliorare il benessere e la sicurezza delle comunit\u00e0. La scadenza per la presentazione delle domande \u00e8 il 25 settembre 2024.<\/p>\n<p>\u2013 Foto Agenzia Fotogramma \u2013<\/p>\n<p>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>MILANO (ITALPRESS) \u2013 Non si pu\u00f2 pi\u00f9 attendere. Gli effetti degli eventi estremi, sempre pi\u00f9 frequenti, sono sotto gli occhi di tutti. Fondazione Cariplo propone un nuovo Bando \u201cTerritori Sicuri \u2013 Studiare soluzioni innovative per le comunit\u00e0 a rischio frane o alluvioni\u201d. A disposizione 3 milioni di euro destinati a finanziare progetti e ricerche a [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":30302,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-30301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eventi climatici estremi, da Fondazione Cariplo bando da 3 milioni - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eventi climatici estremi, da Fondazione Cariplo bando da 3 milioni - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"MILANO (ITALPRESS) \u2013 Non si pu\u00f2 pi\u00f9 attendere. Gli effetti degli eventi estremi, sempre pi\u00f9 frequenti, sono sotto gli occhi di tutti. Fondazione Cariplo propone un nuovo Bando \u201cTerritori Sicuri \u2013 Studiare soluzioni innovative per le comunit\u00e0 a rischio frane o alluvioni\u201d. A disposizione 3 milioni di euro destinati a finanziare progetti e ricerche a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-08T16:01:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Eventi climatici estremi, da Fondazione Cariplo bando da 3 milioni\",\"datePublished\":\"2024-07-08T16:01:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\\\/\"},\"wordCount\":551,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/20240708_0821.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\\\/\",\"name\":\"Eventi climatici estremi, da Fondazione Cariplo bando da 3 milioni - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/20240708_0821.jpg\",\"datePublished\":\"2024-07-08T16:01:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/20240708_0821.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/20240708_0821.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi climatici estremi, da Fondazione Cariplo bando da 3 milioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eventi climatici estremi, da Fondazione Cariplo bando da 3 milioni - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\/","og_locale":"it_IT","og_type":"article","og_title":"Eventi climatici estremi, da Fondazione Cariplo bando da 3 milioni - Live Magazine","og_description":"MILANO (ITALPRESS) \u2013 Non si pu\u00f2 pi\u00f9 attendere. Gli effetti degli eventi estremi, sempre pi\u00f9 frequenti, sono sotto gli occhi di tutti. Fondazione Cariplo propone un nuovo Bando \u201cTerritori Sicuri \u2013 Studiare soluzioni innovative per le comunit\u00e0 a rischio frane o alluvioni\u201d. A disposizione 3 milioni di euro destinati a finanziare progetti e ricerche a [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2024-07-08T16:01:48+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Eventi climatici estremi, da Fondazione Cariplo bando da 3 milioni","datePublished":"2024-07-08T16:01:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\/"},"wordCount":551,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/20240708_0821.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\/","url":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\/","name":"Eventi climatici estremi, da Fondazione Cariplo bando da 3 milioni - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/20240708_0821.jpg","datePublished":"2024-07-08T16:01:48+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/20240708_0821.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/20240708_0821.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/eventi-climatici-estremi-da-fondazione-cariplo-bando-da-3-milioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Eventi climatici estremi, da Fondazione Cariplo bando da 3 milioni"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/20240708_0821.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/30301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=30301"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/30301\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/30302"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=30301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=30301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=30301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}