{"id":30289,"date":"2024-07-08T15:01:40","date_gmt":"2024-07-08T13:01:40","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\/"},"modified":"2024-07-08T15:01:40","modified_gmt":"2024-07-08T13:01:40","slug":"intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\/","title":{"rendered":"Intesa Sanpaolo, 10 miliardi di nuovo credito per il turismo"},"content":{"rendered":"<div>\n<p>TAORMINA (MESSINA) (ITALPRESS) \u2013 <a href=\"https:\/\/group.intesasanpaolo.com\/it\/\">Intesa Sanpaolo<\/a> presenter\u00e0 il 9 luglio a Taormina le nuove misure dedicate allo sviluppo dell\u2019industria turistica, vitale per l\u2019economia italiana e meridionale, per affiancare la crescita delle imprese del settore e cogliere le opportunit\u00e0 previste da PNRR e iniziative ministeriali.<br \/>\nLa prima banca italiana rinnova il proprio impegno per il turismo con 10 miliardi di euro di nuovo credito, di cui 3 miliardi destinati alle aziende del Mezzogiorno, che si aggiungono a circa 9 miliardi di liquidit\u00e0 gi\u00e0 erogati al comparto dal 2020. Questo nuovo intervento a favore delle imprese turistiche si inserisce tra le leve previste nel programma \u201cIl tuo futuro \u00e8 la nostra impresa\u201d della Divisione Banca dei Territori guidata da Stefano Barrese, che destina 120 miliardi di euro fino al 2026 per gli investimenti delle aziende italiane e dedica un sostegno specifico al Turismo e all\u2019Agribusiness, settori strategici per l\u2019economia del Paese.<br \/>\nProprio il rapporto esistente tra Banca, imprese turistiche e aziende agroalimentari \u2013 con queste ultime attraverso la Direzione Agribusiness, rete commerciale loro dedicata \u2013 concorre a far emergere nuove sinergie e potenzialit\u00e0 tra questi settori, con filiere sempre pi\u00f9 complementari. Secondo le analisi di SRM su dati del Rapporto sul Turismo Enogastronomico Italiano relative allo scorso anno, in Italia i turisti enogastronomici rappresentano il 58% del totale, dato in crescita rispetto al 45% registrato nel 2019.<br \/>\nRicerca di qualit\u00e0, esperienza distintiva e servizi aggiuntivi emergono come elementi comuni di competitivit\u00e0 e molte imprese agroalimentari ed enogastronomiche crescono attraverso un\u2019offerta di prodotti collegata a percorsi identitari, culturali e di territorio facilmente coniugabili alla ricettivit\u00e0 turistica.<br \/>\nIl plafond di 10 miliardi di euro incentiver\u00e0 nuovi investimenti in chiave Transizione 5.0, competitivit\u00e0 sostenibile ed efficientamento energetico lungo tre assi: riqualificazione e aumento degli standard qualitativi delle strutture, sostenibilit\u00e0 ambientale dell\u2019offerta e digitalizzazione del modello di servizio.<br \/>\nLe misure messe in campo dal Gruppo saranno illustrate nella splendida cornice dei Giardini Naxos nel corso di un convegno in cui, per Intesa Sanpaolo, interverranno Stefano Barrese, responsabile Divisione Banca dei Territori, Gaetano Miccich\u00e8, chairman Divisione IMI Corporate &amp; Investment Banking e chairman International Subsidiary Banks Division, e Giuseppe Nargi, direttore regionale Campania, Calabria e Sicilia, cui sar\u00e0 affidata l\u2019apertura dei lavori. Il contributo di Massimo Deandreis, direttore generale di SRM, evidenzier\u00e0 le prospettive di crescita del settore turistico. A seguire, in una tavola rotonda si confronteranno Rosario Di Maria, presidente Cantine Ermes, Nicola Fiasconaro, amministratore Fiasconaro, Costanza Giotti, presidente Gruppo Luxury Private Properties, Andrea Mangia, chief financial officer Gruppo Mangi\u00e0s, e Pasqualino Monti, amministratore delegato ENAV e presidente Autorit\u00e0 Portuale di Palermo.<br \/>\nCultura, ambiente, mare, identit\u00e0, socialit\u00e0, stile di vita, accoglienza ed enogastronomia rendono la destinazione Italia quasi unica nel panorama competitivo internazionale in tema di attrazione turistica.<br \/>\nDall\u2019analisi di SRM \u2013 Centro Studi collegato a Intesa Sanpaolo, si evidenzia, non a caso, che nella classifica europea per numerosit\u00e0 di arrivi e presenze turistiche totali, il nostro Paese si posiziona al 4\u00b0 posto con 133,6 milioni di arrivi, mentre sale al 3\u00b0 posto se si considerano i giorni di presenza, ben 447,1 milioni.<br \/>\nNel contesto nazionale, il Mezzogiorno esprime poco meno del 20% di arrivi e presenze. L\u2019attrattivit\u00e0 turistica si trasforma in una ricchezza economica rilevante per l\u2019economia del Paese. Si stima che nel 2024 il settore turistico possa generare un valore aggiunto di circa 103,6 miliardi di euro, con un contributo al Pil del 5,9% che arriva al 10,8% se si include anche l\u2019impatto indiretto ed indotto. Il 24% del Pil turistico nazionale \u00e8 prodotto nel Sud Italia. Nello specifico, si rileva, per quest\u2019area, un valore aggiunto turistico di 24,9 miliardi di euro, il 6,4% del Pil, che sale all\u201911,6% se si considera l\u2019impatto complessivo. Pertanto, il Mezzogiorno si caratterizza per una maggiore specializzazione economica in questo settore rispetto al resto del Paese.<br \/>\nSignificativa \u00e8 anche la sua valenza sociale. In termini di occupazione, il settore turistico italiano impiega oggi quasi 1.300.000 lavoratori con circa 200.000 aziende che hanno almeno un dipendente. Al Sud si concentra il 26,4% dell\u2019occupazione turistica nazionale (ben 340.585 addetti) ed il 31% delle imprese (60.936). Il turismo pu\u00f2 contare su una forza lavoro sostanzialmente giovane (circa il 58,7% dei dipendenti ha meno di quarant\u2019anni e il 36,2% meno di 30) e in prevalenza femminile (52,3%).<br \/>\nIntesa Sanpaolo ha intensificato il supporto alle imprese turistiche durante e dopo la pandemia, venendo in aiuto alle migliaia di aziende in estrema difficolt\u00e0 dopo le chiusure forzate: garantita liquidit\u00e0 attraverso un\u2019iniziativa straordinaria di moratorie estese fino a 36 mesi, accogliendo oltre 70.000 richieste di sospensione di pagamenti per un debito residuo di oltre 8,4 miliardi, di cui circa il 26% nel Mezzogiorno.<br \/>\nTra le misure destinate al settore, le soluzioni di finanziamento S-Loan che prevedono un meccanismo di incentivi economici alle imprese che investono e realizzano obiettivi ESG. Intesa Sanpaolo ha inoltre aderito al fondo tematico per il turismo tramite Equiter, con risorse amministrate dalla BEI per conto del MEF e indirizzate alle imprese. Il Gruppo infine prevede soluzioni di noleggio operativo per avviare programmi di ammodernamento delle strutture, consentendo quindi di preservare l\u2019equilibrio finanziario delle PMI.<br \/>\n\u201cCome banca di riferimento dei principali settori del Paese, rinnoviamo il nostro sostegno all\u2019industria turistica, la cui crescita \u00e8 determinante per rafforzare strutturalmente l\u2019economia italiana \u2013 afferma Stefano Barrese, responsabile Divisione Banca dei Territori di Intesa Sanpaolo (nella foto) -. Il percorso intrapreso in questi ultimi anni dalle imprese del comparto verso sostenibilit\u00e0, digitalizzazione e innalzamento degli standard qualitativi delle strutture mostra risultati incoraggianti e deve proseguire con maggior intensit\u00e0 e diffusione, grazie al potenziale delle filiere del mondo enogastronomico. Intesa Sanpaolo mette a disposizione 10 miliardi di euro per incentivare nuovi investimenti, accompagnare i passaggi generazionali di queste aziende, favorendone anche la crescita dimensionale. Il nostro obiettivo, in linea con le direttrici del PNRR, \u00e8 accelerare i processi di transizione per agevolare una proposta di ospitalit\u00e0 pi\u00f9 efficiente per i bilanci delle imprese e di maggiore salvaguardia per il turismo e per l\u2019ambiente\u201d.<br \/>\nLa filiera turistica sta affrontando nuove e importanti sfide. Crisi geopolitiche, effetti climatici estremi, aumento dei costi e forte attenzione alla sostenibilit\u00e0. In un contesto quindi di un \u201cTurismo che Cambia e si Innova\u201d quest\u2019anno il Rapporto SRM evidenzia quanto sia rilevante puntare su un sistema d\u2019offerta improntato su: diversificazione, delocalizzazione, destagionalizzazione, digitalizzazione e dimensione d\u2019impresa. Le 5D che possono preservare e rafforzare la competitivit\u00e0 turistica dei territori.<br \/>\nDi seguito una fotografia del turismo nel Mezzogiorno: 86,1 milioni di notti trascorse (19% dell\u2019Italia), 3,5 giorni di permanenza media, 76,8% di stagionalit\u00e0 (presenze nei mesi estivi), 38,9% di presenze straniere (ancora in piena fase di recupero post covid). Un\u2019offerta negli alberghi \u2013 in termini di posti letto \u2013 pari al 28,8% dell\u2019Italia (sale al 37,9% nei 4 e 5 stelle) e del 23,1% in strutture extra-alberghiere. Un valore aggiunto pari a 24,9 miliardi di euro (24% del Paese). Nel 2024 si prevede nel Mezzogiorno il pieno recupero delle presenze turistiche. Rispetto al 2019 il dato \u00e8 stimato in crescita del 2,8% per un totale di quasi 89 milioni di notti trascorse. Proseguir\u00e0, con forte intensit\u00e0, la ripresa della domanda internazionale che si stima in crescita del 4,5% rispetto al 2023 superando pienamente il periodo pre-covid (105,4% rispetto al valore 2019).<br \/>\nIl turismo meridionale nel contesto europeo: ben posizionato ma con ampi margini di miglioramento.<br \/>\nDall\u2019analisi su 98 regioni dell\u2019area UE4 (Italia, Spagna, Francia e Germania) tre regioni del Sud (Sardegna, Campania e Puglia) sono tra le prime 30, e la Sicilia \u00e8 trentunesima, per livello di competitivit\u00e0 turistica e ben 6 comunque sono sopra la media europea. Ci sono spazi per crescere sia in termini quantitativi che qualitativi.<br \/>\nEmerge la necessit\u00e0 di migliorare ed ampliare la connessione internazionale e l\u2019accessibilit\u00e0 del territorio.<br \/>\nNel Sud l\u2019obiettivo deve essere un turismo che offra destinazioni sempre pi\u00f9 diversificate e di qualit\u00e0 al fine di favorire la destagionalizzazione, la delocalizzazione e l\u2019impatto economico sul territorio. Borghi, aree interne, zone di prossimit\u00e0 dei grandi attrattori turistici possono essere destinazioni di qualit\u00e0 (per la loro storia, per le loro tradizioni e il buon cibo) utili anche per ridurre gli effetti negativi ed i disagi derivanti dai fenomeni di congestionamento. L\u2019offerta turistica legata alla cultura, all\u2019enogastronomia, all\u2019ambiente ed al turismo business pu\u00f2 essere una combinazione vincente anche al Sud: il moltiplicatore delle presenze di un\u2019offerta cos\u00ec \u201cintegrata\u201d \u00e8 infatti superiore a quello monotematico ad es. di tipo balneare (156\u0080 rispetto a 128,2\u0080 di valore aggiunto per ogni notte trascorsa).<br \/>\nIn questo contesto sempre pi\u00f9 dinamico e sfidante, aumenta la consapevolezza delle imprese che investire \u00e8 l\u2019unica via per competere. Dalla survey di SRM, emerge che circa il 77% delle imprese turistiche del Sud nell\u2019ultimo triennio ha effettuato investimenti (in Italia il 76%). Grande attenzione in particolare alla qualit\u00e0 dei servizi e della recettivit\u00e0 (il 56% delle imprese intervistate ha rinnovato gli arredi e ampliato i servizi ricettivi).<br \/>\nSi guarda inoltre al futuro. Le imprese stanno comprendendo la sfida della digitalizzazione e della sostenibilit\u00e0 (ESG): 4 imprese su 10 nel Sud (25% in Italia) hanno investito su tali obiettivi che ad oggi nel solo Mezzogiorno si stimano essere pari a 300 milioni di euro. Le imprese indicano un\u2019ulteriore crescita di tali investimenti nel prossimo triennio di circa il 2%. Infine, semplificazione burocratica (37%), politiche per il decoro urbano (28%), diversificazione dell\u2019offerta (27%) ed una gestione pi\u00f9 efficiente dei servizi pubblici (24%) sono le principali priorit\u00e0 che le imprese del Sud pongono alla governance pubblica per favorire la competitivit\u00e0 del territorio.<\/p>\n<p>\u2013 Foto ufficio stampa Intesa Sanpaolo \u2013<\/p>\n<p>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>TAORMINA (MESSINA) (ITALPRESS) \u2013 Intesa Sanpaolo presenter\u00e0 il 9 luglio a Taormina le nuove misure dedicate allo sviluppo dell\u2019industria turistica, vitale per l\u2019economia italiana e meridionale, per affiancare la crescita delle imprese del settore e cogliere le opportunit\u00e0 previste da PNRR e iniziative ministeriali. La prima banca italiana rinnova il proprio impegno per il turismo [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":30290,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-30289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Intesa Sanpaolo, 10 miliardi di nuovo credito per il turismo - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intesa Sanpaolo, 10 miliardi di nuovo credito per il turismo - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"TAORMINA (MESSINA) (ITALPRESS) \u2013 Intesa Sanpaolo presenter\u00e0 il 9 luglio a Taormina le nuove misure dedicate allo sviluppo dell\u2019industria turistica, vitale per l\u2019economia italiana e meridionale, per affiancare la crescita delle imprese del settore e cogliere le opportunit\u00e0 previste da PNRR e iniziative ministeriali. La prima banca italiana rinnova il proprio impegno per il turismo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-08T13:01:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Intesa Sanpaolo, 10 miliardi di nuovo credito per il turismo\",\"datePublished\":\"2024-07-08T13:01:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\\\/\"},\"wordCount\":1531,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/20240708_0582.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\\\/\",\"name\":\"Intesa Sanpaolo, 10 miliardi di nuovo credito per il turismo - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/20240708_0582.jpg\",\"datePublished\":\"2024-07-08T13:01:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/20240708_0582.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/20240708_0582.jpg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intesa Sanpaolo, 10 miliardi di nuovo credito per il turismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Intesa Sanpaolo, 10 miliardi di nuovo credito per il turismo - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\/","og_locale":"it_IT","og_type":"article","og_title":"Intesa Sanpaolo, 10 miliardi di nuovo credito per il turismo - Live Magazine","og_description":"TAORMINA (MESSINA) (ITALPRESS) \u2013 Intesa Sanpaolo presenter\u00e0 il 9 luglio a Taormina le nuove misure dedicate allo sviluppo dell\u2019industria turistica, vitale per l\u2019economia italiana e meridionale, per affiancare la crescita delle imprese del settore e cogliere le opportunit\u00e0 previste da PNRR e iniziative ministeriali. La prima banca italiana rinnova il proprio impegno per il turismo [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2024-07-08T13:01:40+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Intesa Sanpaolo, 10 miliardi di nuovo credito per il turismo","datePublished":"2024-07-08T13:01:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\/"},"wordCount":1531,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/20240708_0582.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\/","url":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\/","name":"Intesa Sanpaolo, 10 miliardi di nuovo credito per il turismo - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/20240708_0582.jpg","datePublished":"2024-07-08T13:01:40+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/20240708_0582.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/20240708_0582.jpg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/intesa-sanpaolo-10-miliardi-di-nuovo-credito-per-il-turismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Intesa Sanpaolo, 10 miliardi di nuovo credito per il turismo"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/20240708_0582.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/30289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=30289"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/30289\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/30290"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=30289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=30289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=30289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}