{"id":30281,"date":"2024-07-08T15:01:26","date_gmt":"2024-07-08T13:01:26","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\/"},"modified":"2024-07-08T15:01:26","modified_gmt":"2024-07-08T13:01:26","slug":"shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\/","title":{"rendered":"<div>&#8220;Shukran&#8221;, al cinema la Siria dilaniata dalla guerra civile<\/div>"},"content":{"rendered":"<p>    <video-js id=\"videojs6a9862463c60f\" class=\"vjs-big-play-centered\" controls preload=\"auto\" playsinline data-setup='{\"fluid\": true}'>\r\n        <source src=\"https:\/\/video.italpress.com\/play\/mp4\/video\/PWqA\" type=\"video\/mp4\" \/>\r\n    <\/video-js>\r\n           <br \/>\n<\/p>\n<div> ROMA (ITALPRESS) &#8211; Nella Siria dilaniata dalla guerra civile, con il popolo che insorge contro il regime di Assad, un cardiochirurgo infantile si trover\u00e0 di fronte alla decisione pi\u00f9 difficile della sua vita. \u201cShukran\u201d, opera prima del regista Pietro Malegori, \u00e8 basato su una storia vera ed \u00e8 tratto dall\u2019omonimo libro di Giovanni Terzi edito da Piemme Mondadori. Il film \u00e8 stato girato in Puglia con il contributo di Apulia Film Fund di Apulia Film Commission e Regione Puglia e in associazione con Intesa Sanpaolo, e arriva al cinema l\u20198, il 9 e il 10 luglio con Eagle Pictures. <\/p>\n<p>sat\/gsl<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) &#8211; Nella Siria dilaniata dalla guerra civile, con il popolo che insorge contro il regime di Assad, un cardiochirurgo infantile si trover\u00e0 di fronte alla decisione pi\u00f9 difficile della sua vita. \u201cShukran\u201d, opera prima del regista Pietro Malegori, \u00e8 basato su una storia vera ed \u00e8 tratto dall\u2019omonimo libro di Giovanni Terzi edito [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":30282,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1171],"tags":[],"class_list":["post-30281","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-video","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Shukran&quot;, al cinema la Siria dilaniata dalla guerra civile - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Shukran&quot;, al cinema la Siria dilaniata dalla guerra civile - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"ROMA (ITALPRESS) &#8211; Nella Siria dilaniata dalla guerra civile, con il popolo che insorge contro il regime di Assad, un cardiochirurgo infantile si trover\u00e0 di fronte alla decisione pi\u00f9 difficile della sua vita. \u201cShukran\u201d, opera prima del regista Pietro Malegori, \u00e8 basato su una storia vera ed \u00e8 tratto dall\u2019omonimo libro di Giovanni Terzi edito [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-08T13:01:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"&#8220;Shukran&#8221;, al cinema la Siria dilaniata dalla guerra civile\",\"datePublished\":\"2024-07-08T13:01:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\\\/\"},\"wordCount\":117,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/PWqA.jpg\",\"articleSection\":[\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\\\/\",\"name\":\"\\\"Shukran\\\", al cinema la Siria dilaniata dalla guerra civile - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/PWqA.jpg\",\"datePublished\":\"2024-07-08T13:01:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/PWqA.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/PWqA.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/07\\\/08\\\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Shukran&#8221;, al cinema la Siria dilaniata dalla guerra civile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Shukran\", al cinema la Siria dilaniata dalla guerra civile - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\/","og_locale":"it_IT","og_type":"article","og_title":"\"Shukran\", al cinema la Siria dilaniata dalla guerra civile - Live Magazine","og_description":"ROMA (ITALPRESS) &#8211; Nella Siria dilaniata dalla guerra civile, con il popolo che insorge contro il regime di Assad, un cardiochirurgo infantile si trover\u00e0 di fronte alla decisione pi\u00f9 difficile della sua vita. \u201cShukran\u201d, opera prima del regista Pietro Malegori, \u00e8 basato su una storia vera ed \u00e8 tratto dall\u2019omonimo libro di Giovanni Terzi edito [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2024-07-08T13:01:26+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"&#8220;Shukran&#8221;, al cinema la Siria dilaniata dalla guerra civile","datePublished":"2024-07-08T13:01:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\/"},"wordCount":117,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/PWqA.jpg","articleSection":["Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\/","url":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\/","name":"\"Shukran\", al cinema la Siria dilaniata dalla guerra civile - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/PWqA.jpg","datePublished":"2024-07-08T13:01:26+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/PWqA.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/PWqA.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2024\/07\/08\/shukran-al-cinema-la-siria-dilaniata-dalla-guerra-civile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"&#8220;Shukran&#8221;, al cinema la Siria dilaniata dalla guerra civile"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/07\/PWqA.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/30281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=30281"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/30281\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/30282"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=30281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=30281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=30281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}