{"id":28504,"date":"2024-06-13T15:01:55","date_gmt":"2024-06-13T13:01:55","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2024\/06\/13\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\/"},"modified":"2024-06-13T15:01:55","modified_gmt":"2024-06-13T13:01:55","slug":"stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2024\/06\/13\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\/","title":{"rendered":"Stefano Gallini \u00e8 il nuovo presidente di Federbeton Confindustria"},"content":{"rendered":"<div>\n<p>ROMA (ITALPRESS) \u2013 Federbeton Confindustria, la Federazione che riunisce le imprese della filiera del cemento e del calcestruzzo, ha un nuovo presidente: Stefano Gallini. \u201cE\u2019 un privilegio rappresentare un\u2019industria che in Italia conta oltre 35.000 addetti e che rappresenta il primo fondamentale tassello per realizzare infrastrutture e costruzioni sicure e sostenibili \u2013 afferma il neopresidente Stefano Gallini -. Il nostro settore sta attraversando un momento cruciale, che ci vede impegnati sulla strada della sostenibilit\u00e0 e della decarbonizzazione. Fornire un materiale carbon neutral \u00e8 il traguardo finale per cui stiamo mettendo in campo tutte le risorse necessarie nel rispetto dei tempi e degli obiettivi condivisi a livello europeo \u2013 continua Gallini -. Perch\u00e8 il nostro sforzo sia veramente efficace, sar\u00e0 necessario tutelare tutte quelle aziende e quei lavoratori che stanno investendo in ricerca e in tecnologie e che possono contribuire a garantire al nostro Paese scuole, case, ponti e ospedali sicuri, innovativi, Made in Italy e sempre pi\u00f9 sostenibili\u201d. Il programma della Presidenza Gallini prevede, tra i punti cardine, l\u2019accelerazione della strategia di decarbonizzazione e la tutela dell\u2019industria italiana: in Italia la filiera produttiva del cemento e del calcestruzzo fornisce un materiale unico, sicuro e sostenibile, degno della qualit\u00e0 propria del Made in Italy. Nonostante ci\u00f2, l\u2019industria italiana del cemento rischia una forte contrazione, a causa dell\u2019importazione di materiali con origine extra-EU, proveniente da Paese che si affacciano sul Mediterraneo che, non dovendo rispettare gli alti standard ambientali europei, possono offrire prodotti con costi inferiori. Questo, per una nazione con 8.000 chilometri di coste come l\u2019Italia, si traduce in un aumento esponenziale delle importazioni, arrivate a toccare i 3,6 milioni di tonnellate nel 2023, una crescita del 22,6% rispetto all\u2019anno precedente, con conseguenze pesanti per l\u2019ambiente e per il tessuto produttivo italiano.<br \/>\nAll\u2019attenzione per la tutela dell\u2019industria italiana, nel programma del nuovo Presidente, si affianca una rinnovata volont\u00e0 di fare cultura per raccontare la qualit\u00e0, le innovazioni e la sostenibilit\u00e0 di materiali fondamentali per la vita quotidiana e per lo sviluppo socio-economico del Paese. Molte iniziative proseguiranno in continuit\u00e0 con la precedente presidenza come nel caso dei Porte Aperte, importanti occasioni di incontro con le comunit\u00e0 locali. Un nuovo impulso sar\u00e0 dato, inoltre, a quelle iniziative dedicate alla scuola e, pi\u00f9 in generale, ai giovani che possono trovare nella filiera del cemento e del calcestruzzo un\u2019opportunit\u00e0 per il futuro. Stefano Gallini, 51 anni, \u00e8 l\u2019Amministratore Delegato Italia di Heidelberg Materials, il brand globale che lo scorso anno ha raccolto la storica eredit\u00e0 di Italcementi. Entrato in azienda nel 2000, dove ha ricoperto posizioni sempre pi\u00f9 importanti nelle vendite e nel marketing in Italia e in Egitto, prima di maturare un\u2019esperienza di general management internazionale come Managing Director in Albania, Sierra Leone e Ghana. Nel 2020 ha assunto la posizione di General Manager per l\u2019area combinata di Ghana, Sierra Leone, Gambia e Liberia, per essere successivamente promosso nel 2022 a General Manager della Regione dell\u2019Africa Occidentale.<br \/>\nGallini succede alla presidenza di Federbeton a Roberto Callieri, oggi membro del Managing Board globale del Gruppo Heidelberg Materials. \u201cConcludo oggi un percorso durato sei anni. Abbiamo dato voce alla nostra filiera in anni difficili: prima il Covid, poi l\u2019esplosione di conflitti internazionali che si sono tradotti in contesti di instabilit\u00e0 con ripercussioni dirette sulla nostra economia, con il caro energia e la scarsit\u00e0 di materie prime. Nonostante le difficolt\u00e0, il nostro obiettivo \u00e8 stato quello di difendere e dare visibilit\u00e0 e rappresentanza a un settore fondamentale per il mondo delle costruzioni, nonch\u00e8 per l\u2019economia dello stesso sistema Paese \u2013 ha commentato Roberto Callieri -. Federbeton ha deciso di affidare a Stefano Gallini l\u2019importante compito di continuare questo ambizioso ma fondamentale lavoro. A lui e a tutta la squadra di Presidenza vanno le mie pi\u00f9 sincere congratulazioni\u201d. \u201cRingrazio Roberto Callieri per il grande lavoro svolto in uno dei periodi pi\u00f9 difficili per il nostro settore. Una preziosa eredit\u00e0, della quale far\u00f2 tesoro nel mio mandato\u201d, ha concluso il neo Presidente Gallini. Stefano Gallini assume anche la presidenza di Aitec, l\u2019Associazione che in Federbeton rappresenta l\u2019industria del cemento. In Federbeton sar\u00e0 affiancato da una rinnovata squadra di vicepresidenti che include Ubaldo Colaiacovo (Colacem \u2013 Aitec), Paolo Zelano (Buzzi \u2013 Aitec), Paola Colaiacovo (Colabeton \u2013 Atecap) e cinque coordinatori di commissione che annoverano Paolo Zelano (Buzzi, Commissione Ambiente e Economia Circolare), Fabrizio Pedetta (Colacem, Tecnologie e Prodotto), Lorenzo Colombo (Heidelberg Materials, Comunicazione), Massimo Angeli (Colacem, Relazioni sindacali), e Luca Leonardo (Heidelberg Materials, Legalit\u00e0 e Compliance).<br \/>\n(ITALPRESS).<\/p>\n<p>\u2013 Foto: ufficio stampa Federbeton Confindustria \u2013<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) \u2013 Federbeton Confindustria, la Federazione che riunisce le imprese della filiera del cemento e del calcestruzzo, ha un nuovo presidente: Stefano Gallini. \u201cE\u2019 un privilegio rappresentare un\u2019industria che in Italia conta oltre 35.000 addetti e che rappresenta il primo fondamentale tassello per realizzare infrastrutture e costruzioni sicure e sostenibili \u2013 afferma il neopresidente [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":28505,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-28504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stefano Gallini \u00e8 il nuovo presidente di Federbeton Confindustria - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2024\/06\/13\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stefano Gallini \u00e8 il nuovo presidente di Federbeton Confindustria - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"ROMA (ITALPRESS) \u2013 Federbeton Confindustria, la Federazione che riunisce le imprese della filiera del cemento e del calcestruzzo, ha un nuovo presidente: Stefano Gallini. \u201cE\u2019 un privilegio rappresentare un\u2019industria che in Italia conta oltre 35.000 addetti e che rappresenta il primo fondamentale tassello per realizzare infrastrutture e costruzioni sicure e sostenibili \u2013 afferma il neopresidente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2024\/06\/13\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-13T13:01:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/13\\\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/13\\\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Stefano Gallini \u00e8 il nuovo presidente di Federbeton Confindustria\",\"datePublished\":\"2024-06-13T13:01:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/13\\\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\\\/\"},\"wordCount\":752,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/13\\\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/20240613_0569.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/13\\\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/13\\\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\\\/\",\"name\":\"Stefano Gallini \u00e8 il nuovo presidente di Federbeton Confindustria - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/13\\\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/13\\\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/20240613_0569.jpg\",\"datePublished\":\"2024-06-13T13:01:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/13\\\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/13\\\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/13\\\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/20240613_0569.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/20240613_0569.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/13\\\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stefano Gallini \u00e8 il nuovo presidente di Federbeton Confindustria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stefano Gallini \u00e8 il nuovo presidente di Federbeton Confindustria - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2024\/06\/13\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\/","og_locale":"it_IT","og_type":"article","og_title":"Stefano Gallini \u00e8 il nuovo presidente di Federbeton Confindustria - Live Magazine","og_description":"ROMA (ITALPRESS) \u2013 Federbeton Confindustria, la Federazione che riunisce le imprese della filiera del cemento e del calcestruzzo, ha un nuovo presidente: Stefano Gallini. \u201cE\u2019 un privilegio rappresentare un\u2019industria che in Italia conta oltre 35.000 addetti e che rappresenta il primo fondamentale tassello per realizzare infrastrutture e costruzioni sicure e sostenibili \u2013 afferma il neopresidente [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2024\/06\/13\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2024-06-13T13:01:55+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/13\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/13\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Stefano Gallini \u00e8 il nuovo presidente di Federbeton Confindustria","datePublished":"2024-06-13T13:01:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/13\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\/"},"wordCount":752,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/13\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/20240613_0569.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/13\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\/","url":"https:\/\/www.livemag.it\/index.php\/2024\/06\/13\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\/","name":"Stefano Gallini \u00e8 il nuovo presidente di Federbeton Confindustria - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/13\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/13\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/20240613_0569.jpg","datePublished":"2024-06-13T13:01:55+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/13\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2024\/06\/13\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/13\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/20240613_0569.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/20240613_0569.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/13\/stefano-gallini-e-il-nuovo-presidente-di-federbeton-confindustria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Stefano Gallini \u00e8 il nuovo presidente di Federbeton Confindustria"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/20240613_0569.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/28504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=28504"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/28504\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/28505"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=28504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=28504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=28504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}