{"id":28294,"date":"2024-06-10T15:01:39","date_gmt":"2024-06-10T13:01:39","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2024\/06\/10\/salvini-vannacci-contestato-ma-fa-record-al-nord\/"},"modified":"2024-06-10T15:01:39","modified_gmt":"2024-06-10T13:01:39","slug":"salvini-vannacci-contestato-ma-fa-record-al-nord","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2024\/06\/10\/salvini-vannacci-contestato-ma-fa-record-al-nord\/","title":{"rendered":"Salvini \u201cVannacci? Contestato, ma fa record al Nord\u201d"},"content":{"rendered":"<div>\n<p>MILANO (ITALPRESS) \u2013 \u201cVannacci \u00e8 stato contestato, vituperato da mezzo mondo e da solo ha superato mezzo milione di preferenze con un record al Nord Ovest e al Nord Est\u201d. Lo ha detto il vicepremier, ministro delle Infrastrutture e leader della Lega Matteo Salvini in una conferenza stampa nella sede del partito per commentare le elezioni europee, riferendosi all\u2019elezione all\u2019Europarlamento del generale Roberto Vannacci. \u201cQuando l\u2019ho candidato, dicevano che ero un fesso che non ascoltava la base. Il mezzo milione di voti, che arriva soprattutto dalla Lombardia e dal Veneto, penso che arrivi da gente non iscritta\u201d, ha aggiunto. Alla domanda se il generale ora che \u00e8 stato eletto si iscriver\u00e0 ufficialmente al partito, Salvini ha risposto \u201cnon ho mai chiesto a Vannacci di prendere la tessera della Lega e lui non me lo ha mai chiesto\u201d.<\/p>\n<p>foto: Agenzia Fotogramma<\/p>\n<p>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>MILANO (ITALPRESS) \u2013 \u201cVannacci \u00e8 stato contestato, vituperato da mezzo mondo e da solo ha superato mezzo milione di preferenze con un record al Nord Ovest e al Nord Est\u201d. Lo ha detto il vicepremier, ministro delle Infrastrutture e leader della Lega Matteo Salvini in una conferenza stampa nella sede del partito per commentare le [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":28295,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-28294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salvini \u201cVannacci? Contestato, ma fa record al Nord\u201d - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2024\/06\/10\/salvini-vannacci-contestato-ma-fa-record-al-nord\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salvini \u201cVannacci? Contestato, ma fa record al Nord\u201d - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"MILANO (ITALPRESS) \u2013 \u201cVannacci \u00e8 stato contestato, vituperato da mezzo mondo e da solo ha superato mezzo milione di preferenze con un record al Nord Ovest e al Nord Est\u201d. Lo ha detto il vicepremier, ministro delle Infrastrutture e leader della Lega Matteo Salvini in una conferenza stampa nella sede del partito per commentare le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2024\/06\/10\/salvini-vannacci-contestato-ma-fa-record-al-nord\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-10T13:01:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/10\\\/salvini-vannacci-contestato-ma-fa-record-al-nord\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/10\\\/salvini-vannacci-contestato-ma-fa-record-al-nord\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Salvini \u201cVannacci? Contestato, ma fa record al Nord\u201d\",\"datePublished\":\"2024-06-10T13:01:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/10\\\/salvini-vannacci-contestato-ma-fa-record-al-nord\\\/\"},\"wordCount\":149,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/10\\\/salvini-vannacci-contestato-ma-fa-record-al-nord\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/20240610_0486.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/10\\\/salvini-vannacci-contestato-ma-fa-record-al-nord\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/10\\\/salvini-vannacci-contestato-ma-fa-record-al-nord\\\/\",\"name\":\"Salvini \u201cVannacci? Contestato, ma fa record al Nord\u201d - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/10\\\/salvini-vannacci-contestato-ma-fa-record-al-nord\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/10\\\/salvini-vannacci-contestato-ma-fa-record-al-nord\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/20240610_0486.jpg\",\"datePublished\":\"2024-06-10T13:01:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/10\\\/salvini-vannacci-contestato-ma-fa-record-al-nord\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/10\\\/salvini-vannacci-contestato-ma-fa-record-al-nord\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/10\\\/salvini-vannacci-contestato-ma-fa-record-al-nord\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/20240610_0486.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/20240610_0486.jpg\",\"width\":1200,\"height\":799},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/10\\\/salvini-vannacci-contestato-ma-fa-record-al-nord\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salvini \u201cVannacci? Contestato, ma fa record al Nord\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salvini \u201cVannacci? Contestato, ma fa record al Nord\u201d - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2024\/06\/10\/salvini-vannacci-contestato-ma-fa-record-al-nord\/","og_locale":"it_IT","og_type":"article","og_title":"Salvini \u201cVannacci? Contestato, ma fa record al Nord\u201d - Live Magazine","og_description":"MILANO (ITALPRESS) \u2013 \u201cVannacci \u00e8 stato contestato, vituperato da mezzo mondo e da solo ha superato mezzo milione di preferenze con un record al Nord Ovest e al Nord Est\u201d. Lo ha detto il vicepremier, ministro delle Infrastrutture e leader della Lega Matteo Salvini in una conferenza stampa nella sede del partito per commentare le [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2024\/06\/10\/salvini-vannacci-contestato-ma-fa-record-al-nord\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2024-06-10T13:01:39+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/10\/salvini-vannacci-contestato-ma-fa-record-al-nord\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/10\/salvini-vannacci-contestato-ma-fa-record-al-nord\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Salvini \u201cVannacci? Contestato, ma fa record al Nord\u201d","datePublished":"2024-06-10T13:01:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/10\/salvini-vannacci-contestato-ma-fa-record-al-nord\/"},"wordCount":149,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/10\/salvini-vannacci-contestato-ma-fa-record-al-nord\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/20240610_0486.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/10\/salvini-vannacci-contestato-ma-fa-record-al-nord\/","url":"https:\/\/www.livemag.it\/index.php\/2024\/06\/10\/salvini-vannacci-contestato-ma-fa-record-al-nord\/","name":"Salvini \u201cVannacci? Contestato, ma fa record al Nord\u201d - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/10\/salvini-vannacci-contestato-ma-fa-record-al-nord\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/10\/salvini-vannacci-contestato-ma-fa-record-al-nord\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/20240610_0486.jpg","datePublished":"2024-06-10T13:01:39+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/10\/salvini-vannacci-contestato-ma-fa-record-al-nord\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2024\/06\/10\/salvini-vannacci-contestato-ma-fa-record-al-nord\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/10\/salvini-vannacci-contestato-ma-fa-record-al-nord\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/20240610_0486.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/20240610_0486.jpg","width":1200,"height":799},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/10\/salvini-vannacci-contestato-ma-fa-record-al-nord\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Salvini \u201cVannacci? Contestato, ma fa record al Nord\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/20240610_0486.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/28294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=28294"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/28294\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/28295"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=28294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=28294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=28294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}