{"id":27781,"date":"2024-06-04T12:01:38","date_gmt":"2024-06-04T10:01:38","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\/"},"modified":"2024-06-04T12:01:38","modified_gmt":"2024-06-04T10:01:38","slug":"prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\/","title":{"rendered":"Prevenzione, l\u20198 giugno al via \u201cNel cuore della tua citt\u00e0\u201d"},"content":{"rendered":"<div>\n<p>MAZARA DEL VALLO (TRAPANI) (ITALPRESS) \u2013 Parte da Mazara Del Vallo l\u2019iniziativa di sensibilizzazione e prevenzione delle malattie cardiovascolari \u201cNel cuore della tua citt\u00e0\u201d, promossa da Novartis nell\u2019ambito della campagna \u201cAscolta il tuo battito\u201d, sostenuta da AISC (Associazione Italiana Scompensati Cardiaci) e FIPC (Fondazione Italiana Per il Cuore). L\u2019appuntamento \u00e8 fissato per sabato 8 giugno presso l\u2019ospedale \u201cAbele Ajello\u201d dalle 8,30 alle 13,30. Un intervento su misura che prevede consulti cardiologici gratuiti e misurazioni del colesterolo. Per prenotare \u00e8 necessario consultare il sito www.nelcuoredellatuacitta.it.<br \/>L\u20198 giugno in pochi minuti, tramite pungidito, sar\u00e0 possibile conoscere i livelli del profilo lipidico presso i locali dell\u2019ambulatorio, al primo piano del Presidio Ospedaliero e successivamente approfondire i risultati con uno specialista.<br \/>La tappa di Mazara rappresenta la prima delle quattro in programma in  diverse Regioni della penisola. Un appuntamento che invita soprattutto le persone con medio e alto rischio cardiovascolare \u2013 ad esempio coloro che hanno gi\u00e0 avuto un infarto o ictus, chi soffre di diabete o ha una familiarit\u00e0 con questo tipo di patologie \u2013 a non sottovalutare e a ridurre il proprio livello di rischio grazie a una migliore conoscenza e gestione dei livelli di LDL, una delle prime cause di incorrere in un nuovo evento acuto. Nei pazienti che hanno superato un infarto o un ictus la prevenzione secondaria diventa prioritaria per ridurre il rischio di recidive ischemiche e quindi migliorare la loro qualit\u00e0 di vita. La corretta gestione di questi pazienti deve, quindi, necessariamente mirare a raggiungere i valori i di colesterolemia LDL raccomandato dalle Linee Guida congiunte della Societ\u00e0 Europea di Cardiologia (ESC) e della Societ\u00e0 Europea di Aterosclerosi (EAS). Obiettivi, quelli del monitoraggio e del raggiungimento dei livelli target di colesterolo, che non risultano essere di facile ottenimento: in Sicilia, ad esempio, circa il 62% dei pazienti gi\u00e0 in trattamento per problemi di ipercolesterolemia non controlla adeguatamente i valori LDL. Sebbene si tratti del fattore di rischio pi\u00f9 facilmente modificabile, ottenere una riduzione efficace e sostenuta nel tempo dell\u2019LDL \u00e8 infatti ancora una sfida, tanto che 8 su 10 pazienti ad alto rischio non sono in grado di ridurre il loro colesterolo cattivo ai livelli raccomandati. A questo si aggiunge la difficolt\u00e0 di aderenza alla terapia, uno scenario che ha evidenziato come solo il 43,6% della popolazione gi\u00e0 in trattamento sia aderente, riportando che questa si riduce nel tempo a causa della complessit\u00e0 del regime terapeutico e degli effetti indesiderati.<br \/>In Sicilia nel 2020 sono stati registrati oltre 20.000 decessi provocati dalle malattie cardiovascolari (44,4% tra gli uomini e 55,6% tra le donne). Queste patologie costituiscono oggi in Italia la prima causa di morte nell\u2019adulto, con oltre 220.000 decessi ogni anno, di cui il 30% ascrivibile a una condizione di trombosi o di aterosclerosi della parete arteriosa. A livello globale, 1\/3 delle cardiopatie ischemiche \u00e8 attribuibile a ipercolesterolemia che \u00e8 responsabile di 4,4 milioni di decessi all\u2019anno. <br \/>\u201cL\u2019importanza di un\u2019adeguata aderenza e di una conoscenza del proprio rischio di incorrere in un nuovo evento acuto rappresentano temi sui quali vogliamo impegnarci. Iniziative come queste \u2013 sottolinea Ferdinando Croce, Commissario Straordinario Azienda Sanitaria Provinciale Trapani \u2013 permettono di offrire ai nostri pazienti risorse per migliorare la loro qualit\u00e0 di vita e favorire la loro presa in carico da parte dei tanti centri di eccellenza presenti sul nostro territorio\u201d.<br \/>\u201cContinuano a preoccupare i casi attribuibili a condizioni trombotiche o di aterosclerosi in cui l\u2019ipercolesterolemia rappresenta un fattore di rischio chiave. Le malattie cardiovascolari \u2013 precisa Michele Gabriele, Direttore U.O.C. UTIC con Cardiologia e Centro di Cardiostimolazione del Presidio Ospedaliero Abele Ajello \u2013 si confermano purtroppo come la principale causa di morte nel mondo, pi\u00f9 ancora dei tumori. Bench\u00e8 l\u2019innovazione a disposizione consenta di intervenire preventivamente su circa l\u201980% degli eventi cardiovascolari, perseverare con attivit\u00e0 di questo tipo contribuisce a ridurne l\u2019incidenza e salvare molte vite, soprattutto nei pazienti che hanno gi\u00e0 avuto un evento pregresso e che, proprio in virt\u00f9 di questa condizione, devono prestare maggiore attenzione al loro percorso di cura\u201d.<\/p>\n<p>\u2013 Foto \u201cNel cuore della tua citt\u00e0\u201d \u2013<br \/>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>MAZARA DEL VALLO (TRAPANI) (ITALPRESS) \u2013 Parte da Mazara Del Vallo l\u2019iniziativa di sensibilizzazione e prevenzione delle malattie cardiovascolari \u201cNel cuore della tua citt\u00e0\u201d, promossa da Novartis nell\u2019ambito della campagna \u201cAscolta il tuo battito\u201d, sostenuta da AISC (Associazione Italiana Scompensati Cardiaci) e FIPC (Fondazione Italiana Per il Cuore). L\u2019appuntamento \u00e8 fissato per sabato 8 giugno [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":27782,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-27781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prevenzione, l\u20198 giugno al via \u201cNel cuore della tua citt\u00e0\u201d - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prevenzione, l\u20198 giugno al via \u201cNel cuore della tua citt\u00e0\u201d - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"MAZARA DEL VALLO (TRAPANI) (ITALPRESS) \u2013 Parte da Mazara Del Vallo l\u2019iniziativa di sensibilizzazione e prevenzione delle malattie cardiovascolari \u201cNel cuore della tua citt\u00e0\u201d, promossa da Novartis nell\u2019ambito della campagna \u201cAscolta il tuo battito\u201d, sostenuta da AISC (Associazione Italiana Scompensati Cardiaci) e FIPC (Fondazione Italiana Per il Cuore). L\u2019appuntamento \u00e8 fissato per sabato 8 giugno [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-04T10:01:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Prevenzione, l\u20198 giugno al via \u201cNel cuore della tua citt\u00e0\u201d\",\"datePublished\":\"2024-06-04T10:01:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\\\/\"},\"wordCount\":669,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/20240604_0304.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\\\/\",\"name\":\"Prevenzione, l\u20198 giugno al via \u201cNel cuore della tua citt\u00e0\u201d - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/20240604_0304.jpg\",\"datePublished\":\"2024-06-04T10:01:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/20240604_0304.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/20240604_0304.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prevenzione, l\u20198 giugno al via \u201cNel cuore della tua citt\u00e0\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prevenzione, l\u20198 giugno al via \u201cNel cuore della tua citt\u00e0\u201d - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\/","og_locale":"it_IT","og_type":"article","og_title":"Prevenzione, l\u20198 giugno al via \u201cNel cuore della tua citt\u00e0\u201d - Live Magazine","og_description":"MAZARA DEL VALLO (TRAPANI) (ITALPRESS) \u2013 Parte da Mazara Del Vallo l\u2019iniziativa di sensibilizzazione e prevenzione delle malattie cardiovascolari \u201cNel cuore della tua citt\u00e0\u201d, promossa da Novartis nell\u2019ambito della campagna \u201cAscolta il tuo battito\u201d, sostenuta da AISC (Associazione Italiana Scompensati Cardiaci) e FIPC (Fondazione Italiana Per il Cuore). L\u2019appuntamento \u00e8 fissato per sabato 8 giugno [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2024-06-04T10:01:38+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Prevenzione, l\u20198 giugno al via \u201cNel cuore della tua citt\u00e0\u201d","datePublished":"2024-06-04T10:01:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\/"},"wordCount":669,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/20240604_0304.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\/","url":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\/","name":"Prevenzione, l\u20198 giugno al via \u201cNel cuore della tua citt\u00e0\u201d - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/20240604_0304.jpg","datePublished":"2024-06-04T10:01:38+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/20240604_0304.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/20240604_0304.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/prevenzione-l8-giugno-al-via-nel-cuore-della-tua-citta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Prevenzione, l\u20198 giugno al via \u201cNel cuore della tua citt\u00e0\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/20240604_0304.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/27781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=27781"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/27781\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/27782"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=27781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=27781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=27781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}