{"id":27759,"date":"2024-06-04T00:01:23","date_gmt":"2024-06-03T22:01:23","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\/"},"modified":"2024-06-04T00:01:23","modified_gmt":"2024-06-03T22:01:23","slug":"tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\/","title":{"rendered":"Tajani \u201cL\u2019Italia in aiuto del popolo palestinese che soffre\u201d"},"content":{"rendered":"<div>\n<p>ROMA (ITALPRESS) \u2013 Il Vice Presidente del Consiglio e Ministro degli Affari Esteri e della Cooperazione Internazionale, Antonio Tajani, ha tenuto una conferenza stampa per annunciare i risultati del tavolo tecnico dell\u2019iniziativa Food for Gaza e presentare il primo carico di aiuti raccolti per la popolazione di Gaza.<br \/>\u201cCon questa iniziativa abbiamo ribadito l\u2019impegno del Governo italiano di fronte all\u2019emergenza umanitaria nella Striscia di Gaza: lavoriamo affinch\u00e8 gli aiuti arrivino prima possibile\u201d, ha commentato Tajani, evidenziando come l\u2019iniziativa abbia l\u2019obiettivo di portare un aiuto concreto per la sicurezza alimentare e per la salute dei civili palestinesi.<br \/>\u201cSiamo grati a tutta la squadra italiana che si \u00e8 messa in moto in queste settimane\u201d, ha aggiunto il Ministro, ringraziando le Agenzie del Polo ONU di Roma, la Croce Rossa Italiana e FICROSS e la Protezione Civile, oltre a Coldiretti e Confagricoltura, dai cui depositi partono gli aiuti.<br \/>Dal 7 ottobre 2023, \u00e8 stato sottolineato, l\u2019Italia \u00e8 in prima fila nella risposta all\u2019emergenza umanitaria nella Striscia di Gaza. Da allora il Governo ha stanziato una serie di pacchetti di aiuti per un totale di 55 milioni di euro. In tale ambito si situa l\u2019iniziativa \u201cFood for Gaza\u201d, il cui stanziamento totale ammonta attualmente a 30 milioni di euro. <br \/>Alla presentazione hanno preso parte anche i rappresentanti di FAO, WFP, FICROSS e Protezione Civile, partner di Food for Gaza. Presenti anche il presidente di Coldiretti, Ettore Prandini, e l\u2019amministratore delegato di Filiera Italia, Luigi Scordamaglia, associazioni che sostengono l\u2019iniziativa.<br \/>Coinvolta nell\u2019iniziativa anche l\u2019Agenzia delle Dogane attraverso la fornitura di uno scanner di ultima generazione che sar\u00e0 imbarcato gioved\u00ec a Gioia Tauro alla volta di Cipro e poi impiegato per i controlli sui container di aiuti che affluiranno nella Striscia.<br \/>\u2013 foto Agenzia Fotogramma \u2013<br \/>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) \u2013 Il Vice Presidente del Consiglio e Ministro degli Affari Esteri e della Cooperazione Internazionale, Antonio Tajani, ha tenuto una conferenza stampa per annunciare i risultati del tavolo tecnico dell\u2019iniziativa Food for Gaza e presentare il primo carico di aiuti raccolti per la popolazione di Gaza.\u201cCon questa iniziativa abbiamo ribadito l\u2019impegno del Governo [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":27760,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1129],"tags":[],"class_list":["post-27759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tajani \u201cL\u2019Italia in aiuto del popolo palestinese che soffre\u201d - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tajani \u201cL\u2019Italia in aiuto del popolo palestinese che soffre\u201d - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"ROMA (ITALPRESS) \u2013 Il Vice Presidente del Consiglio e Ministro degli Affari Esteri e della Cooperazione Internazionale, Antonio Tajani, ha tenuto una conferenza stampa per annunciare i risultati del tavolo tecnico dell\u2019iniziativa Food for Gaza e presentare il primo carico di aiuti raccolti per la popolazione di Gaza.\u201cCon questa iniziativa abbiamo ribadito l\u2019impegno del Governo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-03T22:01:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Tajani \u201cL\u2019Italia in aiuto del popolo palestinese che soffre\u201d\",\"datePublished\":\"2024-06-03T22:01:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\\\/\"},\"wordCount\":303,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/20240603_1610.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\\\/\",\"name\":\"Tajani \u201cL\u2019Italia in aiuto del popolo palestinese che soffre\u201d - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/20240603_1610.jpg\",\"datePublished\":\"2024-06-03T22:01:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/20240603_1610.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/20240603_1610.jpg\",\"width\":1620,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/04\\\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tajani \u201cL\u2019Italia in aiuto del popolo palestinese che soffre\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tajani \u201cL\u2019Italia in aiuto del popolo palestinese che soffre\u201d - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\/","og_locale":"it_IT","og_type":"article","og_title":"Tajani \u201cL\u2019Italia in aiuto del popolo palestinese che soffre\u201d - Live Magazine","og_description":"ROMA (ITALPRESS) \u2013 Il Vice Presidente del Consiglio e Ministro degli Affari Esteri e della Cooperazione Internazionale, Antonio Tajani, ha tenuto una conferenza stampa per annunciare i risultati del tavolo tecnico dell\u2019iniziativa Food for Gaza e presentare il primo carico di aiuti raccolti per la popolazione di Gaza.\u201cCon questa iniziativa abbiamo ribadito l\u2019impegno del Governo [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2024-06-03T22:01:23+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Tajani \u201cL\u2019Italia in aiuto del popolo palestinese che soffre\u201d","datePublished":"2024-06-03T22:01:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\/"},"wordCount":303,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/20240603_1610.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\/","url":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\/","name":"Tajani \u201cL\u2019Italia in aiuto del popolo palestinese che soffre\u201d - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/20240603_1610.jpg","datePublished":"2024-06-03T22:01:23+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/20240603_1610.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/20240603_1610.jpg","width":1620,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/04\/tajani-litalia-in-aiuto-del-popolo-palestinese-che-soffre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Tajani \u201cL\u2019Italia in aiuto del popolo palestinese che soffre\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/20240603_1610.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/27759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=27759"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/27759\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/27760"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=27759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=27759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=27759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}