{"id":27733,"date":"2024-06-03T18:01:05","date_gmt":"2024-06-03T16:01:05","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2024\/06\/03\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\/"},"modified":"2024-06-03T18:01:05","modified_gmt":"2024-06-03T16:01:05","slug":"europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2024\/06\/03\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\/","title":{"rendered":"<div>Europee, Reguzzoni &#8220;Ppe sar\u00e0 in maggioranza, l&#8217;Italia pesi di pi\u00f9&#8221;<\/div>"},"content":{"rendered":"<p>    <video-js id=\"videojs6a988adbd0895\" class=\"vjs-big-play-centered\" controls preload=\"auto\" playsinline data-setup='{\"fluid\": true}'>\r\n        <source src=\"https:\/\/video.italpress.com\/play\/mp4\/video\/w7jr\" type=\"video\/mp4\" \/>\r\n    <\/video-js>\r\n           <br \/>\n<\/p>\n<div> MILANO (ITALPRESS) &#8211; Bisogna &#8220;portare il lavoro in Europa: se non recuperiamo competitivit\u00e0 delle nostre imprese e potere d&#8217;acquisto nelle nostre buste paga e nei nostri redditi, saremo sempre pi\u00f9 poveri&#8221;. Lo spiega Marco Reguzzoni, candidato indipendente di Forza Italia, intervistato da Claudio Brachino per la rubrica &#8220;Primo Piano &#8211; Elezioni europee&#8221; dell&#8217;agenzia Italpress. Per quanto riguarda le alleanze post-voto, &#8220;dipende come voteranno gli altri Paesi europei e dalle decisioni che prenderanno i leader. Salvini ha gi\u00e0 detto che sta all&#8217;opposizione, quindi il voto alla Lega \u00e8 un voto politicamente inutile, mentre invece il PPE, indipendentemente da quello che faranno gli altri, sar\u00e0 al governo. Auspico che ci sia una vittoria di un centrodestra moderato in tutta Europa, se questo per\u00f2 non dovesse accadere si dovranno prendere altre decisioni, ma il Partito Popolare Europeo sar\u00e0 in maggioranza. Ho scelto di candidarmi nel PPE, perch\u00e9 in questo modo si possono difendere i nostri interessi&#8221;. Potrebbero esserci dei riflessi nazionali di questo voto? &#8220;Questo dipende dalle posizioni che prende Salvini: ho visto attaccare il presidente Mattarella in maniera pesante, questo \u00e8 sbagliato, il Presidente della Repubblica non si attacca mai. Sono toni da campagna elettorale, credo che non ci si debba mai spingere oltre un certo livello&#8221;.<br \/>\nxi2\/fsc\/gsl<\/div>\n","protected":false},"excerpt":{"rendered":"<p>MILANO (ITALPRESS) &#8211; Bisogna &#8220;portare il lavoro in Europa: se non recuperiamo competitivit\u00e0 delle nostre imprese e potere d&#8217;acquisto nelle nostre buste paga e nei nostri redditi, saremo sempre pi\u00f9 poveri&#8221;. Lo spiega Marco Reguzzoni, candidato indipendente di Forza Italia, intervistato da Claudio Brachino per la rubrica &#8220;Primo Piano &#8211; Elezioni europee&#8221; dell&#8217;agenzia Italpress. Per [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":27734,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1171],"tags":[],"class_list":["post-27733","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-video","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Europee, Reguzzoni &quot;Ppe sar\u00e0 in maggioranza, l&#039;Italia pesi di pi\u00f9&quot; - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2024\/06\/03\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Europee, Reguzzoni &quot;Ppe sar\u00e0 in maggioranza, l&#039;Italia pesi di pi\u00f9&quot; - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"MILANO (ITALPRESS) &#8211; Bisogna &#8220;portare il lavoro in Europa: se non recuperiamo competitivit\u00e0 delle nostre imprese e potere d&#8217;acquisto nelle nostre buste paga e nei nostri redditi, saremo sempre pi\u00f9 poveri&#8221;. Lo spiega Marco Reguzzoni, candidato indipendente di Forza Italia, intervistato da Claudio Brachino per la rubrica &#8220;Primo Piano &#8211; Elezioni europee&#8221; dell&#8217;agenzia Italpress. Per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2024\/06\/03\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-03T16:01:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/03\\\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/03\\\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Europee, Reguzzoni &#8220;Ppe sar\u00e0 in maggioranza, l&#8217;Italia pesi di pi\u00f9&#8221;\",\"datePublished\":\"2024-06-03T16:01:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/03\\\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\\\/\"},\"wordCount\":232,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/03\\\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/w7jr.jpg\",\"articleSection\":[\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/03\\\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/03\\\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\\\/\",\"name\":\"Europee, Reguzzoni \\\"Ppe sar\u00e0 in maggioranza, l'Italia pesi di pi\u00f9\\\" - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/03\\\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/03\\\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/w7jr.jpg\",\"datePublished\":\"2024-06-03T16:01:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/03\\\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/03\\\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/03\\\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/w7jr.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/w7jr.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/06\\\/03\\\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Europee, Reguzzoni &#8220;Ppe sar\u00e0 in maggioranza, l&#8217;Italia pesi di pi\u00f9&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Europee, Reguzzoni \"Ppe sar\u00e0 in maggioranza, l'Italia pesi di pi\u00f9\" - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2024\/06\/03\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\/","og_locale":"it_IT","og_type":"article","og_title":"Europee, Reguzzoni \"Ppe sar\u00e0 in maggioranza, l'Italia pesi di pi\u00f9\" - Live Magazine","og_description":"MILANO (ITALPRESS) &#8211; Bisogna &#8220;portare il lavoro in Europa: se non recuperiamo competitivit\u00e0 delle nostre imprese e potere d&#8217;acquisto nelle nostre buste paga e nei nostri redditi, saremo sempre pi\u00f9 poveri&#8221;. Lo spiega Marco Reguzzoni, candidato indipendente di Forza Italia, intervistato da Claudio Brachino per la rubrica &#8220;Primo Piano &#8211; Elezioni europee&#8221; dell&#8217;agenzia Italpress. Per [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2024\/06\/03\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2024-06-03T16:01:05+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/03\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/03\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Europee, Reguzzoni &#8220;Ppe sar\u00e0 in maggioranza, l&#8217;Italia pesi di pi\u00f9&#8221;","datePublished":"2024-06-03T16:01:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/03\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\/"},"wordCount":232,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/03\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/w7jr.jpg","articleSection":["Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/03\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\/","url":"https:\/\/www.livemag.it\/index.php\/2024\/06\/03\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\/","name":"Europee, Reguzzoni \"Ppe sar\u00e0 in maggioranza, l'Italia pesi di pi\u00f9\" - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/03\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/03\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/w7jr.jpg","datePublished":"2024-06-03T16:01:05+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/03\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2024\/06\/03\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/03\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/w7jr.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/w7jr.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2024\/06\/03\/europee-reguzzoni-ppe-sara-in-maggioranza-litalia-pesi-di-piu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Europee, Reguzzoni &#8220;Ppe sar\u00e0 in maggioranza, l&#8217;Italia pesi di pi\u00f9&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/06\/w7jr.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/27733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=27733"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/27733\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/27734"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=27733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=27733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=27733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}